{"id":1392,"date":"2019-08-03T20:19:00","date_gmt":"2019-08-03T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1392"},"modified":"2021-02-08T22:25:28","modified_gmt":"2021-02-08T22:25:28","slug":"joselo-el-nombre-que-puede-hundir-al-vice","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/","title":{"rendered":"Joselo, el nombre que puede hundir al vice"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las gestiones del abogado Jos\u00e9 Miguel Rodr\u00edguez Gonz\u00e1lez (26), alias Joselo, en torno al llamado trato ka\u00f1y con el Brasil, sobre la venta de la energ\u00eda de&nbsp;Itaip\u00fa, as\u00ed como la presi\u00f3n que ejerci\u00f3 para que la&nbsp;ANDE haga negocios con una empresa brasile\u00f1a, amenazan con hundir al vicepresidente Hugo Vel\u00e1zquez, quien esta semana ya se salv\u00f3 de un juicio pol\u00edtico, junto con el presidente Mario Abdo Ben\u00edtez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ayer se filtraron otros mensajes que el joven, quien dec\u00eda ser asesor de la Vicepresidencia, hab\u00eda enviado al entonces presidente de la ANDE, Pedro Ferreira, a quien se dirig\u00eda \u201cen nombre del vicepresidente Hugo Vel\u00e1zquez\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joselo le dec\u00eda a Ferreira que la firma Leros, del Brasil, ven\u00eda \u201cen representaci\u00f3n de la familia presidencial del vecino pa\u00eds\u201d, implicando as\u00ed al presidente&nbsp;Jair Bolsonaro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rodr\u00edguez Gonz\u00e1lez, hijo de la exministra de la Seprelad, Mar\u00eda Epifan\u00eda Gonz\u00e1lez, quien tuvo que renunciar, es amigo del hijo de Vel\u00e1zquez, pese a que este sostuvo ante la plenaria de los diputados que lo conoc\u00eda solo de las campa\u00f1as electorales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tiene 3 a\u00f1os de experiencia en la profesi\u00f3n, seg\u00fan su mam\u00e1, quien ayer cuestion\u00f3 a Ferreira por ventilar los chats con su hijo. \u201cEl hijo de Pedro Ferreira siempre ven\u00eda a mi casa a compartir asados con Joselo. Para m\u00ed los amigos de mis hijos son todos mis sobrinos; lo \u00fanico que yo estoy segura es que \u00e9l no era un extra\u00f1o para el ingeniero (Ferreira)\u201d, dijo la exministra a radio 1000.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Las renuncias<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A ra\u00edz del pacto que se conoci\u00f3 hace poco tras la salida de Ferreira de la ANDE, tuvieron que renunciar Luis Alberto Castiglioni, excanciller; Jos\u00e9 Alberto Alderete, exdirector de Itaip\u00fa; Hugo Saguier Caballero, embajador en Brasil, y Alcides Jim\u00e9nez, quien hab\u00eda asumido en la ANDE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los 4, m\u00e1s el vicepresidente&nbsp;Hugo Vel\u00e1zquez, el ministro de Hacienda, Benigno L\u00f3pez, y Joselo Rodr\u00edguez, fueron denunciados por traici\u00f3n a la patria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se exponen a condenas de 5 a 25 a\u00f1os de c\u00e1rcel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joselo fue llamado a declarar hoy, sobre el caso, en la Fiscal\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las gestiones del abogado Jos\u00e9 Miguel Rodr\u00edguez Gonz\u00e1lez (26), alias Joselo, en torno al llamado trato ka\u00f1y con el Brasil, sobre la venta de la energ\u00eda de&nbsp;Itaip\u00fa, as\u00ed como la presi\u00f3n que ejerci\u00f3 para que la&nbsp;ANDE haga negocios con una empresa brasile\u00f1a, amenazan con hundir al vicepresidente Hugo Vel\u00e1zquez, quien esta semana ya se salv\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[452,353,665,666,668],"ppma_author":[1039],"class_list":["post-1392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-ande","tag-benigno-lopez","tag-hugo-velazquez","tag-itaipu","tag-joselo-rodriguez"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Joselo, el nombre que puede hundir al vice - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joselo, el nombre que puede hundir al vice - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Las gestiones del abogado Jos\u00e9 Miguel Rodr\u00edguez Gonz\u00e1lez (26), alias Joselo, en torno al llamado trato ka\u00f1y con el Brasil, sobre la venta de la energ\u00eda de&nbsp;Itaip\u00fa, as\u00ed como la presi\u00f3n que ejerci\u00f3 para que la&nbsp;ANDE haga negocios con una empresa brasile\u00f1a, amenazan con hundir al vicepresidente Hugo Vel\u00e1zquez, quien esta semana ya se salv\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-03T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T22:25:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/joselo-y-hugo-velazquez-2.jpg?fit=764%2C562&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"764\" \/>\n\t<meta property=\"og:image:height\" content=\"562\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Joselo, el nombre que puede hundir al vice\",\"datePublished\":\"2019-08-03T20:19:00+00:00\",\"dateModified\":\"2021-02-08T22:25:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/\"},\"wordCount\":383,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/joselo-y-hugo-velazquez-2.jpg?fit=764%2C562&ssl=1\",\"keywords\":[\"ande\",\"Benigno L\u00f3pez\",\"hugo velazquez\",\"itaipu\",\"Joselo Rodriguez\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/\",\"name\":\"Joselo, el nombre que puede hundir al vice - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/joselo-y-hugo-velazquez-2.jpg?fit=764%2C562&ssl=1\",\"datePublished\":\"2019-08-03T20:19:00+00:00\",\"dateModified\":\"2021-02-08T22:25:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/joselo-y-hugo-velazquez-2.jpg?fit=764%2C562&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/joselo-y-hugo-velazquez-2.jpg?fit=764%2C562&ssl=1\",\"width\":764,\"height\":562},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/03\\\/joselo-el-nombre-que-puede-hundir-al-vice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joselo, el nombre que puede hundir al vice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joselo, el nombre que puede hundir al vice - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/","og_locale":"es_ES","og_type":"article","og_title":"Joselo, el nombre que puede hundir al vice - Informatepy","og_description":"Las gestiones del abogado Jos\u00e9 Miguel Rodr\u00edguez Gonz\u00e1lez (26), alias Joselo, en torno al llamado trato ka\u00f1y con el Brasil, sobre la venta de la energ\u00eda de&nbsp;Itaip\u00fa, as\u00ed como la presi\u00f3n que ejerci\u00f3 para que la&nbsp;ANDE haga negocios con una empresa brasile\u00f1a, amenazan con hundir al vicepresidente Hugo Vel\u00e1zquez, quien esta semana ya se salv\u00f3 [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/","og_site_name":"Informatepy","article_published_time":"2019-08-03T20:19:00+00:00","article_modified_time":"2021-02-08T22:25:28+00:00","og_image":[{"width":764,"height":562,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/joselo-y-hugo-velazquez-2.jpg?fit=764%2C562&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Joselo, el nombre que puede hundir al vice","datePublished":"2019-08-03T20:19:00+00:00","dateModified":"2021-02-08T22:25:28+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/"},"wordCount":383,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/joselo-y-hugo-velazquez-2.jpg?fit=764%2C562&ssl=1","keywords":["ande","Benigno L\u00f3pez","hugo velazquez","itaipu","Joselo Rodriguez"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/","url":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/","name":"Joselo, el nombre que puede hundir al vice - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/joselo-y-hugo-velazquez-2.jpg?fit=764%2C562&ssl=1","datePublished":"2019-08-03T20:19:00+00:00","dateModified":"2021-02-08T22:25:28+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/joselo-y-hugo-velazquez-2.jpg?fit=764%2C562&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/joselo-y-hugo-velazquez-2.jpg?fit=764%2C562&ssl=1","width":764,"height":562},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Joselo, el nombre que puede hundir al vice"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/joselo-y-hugo-velazquez-2.jpg?fit=764%2C562&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1393,"url":"https:\/\/informatepy.com\/2021\/2019\/08\/03\/joselo-el-nombre-que-puede-hundir-al-vice-2\/","url_meta":{"origin":1392,"position":0},"title":"Joselo, el nombre que puede hundir al vice","date":"3 de agosto de 2019","format":false,"excerpt":"Las gestiones del abogado Jos\u00e9 Miguel Rodr\u00edguez Gonz\u00e1lez (26), alias Joselo, en torno al llamado trato ka\u00f1y con el Brasil, sobre la venta de la energ\u00eda de\u00a0Itaip\u00fa, as\u00ed como la presi\u00f3n que ejerci\u00f3 para que la\u00a0ANDE haga negocios con una empresa brasile\u00f1a, amenazan con hundir al vicepresidente Hugo Vel\u00e1zquez, quien\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/joselo-y-hugo-velazquez-2.jpg?fit=764%2C562&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1538,"url":"https:\/\/informatepy.com\/2021\/2019\/09\/30\/anetete-aprueba-candidatura-de-joven-imputado\/","url_meta":{"origin":1392,"position":1},"title":"A\u00f1etet\u00e9 aprueba candidatura de joven imputado","date":"30 de septiembre de 2019","format":false,"excerpt":"Aunque ya no sorprenda, desde el Movimiento Colorado A\u00f1etet\u00e9, puntualmente desde el entorno del vicepresidente Hugo Vel\u00e1zquez, se est\u00e1 apadrinando la candidatura de un joven que tendr\u00eda m\u00e1s antecedentes penales que pol\u00edticos. Se trata de Carlos Enrique Cabrera M\u00e9ndez, candidato a miembro nacional de la Juventud Colorada, y que, entre\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/kike-cabrera-ANR-juventud.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1385,"url":"https:\/\/informatepy.com\/2021\/2019\/08\/01\/nos-quieren-tomar-de-boludos\/","url_meta":{"origin":1392,"position":2},"title":"Nos quieren tomar de boludos","date":"1 de agosto de 2019","format":false,"excerpt":"En pol\u00edtica las casualidades no existen, tampoco los improvisados o, al menos, estos no llegan a Presidente y Vicepresidente de un pa\u00eds; a lo sumo, son asesores de segunda l\u00ednea que se ganan sus monedas agrediendo a los \"disidentes del r\u00e9gimen\" por las redes sociales. Toda esta cuesti\u00f3n del acta\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/abdo-bolsonaro.jpg?fit=780%2C405&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1409,"url":"https:\/\/informatepy.com\/2021\/2019\/08\/09\/presidente-y-vice-citados-a-declarar-por-el-acta-bilateral\/","url_meta":{"origin":1392,"position":3},"title":"Presidente y Vice citados a declarar por el Acta Bilateral","date":"9 de agosto de 2019","format":false,"excerpt":"De acuerdo a los informes de la Fiscal\u00eda, el llamado se registra en el marco de la causa penal abierta, tras la denuncia formulada y las diferentes informaciones generadas que tienen como base la firma del acta bilateral del uso de Energ\u00eda de Itaip\u00fa entre Paraguay y Brasil. Mientras que\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/abdo-velazquez.jpg?fit=658%2C391&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1543,"url":"https:\/\/informatepy.com\/2021\/2019\/10\/01\/la-supuesta-estafa-en-la-una-que-involucra-a-jovenes-anetete\/","url_meta":{"origin":1392,"position":4},"title":"La supuesta estafa en la UNA que involucra a j\u00f3venes A\u00f1etet\u00e9","date":"1 de octubre de 2019","format":false,"excerpt":"En el a\u00f1o 2018, cuando se desarrollaron las \u00faltimas y muy cuestionadas elecciones en Derecho - UNA, uno de los entonces candidatos, Aldo Gonz\u00e1lez, denunci\u00f3 a varios j\u00f3venes dirigentes del Movimiento Colorado A\u00f1etet\u00e9, que hoy se presentan como la \"renovaci\u00f3n\" del Partido Colorado. Los denunciados en aquella oportunidad, fueron Ceres\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/kike-y-joselo-scaled.jpg?fit=1200%2C872&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13421,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/18\/hugo-velazquez-por-ahora-no-renunciara-a-la-vicepresidencia-y-promete-entregar-la-cabeza-de-mario-abdo\/","url_meta":{"origin":1392,"position":5},"title":"Hugo Vel\u00e1zquez por ahora no renunciar\u00e1 a la Vicepresidencia y promete entregar la cabeza de Mario Abdo","date":"18 de agosto de 2022","format":false,"excerpt":"El vicepresidente de la Rep\u00fablica no presentar\u00e1 su renuncia como vicepresidente y aguardar\u00e1 informe sobre las declaraciones de los Estados Unidos. El Departamento de Estado de ese pa\u00eds lo design\u00f3 \u00absignificativamente corrupto\u00bb, por supuestamente, ofrecer una coima de 1 mill\u00f3n de d\u00f3lares a un funcionario. As\u00ed tambi\u00e9n, la Fiscal\u00eda no\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/fractura-abdo-velazquez.png?fit=1200%2C657&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1392"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1392\/revisions"}],"predecessor-version":[{"id":2814,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1392\/revisions\/2814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1395"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1392"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}