{"id":1356,"date":"2019-07-21T20:19:00","date_gmt":"2019-07-21T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1356"},"modified":"2021-02-20T17:46:44","modified_gmt":"2021-02-20T21:46:44","slug":"la-importancia-de-los-simbolos","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/","title":{"rendered":"La importancia de los s\u00edmbolos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En un mundo donde la gente se mira, mira y ve cada vez\nmenos, no se le suele dar la importancia que merecen los s\u00edmbolos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A quienes fuimos educados hace ya algunos a\u00f1os, desde la m\u00e1s tierna infancia nos han inculcado el valor y el respeto a los s\u00edmbolos y a lo simb\u00f3lico, d\u00e1ndonos a entender que, no alcanza con decir, hay que hacer; hay que ser y parecer. Por ejemplo, puedo considerarme y hasta verme como un caballero pero, si no le cedo el asiento a una dama (aunque las feministas modernas se ofendan), si no me pongo de pie para estrechar la mano de una persona, dif\u00edcilmente se me pueda considerar un caballero; esos s\u00edmbolos env\u00edan un mensaje m\u00e1s all\u00e1 del propio mensaje. Tambi\u00e9n, fuimos educados en cuanto a que cuanto mayor fuera nuestra relevancia en cualquier \u00e1mbito, m\u00e1s importante era el cuidado de esos \u201cdetalles\u201d debido a que quienes nos observaban aprender\u00edan de ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno, parece que, si bien somos contempor\u00e1neos con el presidente Mario Adbo, o no le ense\u00f1aron lo mismo que a m\u00ed, o no aprendi\u00f3 o, lo que ser\u00eda peor (y m\u00e1s peligroso) aprendi\u00f3, entendi\u00f3 todo y est\u00e1 enviando un metamensaje vaya uno a saber qui\u00e9n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los \u00faltimos d\u00edas, se lo vio al presidente Abdo luciendo una prenda originaria de Medio Oriente llamada \u201cKufiyya\u201d, com\u00fanmente conocida como \u201cpa\u00f1uelo palestino\u201d. Este s\u00edmbolo, est\u00e1 tradicionalmente ligado a la causa palestina; de hecho, si bien es una prenda de uso milenario en muchos pa\u00edses \u00e1rabes, se considera a la&nbsp;kufiyya&nbsp;como un s\u00edmbolo de respaldo al terrorismo, y para entender el porqu\u00e9, solo basta con googlear terrorista palestino para entender el porqu\u00e9.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/yasser-arafat.jpg?resize=259%2C146&#038;ssl=1\" alt=\"\" class=\"wp-image-1689\" width=\"259\" height=\"146\" data-recalc-dims=\"1\" \/><figcaption>Yasser Arafat &#8211; L\u00edder Hist\u00f3rico de la OLP<br><br><img decoding=\"async\" class=\"wp-image-1690\" style=\"width: 300px\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/terrorista-palestino.jpg?w=740&#038;ssl=1\" alt=\"\" data-recalc-dims=\"1\"><br>Terrorista Palestino<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Probablemente, en otro contexto hist\u00f3rico o pol\u00edtico, el \u201cerror\u201d del presidente Mario Abdo Ben\u00edtez, hubiese pasado inadvertido o, tal vez, como una desafortunada elecci\u00f3n en su vestuario, eventualmente hasta podr\u00eda haberle echado la culpa a alguno de sus asesores pero, teniendo en cuenta las posturas adoptadas  por el presidente en el marco de las relaciones bilaterales con Israel y con el denominado mundo \u00e1rabe (tema embajada entre otros), es posible pensar que no se trata de un error, y si que se trata de un metamensaje enviado al mundo acerca de a quienes \u00e9l respeta y con quienes quiere congraciarse, sin darse cuenta que, finalmente, \u00e9l ya no es \u00e9l sino que es \u201cnosotros\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ND<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un mundo donde la gente se mira, mira y ve cada vez menos, no se le suele dar la importancia que merecen los s\u00edmbolos. A quienes fuimos educados hace ya algunos a\u00f1os, desde la m\u00e1s tierna infancia nos han inculcado el valor y el respeto a los s\u00edmbolos y a lo simb\u00f3lico, d\u00e1ndonos a [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1357,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[248],"tags":[384,332,479,654],"ppma_author":[1065],"class_list":["post-1356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-israel","tag-mario-abdo","tag-nd","tag-palestina"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La importancia de los s\u00edmbolos - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La importancia de los s\u00edmbolos - Informatepy\" \/>\n<meta property=\"og:description\" content=\"En un mundo donde la gente se mira, mira y ve cada vez menos, no se le suele dar la importancia que merecen los s\u00edmbolos. A quienes fuimos educados hace ya algunos a\u00f1os, desde la m\u00e1s tierna infancia nos han inculcado el valor y el respeto a los s\u00edmbolos y a lo simb\u00f3lico, d\u00e1ndonos a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-21T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-20T21:46:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/abdo-paC3B1uelo.jpg?fit=1045%2C1280&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1045\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicol\u00e1s D\u00b4Ursi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/NicoDursi\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicol\u00e1s D\u00b4Ursi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/\"},\"author\":{\"name\":\"Nicol\u00e1s D\u00b4Ursi\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/5f11462f4da127b423f029d0dbae9131\"},\"headline\":\"La importancia de los s\u00edmbolos\",\"datePublished\":\"2019-07-21T20:19:00+00:00\",\"dateModified\":\"2021-02-20T21:46:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/\"},\"wordCount\":440,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/abdo-paC3B1uelo.jpg?fit=1045%2C1280&ssl=1\",\"keywords\":[\"israel\",\"mario abdo\",\"ND\",\"palestina\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/\",\"name\":\"La importancia de los s\u00edmbolos - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/abdo-paC3B1uelo.jpg?fit=1045%2C1280&ssl=1\",\"datePublished\":\"2019-07-21T20:19:00+00:00\",\"dateModified\":\"2021-02-20T21:46:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/abdo-paC3B1uelo.jpg?fit=1045%2C1280&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/abdo-paC3B1uelo.jpg?fit=1045%2C1280&ssl=1\",\"width\":1045,\"height\":1280,\"caption\":\"Presidente Mario Abdo Ben\u00edtez\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/21\\\/la-importancia-de-los-simbolos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La importancia de los s\u00edmbolos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/5f11462f4da127b423f029d0dbae9131\",\"name\":\"Nicol\u00e1s D\u00b4Ursi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/nicolas-dursi.jpg?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/nicolas-dursi.jpg?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/nicolas-dursi.jpg?fit=96%2C96&ssl=1\",\"caption\":\"Nicol\u00e1s D\u00b4Ursi\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/NicoDursi\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/ndursi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La importancia de los s\u00edmbolos - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/","og_locale":"es_ES","og_type":"article","og_title":"La importancia de los s\u00edmbolos - Informatepy","og_description":"En un mundo donde la gente se mira, mira y ve cada vez menos, no se le suele dar la importancia que merecen los s\u00edmbolos. A quienes fuimos educados hace ya algunos a\u00f1os, desde la m\u00e1s tierna infancia nos han inculcado el valor y el respeto a los s\u00edmbolos y a lo simb\u00f3lico, d\u00e1ndonos a [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/","og_site_name":"Informatepy","article_published_time":"2019-07-21T20:19:00+00:00","article_modified_time":"2021-02-20T21:46:44+00:00","og_image":[{"width":1045,"height":1280,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/abdo-paC3B1uelo.jpg?fit=1045%2C1280&ssl=1","type":"image\/jpeg"}],"author":"Nicol\u00e1s D\u00b4Ursi","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/NicoDursi","twitter_misc":{"Escrito por":"Nicol\u00e1s D\u00b4Ursi","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/"},"author":{"name":"Nicol\u00e1s D\u00b4Ursi","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/5f11462f4da127b423f029d0dbae9131"},"headline":"La importancia de los s\u00edmbolos","datePublished":"2019-07-21T20:19:00+00:00","dateModified":"2021-02-20T21:46:44+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/"},"wordCount":440,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/abdo-paC3B1uelo.jpg?fit=1045%2C1280&ssl=1","keywords":["israel","mario abdo","ND","palestina"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/","url":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/","name":"La importancia de los s\u00edmbolos - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/abdo-paC3B1uelo.jpg?fit=1045%2C1280&ssl=1","datePublished":"2019-07-21T20:19:00+00:00","dateModified":"2021-02-20T21:46:44+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/abdo-paC3B1uelo.jpg?fit=1045%2C1280&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/abdo-paC3B1uelo.jpg?fit=1045%2C1280&ssl=1","width":1045,"height":1280,"caption":"Presidente Mario Abdo Ben\u00edtez"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/la-importancia-de-los-simbolos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"La importancia de los s\u00edmbolos"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/5f11462f4da127b423f029d0dbae9131","name":"Nicol\u00e1s D\u00b4Ursi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","caption":"Nicol\u00e1s D\u00b4Ursi"},"sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/NicoDursi"],"url":"https:\/\/informatepy.com\/2021\/author\/ndursi\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/abdo-paC3B1uelo.jpg?fit=1045%2C1280&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1603,"url":"https:\/\/informatepy.com\/2021\/2019\/11\/11\/la-importancia-de-los-simbolos-ii\/","url_meta":{"origin":1356,"position":0},"title":"La importancia de los s\u00edmbolos II","date":"11 de noviembre de 2019","format":false,"excerpt":"Hace alg\u00fan tiempo desde esta plataforma compartimos con nuestros lectores, unas l\u00edneas tituladas \"La importancia de los s\u00edmbolos\"; en ellas, describ\u00edamos la poca importancia que desde el gobierno nacional se le daba a los gestos como mecanismo de comunicaci\u00f3n de las ideas o, lo que ser\u00eda a\u00fan peor, lo deliberado\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/accidente-comitiva-abdo.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2273,"url":"https:\/\/informatepy.com\/2021\/2020\/11\/18\/amnesty-mancilla-simbolos-y-presiona-por-el-aborto-en-argentina\/","url_meta":{"origin":1356,"position":1},"title":"Amnesty mancilla s\u00edmbolos y presiona por el aborto en Argentina","date":"18 de noviembre de 2020","format":false,"excerpt":"El d\u00eda de ayer, en el marco de su campa\u00f1a en favor de la despenalizaci\u00f3n del aborto, la organizaci\u00f3n inglesa, Amnesty Internacional, ilumin\u00f3 de color verde la fachada del hist\u00f3rico Cabildo de la Ciudad de Buenos Aires. Este acci\u00f3n, mancilla un importante s\u00edmbolo patrio argentino y, lo que es peor\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/cabildo-amnesty-aborto.jpg?fit=680%2C466&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6297,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/09\/llevando-la-estupidez-a-un-nuevo-nivel-una-universidad-de-ee-uu-retira-roca-de-millones-de-anos-por-ser-un-simbolo-racista\/","url_meta":{"origin":1356,"position":2},"title":"Llevando la estupidez a un nuevo nivel: Una universidad de EE. UU. retira roca de millones de a\u00f1os \u201cpor ser un s\u00edmbolo racista\u201d","date":"9 de agosto de 2021","format":false,"excerpt":"La Universidad de Wisconsin en Madison (EE.\u00a0UU.) anunci\u00f3 que la monumental roca \u201cChamberlin\u201d, que hab\u00eda estado expuesta en su campus durante casi 100 a\u00f1os, hab\u00eda sido retirada a petici\u00f3n de los estudiantes afroamericanos y de otras minor\u00edas \u00e9tnicas que consideraban el monolito como un s\u00edmbolo de racismo. La enorme roca\u2026","rel":"","context":"En \u00abCiencia y Tecnolog\u00eda\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/roca-Chamberlin.jpg?fit=750%2C375&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13384,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/16\/eeuu-un-articulo-de-opinion-afirma-que-el-rosario-catolico-se-ha-convertido-en-un-simbolo-extremista\/","url_meta":{"origin":1356,"position":3},"title":"EEUU: Un art\u00edculo de opini\u00f3n afirma que el rosario cat\u00f3lico se ha convertido en &#8216;un s\u00edmbolo extremista&#8217;","date":"16 de agosto de 2022","format":false,"excerpt":"El autor afirm\u00f3: \"Los cat\u00f3licos son un contingente creciente del nacionalismo cristiano\".","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/rosario.webp?fit=720%2C405&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12406,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/27\/la-agencia-bloomberg-ahora-dice-que-el-default-de-rusia-es-simbolico\/","url_meta":{"origin":1356,"position":4},"title":"La Agencia Bloomberg ahora dice que el default de Rusia es \u00absimb\u00f3lico\u00bb","date":"27 de junio de 2022","format":false,"excerpt":"Durante las \u00faltimas horas,\u00a0el Gobierno ruso expres\u00f3 su desacuerdo con las afirmaciones publicadas este lunes que aseguran que la Federaci\u00f3n de\u00a0Rusia\u00a0ha incurrido en un impago de las obligaciones de su deuda denominada en divisas, algo que no hab\u00eda sucedido desde 1918. Consultado en rueda de prensa sobre si Mosc\u00fa compart\u00eda\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Putin.jpg?fit=611%2C308&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2079,"url":"https:\/\/informatepy.com\/2021\/2020\/07\/24\/de-iluminatis-masones-e-ignorantes\/","url_meta":{"origin":1356,"position":5},"title":"De Iluminatis, Masones e ignorantes","date":"24 de julio de 2020","format":false,"excerpt":"Desde que sali\u00f3 a la luz el caso de \u201cYuyu\u201d, en los medios de prensa y en las redes sociales hubo toda clase de elucubraciones acerca de los s\u00edmbolos \u201ciluminatis\u201d que existen en los ingresos de varias de las propiedades allanadas pero, lo cierto es que solo dos cosas estuvieron\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/ojo-residencia-caso-juliette.jpg?fit=730%2C486&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1065,"user_id":5,"is_guest":0,"slug":"ndursi","display_name":"Nicol\u00e1s D\u00b4Ursi","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","first_name":"Nicol\u00e1s","last_name":"D\u00b4Ursi","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1356"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1356\/revisions"}],"predecessor-version":[{"id":2839,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1356\/revisions\/2839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1357"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1356"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}