{"id":13482,"date":"2022-08-21T17:20:15","date_gmt":"2022-08-21T20:20:15","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=13482"},"modified":"2022-08-21T17:20:18","modified_gmt":"2022-08-21T20:20:18","slug":"trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/","title":{"rendered":"\u00bfTr\u00e1fico de influencias en el caso del hijo del senador Monges?"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Este viernes se confirm\u00f3 la revocaci\u00f3n de la prisi\u00f3n preventiva de <strong>Juan Ariel Monges Esp\u00ednola<\/strong>, hijo de senador colorado <strong>Juan Dar\u00edo Monges<\/strong> a cambio de una fianza de 2.000 millones de guaran\u00edes.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">De acuerdo a las declaraciones del abogado de la v\u00edctima de <strong>Monges Esp\u00ednola<\/strong>, <strong>Juan Carlos Balmori<\/strong>, se confirm\u00f3 que no hubo modificaciones en la situaci\u00f3n procesal que justifiquen el cambio de la situaci\u00f3n procesal del imputado, el arresto preventivo dictado por la jueza <strong>Ana Mar\u00eda Esquivel<\/strong>, ahora transformado en arresto domiciliario.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Monges hab\u00eda declarado que atropell\u00f3 a Denis L\u00f3pez Salgueiro porque <strong>lo reconoci\u00f3 como el autor de un robo de focos en su propiedad <\/strong>pero, hasta el momento, <strong>no present\u00f3 ninguna prueba que apoye sus dichos <\/strong>y,aunque no lo excusar\u00eda de la desproporcionada reacci\u00f3n, las im\u00e1genes del circuito cerrado del domicilio de Monges no muestran ni el robo de los focos ni a Denis L\u00f3pez Salgueiro en el interior de la propiedad.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfCorrupci\u00f3n policial?<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Tambi\u00e9n, el abogado de la v\u00edctima, <strong>Juan Carlos Balmori,<\/strong> denunci\u00f3 que se redactaron dos informes policiales que no coinciden uno con otro. Los Suboficiales <strong>Ricardo \u00c1lvarez<\/strong> y <strong>William Ben\u00edtez<\/strong> testificaron en sede judicial que fueron presionados por <strong>el Subcomisario Hugo Mar\u00edn <\/strong>para cambiar el informe inicial de los hechos. El suboficial Ben\u00edtez reconoci\u00f3 que entreg\u00f3 el acta original con firmas originales y \u00e9sta luego fue cambiada en sede judicial por una nueva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este viernes se confirm\u00f3 la revocaci\u00f3n de la prisi\u00f3n preventiva de Juan Ariel Monges Esp\u00ednola, hijo de senador colorado Juan Dar\u00edo Monges a cambio de una fianza de 2.000 millones de guaran\u00edes. De acuerdo a las declaraciones del abogado de la v\u00edctima de Monges Esp\u00ednola, Juan Carlos Balmori, se confirm\u00f3 que no hubo modificaciones en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13483,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[1036,1563,887],"ppma_author":[1051],"class_list":["post-13482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-destacada","tag-juan-dario-monges","tag-trafico-de-influencias"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfTr\u00e1fico de influencias en el caso del hijo del senador Monges? - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfTr\u00e1fico de influencias en el caso del hijo del senador Monges? - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Este viernes se confirm\u00f3 la revocaci\u00f3n de la prisi\u00f3n preventiva de Juan Ariel Monges Esp\u00ednola, hijo de senador colorado Juan Dar\u00edo Monges a cambio de una fianza de 2.000 millones de guaran\u00edes. De acuerdo a las declaraciones del abogado de la v\u00edctima de Monges Esp\u00ednola, Juan Carlos Balmori, se confirm\u00f3 que no hubo modificaciones en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-21T20:20:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-21T20:20:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/Juan-Ariel-Monges-Espinola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1281\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"\u00bfTr\u00e1fico de influencias en el caso del hijo del senador Monges?\",\"datePublished\":\"2022-08-21T20:20:15+00:00\",\"dateModified\":\"2022-08-21T20:20:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/\"},\"wordCount\":262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Juan-Ariel-Monges-Espinola.jpg?fit=1281%2C676&ssl=1\",\"keywords\":[\"destacada\",\"juan dario monges\",\"trafico de influencias\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/\",\"name\":\"\u00bfTr\u00e1fico de influencias en el caso del hijo del senador Monges? - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Juan-Ariel-Monges-Espinola.jpg?fit=1281%2C676&ssl=1\",\"datePublished\":\"2022-08-21T20:20:15+00:00\",\"dateModified\":\"2022-08-21T20:20:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Juan-Ariel-Monges-Espinola.jpg?fit=1281%2C676&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Juan-Ariel-Monges-Espinola.jpg?fit=1281%2C676&ssl=1\",\"width\":1281,\"height\":676},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfTr\u00e1fico de influencias en el caso del hijo del senador Monges?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfTr\u00e1fico de influencias en el caso del hijo del senador Monges? - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfTr\u00e1fico de influencias en el caso del hijo del senador Monges? - Informatepy","og_description":"Este viernes se confirm\u00f3 la revocaci\u00f3n de la prisi\u00f3n preventiva de Juan Ariel Monges Esp\u00ednola, hijo de senador colorado Juan Dar\u00edo Monges a cambio de una fianza de 2.000 millones de guaran\u00edes. De acuerdo a las declaraciones del abogado de la v\u00edctima de Monges Esp\u00ednola, Juan Carlos Balmori, se confirm\u00f3 que no hubo modificaciones en [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-08-21T20:20:15+00:00","article_modified_time":"2022-08-21T20:20:18+00:00","og_image":[{"width":1281,"height":676,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/Juan-Ariel-Monges-Espinola.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"\u00bfTr\u00e1fico de influencias en el caso del hijo del senador Monges?","datePublished":"2022-08-21T20:20:15+00:00","dateModified":"2022-08-21T20:20:18+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/"},"wordCount":262,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/Juan-Ariel-Monges-Espinola.jpg?fit=1281%2C676&ssl=1","keywords":["destacada","juan dario monges","trafico de influencias"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/","url":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/","name":"\u00bfTr\u00e1fico de influencias en el caso del hijo del senador Monges? - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/Juan-Ariel-Monges-Espinola.jpg?fit=1281%2C676&ssl=1","datePublished":"2022-08-21T20:20:15+00:00","dateModified":"2022-08-21T20:20:18+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/Juan-Ariel-Monges-Espinola.jpg?fit=1281%2C676&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/Juan-Ariel-Monges-Espinola.jpg?fit=1281%2C676&ssl=1","width":1281,"height":676},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/trafico-de-influencias-en-el-caso-del-hijo-del-senador-monges\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"\u00bfTr\u00e1fico de influencias en el caso del hijo del senador Monges?"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/Juan-Ariel-Monges-Espinola.jpg?fit=1281%2C676&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":8514,"url":"https:\/\/informatepy.com\/2021\/2021\/11\/27\/monges-inaugura-bancada-y-escucha-ofertas\/","url_meta":{"origin":13482,"position":0},"title":"Monges inaugura bancada y&#8230; \u00bfEscucha ofertas?","date":"27 de noviembre de 2021","format":false,"excerpt":"Los senadores Juan Dar\u00edo Monges, Mart\u00edn Ar\u00e9valo, Derlis Osorio y Javier Zacar\u00edas Ir\u00fan, inauguraron una nueva bancada en la c\u00e1mara alta con la intenci\u00f3n de mantenerse \"alejados de lo que tenga que ver con la campa\u00f1a de Hugo Vel\u00e1zquez para el 2023\". Monges, en su car\u00e1cter de presidente del nuevo\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/senador-juan-dario-monges.jpg?fit=952%2C619&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11004,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/05\/celeste-dime-de-que-haces-alarde-y-te-dire-de-que-careces\/","url_meta":{"origin":13482,"position":1},"title":"Celeste, dime de que haces alarde y te dir\u00e9 de que careces","date":"5 de abril de 2022","format":false,"excerpt":"La condesa del Valle de San Bernardino, tambi\u00e9n conocida como Celeste Amarilla, fiel a su estilo, critic\u00f3 la forma de hablar del senador Juan Dar\u00edo Monges quien habr\u00eda pronunciado \"Nasta\" en lugar de \"Nafta\". Lo curioso del caso fue que de manera inmediata, los internautas criticaron su forma de escribir,\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/celeste-amarilla.jpg?fit=1020%2C625&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12326,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/23\/el-senado-aprobo-que-la-deduccion-del-iva-de-la-canasta-familiar-sea-del-30\/","url_meta":{"origin":13482,"position":2},"title":"El Senado aprob\u00f3 que la deducci\u00f3n del IVA de la canasta familiar sea del 30%","date":"23 de junio de 2022","format":false,"excerpt":"El proyecto de ley que deduce del IVA los productos de la canasta familiar y otros gastos, como los servicios p\u00fablicos, originado en Diputados, fue aprobado con modificaciones en el Senado, de acuerdo a conversaciones mantenidas con el ministro de Hacienda. Si bien el pleno estuvo de acuerdo en la\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/camara-de-senadores.jpeg?fit=800%2C459&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8542,"url":"https:\/\/informatepy.com\/2021\/2021\/11\/29\/anetete-se-sigue-dividiendo-por-la-candidatura-de-hugo-velazquez\/","url_meta":{"origin":13482,"position":3},"title":"A\u00f1etete se sigue dividiendo por la candidatura de Hugo Vel\u00e1zquez","date":"29 de noviembre de 2021","format":false,"excerpt":"Lo que parec\u00eda un bloque gran\u00edticamente compuesto, sobre todo en el senado, a partir de la apresurada candidatura presidencial de Hugo Vel\u00e1zquez comenz\u00f3 a fragmentarse y parece que se ir\u00e1 profundizando. La bancada A\u00f1etete compuesta por casi la totalidad de los 17 senadores de la Asociaci\u00f3n Nacional Republicana, apoyada por\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/fractura-abdo-velazquez.png?fit=1200%2C657&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2018,"url":"https:\/\/informatepy.com\/2021\/2020\/06\/13\/cuando-hablabamos-de-hipocresia-llego-esperanza-martinez\/","url_meta":{"origin":13482,"position":4},"title":"Cuando habl\u00e1bamos de hipocres\u00eda&#8230; lleg\u00f3 Esperanza Mart\u00ednez","date":"13 de junio de 2020","format":false,"excerpt":"Hoy, una vez m\u00e1s (y van...) la izquierda vern\u00e1cula nos da una muestra de los niveles de hipocres\u00eda que pueden llegar a alcanzar. Seg\u00fan informaron distintos medios de prensa, locales y de Argentina, el hijo de la Senadora y l\u00edder bloque de senadores del Frente Guas\u00fa, Esperanza Mart\u00ednez, fue detenido\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/esperanza-martinez.jpg?fit=700%2C394&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9853,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/31\/ataque-mortal-en-san-ber-verificaran-vehiculo-de-uno-de-los-fallecidos-y-aguardan-cuerpos-para-inspeccion\/","url_meta":{"origin":13482,"position":5},"title":"Ataque mortal en San Ber: verificar\u00e1n veh\u00edculo de uno de los fallecidos y aguardan cuerpos para inspecci\u00f3n","date":"31 de enero de 2022","format":false,"excerpt":"Esta ma\u00f1ana ser\u00e1 verificada la camioneta de una de las personas fallecidas en el ataque mortal registrado anoche en la fiesta Ja\u2019umina, en el anfiteatro de San Bernardino. Se trata de Marcos Rojas Mora. El rodado est\u00e1 inscripto a nombre de Osvaldo Ort\u00edz. La apertura estar\u00e1 a cargo del fiscal\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/jaumina-sanber.jpg?fit=660%2C330&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=13482"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13482\/revisions"}],"predecessor-version":[{"id":13484,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13482\/revisions\/13484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/13483"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=13482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=13482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=13482"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=13482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}