{"id":13476,"date":"2022-08-21T10:54:16","date_gmt":"2022-08-21T13:54:16","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=13476"},"modified":"2022-08-21T10:54:19","modified_gmt":"2022-08-21T13:54:19","slug":"la-moda-como-dogma","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/","title":{"rendered":"La moda como dogma"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por <a href=\"https:\/\/twitter.com\/KrauerAquino\" target=\"_blank\" rel=\"noreferrer noopener\">Nicol\u00e1s Ezequiel Aquino Krauer<\/a><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Si hay algo que es un hecho hoy en d\u00eda, es que el devenir de todo el progresismo (entendi\u00e9ndose como ideolog\u00eda), ya sea el feminismo, indigenismo, ideolog\u00eda de g\u00e9nero, entre otras manifestaciones m\u00e1s influyentes y actuales del mismo, para nada vino a imponerse por medio de \u201cLa coerci\u00f3n estatal\u201d. Es m\u00e1s, por m\u00e1s cierta afinidad que nuestro actual gobierno tenga con sectores de izquierda, sus adherentes (al progresismo) al menos la poblaci\u00f3n m\u00e1s joven, ni siquiera tienen v\u00ednculo alguno con el estado. Tratando de comprender este fen\u00f3meno, describo aqu\u00ed, el c\u00f3mo y por qu\u00e9 el progresismo actualmente consigue semejante cantidad de adherentes, sin siquiera tener participaci\u00f3n pol\u00edtica mayoritaria (como es el caso de otros pa\u00edses: Argentina, Chile), usando a la moda como medio. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Es claro que el hombre siempre tiende y tendera hacia lo que la mayor\u00eda dicta, ya sea por su ideolog\u00eda, filosof\u00eda, religi\u00f3n, ideales o por alg\u00fan vac\u00edo mismo que busque llenar; la tendencia como tal quiz\u00e1s sea el mecanismo m\u00e1s antiguo y at\u00e1vico que el hombre tenga para dirigir correctamente acciones y pensamientos, de manera tal que la cr\u00edtica a describir no es contra la tendencia o moda en s\u00ed mismo sino a su contenido propiamente dicho, que vendr\u00eda a constituir una nueva especie de verdad universal (Dogma) tan proclamada por la generaci\u00f3n actual. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">De manera general, se podr\u00eda decir que el contenido de la tendencia del hombre premoderno lo dicto en su mayor\u00eda la Teolog\u00eda, en donde la funci\u00f3n de las redes sociales (en t\u00e9rminos actuales) reca\u00eda meramente sobre la Iglesia. Luego con la secularizaci\u00f3n cultural que Occidente en su mayor\u00eda vivi\u00f3, el rol de la tendencia fue guiada por el Estado Moderno (\u00e9poca en que el modernismo tuvo su auge), donde se podr\u00eda decir que la Revoluci\u00f3n Francesa tuvo principal participaci\u00f3n y a la vez que secularizaban toda instituci\u00f3n, endiosaban el mismo estado, de manera que la nueva religi\u00f3n y a la vez tendencia seria pr\u00e1cticamente la adoraci\u00f3n comunitaria de todo ente civil desligado de la Iglesia. Para luego pasar a la actualidad y a lo que muchos reconocen como posmodernidad, en donde el mismo t\u00e9rmino \u201ctendencia\u201d se popularizo a la vez que la falta de sentido, de preferencia sexual hasta incluso la misma identidad sexual son productos de una tendencia exclusivamente de redes sociales tan vol\u00e1tiles, banales y manipulables. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En la \u201cmodernidad liquida\u201d, al decir de Bauman, el principal peligro de las tendencias actuales, es que los mecanismos con que se crean son m\u00e1s vol\u00e1tiles que nunca y est\u00e1n al servicio del mejor postor (empresas, corporaciones, \u201cfundaciones\u201d, \u201cfil\u00e1ntropos\u201d, etc.), yendo totalmente en detrimento en lo que anteriormente la tradici\u00f3n espont\u00e1neamente forjaba y no estaba sujeta por el \u201cInfluencer\u201d de turno. E incluso indagando a\u00fan m\u00e1s los mecanismos tan inestables actuales en el que la tendencia se crea, es el contenido de la misma la que involucra de un est\u00edmulo compulsivo, creando como dir\u00eda Jordan Peterson un efecto de retroalimentaci\u00f3n positiva, generando una dependencia extrema de esos cambios superfluos para saciar el est\u00edmulo y la demanda cada vez m\u00e1s de contenidos \u201cm\u00e1s f\u00e1ciles de digerir\u201d. Pero adentrando al tema de fondo, \u00bfpor qu\u00e9 catalogo a las actuales modas como dogma?: es claro, la gente necesita sentido, creencia, trascendencia, aceptaci\u00f3n, un norte, un grupo al cual pertenecer, y si anteriormente nos brindaban eso instituciones muchos m\u00e1s estables como la Iglesia o el estado (al que particularmente no adhiero mucho, pero he de reconocer su inmensa estabilidad frente a las tendencia actuales) y sus adherentes lo defend\u00edan, por supuesto, el mismo efecto generaran los nuevos proveedores de tendencia: las redes sociales. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Entendiendo esto, no es de extra\u00f1ar que grupos de \u201cfans\u201d sufran por la separaci\u00f3n de su banda, clamen censura por el m\u00e1s m\u00ednimo reproche hacia sus \u00eddolos, propongan que toda la atenci\u00f3n publica este al servicio de su ideolog\u00eda de Moda hasta el punto de institucionalizarlos, glorifiquen a sus faranduleros favoritos, practiquen cualquier \u201cChallenge\u201d en la medida de los likes, y sobre todo \u201camen\u201d la tolerancia en la medida que no cuestione su identidad sexual del d\u00eda. Si no quedo claro, todo lo dem\u00e1s mencionado son paralelismos religiosos, que ilustran como las nuevas modas vendr\u00edan a constituir las nuevas pr\u00e1cticas dogm\u00e1ticas del tan aclamado S.XXI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Nicol\u00e1s Ezequiel Aquino Krauer Si hay algo que es un hecho hoy en d\u00eda, es que el devenir de todo el progresismo (entendi\u00e9ndose como ideolog\u00eda), ya sea el feminismo, indigenismo, ideolog\u00eda de g\u00e9nero, entre otras manifestaciones m\u00e1s influyentes y actuales del mismo, para nada vino a imponerse por medio de \u201cLa coerci\u00f3n estatal\u201d. Es [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":false},"categories":[248],"tags":[1036,1919,1286],"ppma_author":[1051],"class_list":["post-13476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-destacada","tag-dogmatismo","tag-progresismo"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La moda como dogma - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La moda como dogma - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Por Nicol\u00e1s Ezequiel Aquino Krauer Si hay algo que es un hecho hoy en d\u00eda, es que el devenir de todo el progresismo (entendi\u00e9ndose como ideolog\u00eda), ya sea el feminismo, indigenismo, ideolog\u00eda de g\u00e9nero, entre otras manifestaciones m\u00e1s influyentes y actuales del mismo, para nada vino a imponerse por medio de \u201cLa coerci\u00f3n estatal\u201d. Es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-21T13:54:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-21T13:54:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/dogmaitismo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1281\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"La moda como dogma\",\"datePublished\":\"2022-08-21T13:54:16+00:00\",\"dateModified\":\"2022-08-21T13:54:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/\"},\"wordCount\":785,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/dogmaitismo.jpg?fit=1281%2C676&ssl=1\",\"keywords\":[\"destacada\",\"dogmatismo\",\"progresismo\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/\",\"name\":\"La moda como dogma - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/dogmaitismo.jpg?fit=1281%2C676&ssl=1\",\"datePublished\":\"2022-08-21T13:54:16+00:00\",\"dateModified\":\"2022-08-21T13:54:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/dogmaitismo.jpg?fit=1281%2C676&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/dogmaitismo.jpg?fit=1281%2C676&ssl=1\",\"width\":1281,\"height\":676},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/21\\\/la-moda-como-dogma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La moda como dogma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La moda como dogma - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/","og_locale":"es_ES","og_type":"article","og_title":"La moda como dogma - Informatepy","og_description":"Por Nicol\u00e1s Ezequiel Aquino Krauer Si hay algo que es un hecho hoy en d\u00eda, es que el devenir de todo el progresismo (entendi\u00e9ndose como ideolog\u00eda), ya sea el feminismo, indigenismo, ideolog\u00eda de g\u00e9nero, entre otras manifestaciones m\u00e1s influyentes y actuales del mismo, para nada vino a imponerse por medio de \u201cLa coerci\u00f3n estatal\u201d. Es [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-08-21T13:54:16+00:00","article_modified_time":"2022-08-21T13:54:19+00:00","og_image":[{"width":1281,"height":676,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/dogmaitismo.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"La moda como dogma","datePublished":"2022-08-21T13:54:16+00:00","dateModified":"2022-08-21T13:54:19+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/"},"wordCount":785,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/dogmaitismo.jpg?fit=1281%2C676&ssl=1","keywords":["destacada","dogmatismo","progresismo"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/","url":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/","name":"La moda como dogma - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/dogmaitismo.jpg?fit=1281%2C676&ssl=1","datePublished":"2022-08-21T13:54:16+00:00","dateModified":"2022-08-21T13:54:19+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/dogmaitismo.jpg?fit=1281%2C676&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/dogmaitismo.jpg?fit=1281%2C676&ssl=1","width":1281,"height":676},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/21\/la-moda-como-dogma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"La moda como dogma"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/dogmaitismo.jpg?fit=1281%2C676&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":6724,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/24\/alejandro-diaz-arce-nueva-victima-de-la-intolerancia-progresista\/","url_meta":{"origin":13476,"position":0},"title":"Alejandro D\u00edaz Arce, nueva v\u00edctima de la intolerancia \u201cprogresista\u201d","date":"24 de agosto de 2021","format":false,"excerpt":"Por definici\u00f3n, el progresismo es la ideolog\u00eda y doctrina que defiende y busca el desarrollo y el progreso de la sociedad en todos los \u00e1mbitos y especialmente en el pol\u00edtico-social pero, a juzgar por como le gusta hacer las cosas a los progresistas locales, est\u00e1n m\u00e1s cerca de ser una\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/alejandro-diaz-arce.png?fit=508%2C331&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13350,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/","url_meta":{"origin":13476,"position":1},"title":"La batalla de Acosta \u00d1\u00fa y las batallas actuales","date":"15 de agosto de 2022","format":false,"excerpt":"\u00bfQui\u00e9n no estudi\u00f3, ley\u00f3 o escuch\u00f3 los relatos de la ignominiosa Batalla de Acosta \u00d1u? Como paraguayos, cada vez que recordamos el vil ataque y muerte de nuestros ni\u00f1os, en el campo de batalla, se nos arruga el coraz\u00f3n, se nos agrieta el esp\u00edritu. M\u00e1s de 100 a\u00f1os pasaron y\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/ideologia-genero.jpg?fit=1200%2C657&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11535,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/08\/educacion-sexual-integral-esi-la-ignorancia-del-progresista-que-no-sabe-lo-que-pide-pero-lo-quiere-ya\/","url_meta":{"origin":13476,"position":2},"title":"Educaci\u00f3n Sexual Integral (ESI): La ignorancia del progresista que no sabe lo que pide, pero lo quiere ya","date":"8 de mayo de 2022","format":false,"excerpt":"En la actualidad, ser \u201cprogresista\u201d es manifestar un profundo desconocimiento de las fuerzas que existen en la naturaleza humana. Una de esas fuerzas -profunda, misteriosa y poderosa- es la que deriva del impulso sexual, y es tan primordial, tan imperiosamente necesaria que millones de a\u00f1os de evoluci\u00f3n se han asegurado\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/05\/evolucion-progre.jpg?fit=1200%2C750&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12806,"url":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/la-hipocresia-progresista-ii\/","url_meta":{"origin":13476,"position":3},"title":"La hipocres\u00eda progresista II","date":"24 de julio de 2022","format":false,"excerpt":"Hace poco m\u00e1s de un a\u00f1o, en ocasi\u00f3n del mes del \"Orgullo (?) gay\" escrib\u00ed acerca de la hipocres\u00eda progresista, en ese momento fue una cr\u00edtica a las empresas que a lo largo del mes, en los pa\u00edses libres sin importar el sentido del pueblo, te bombardeaban con banderas arco\u00edris\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/carlos-gomez.jpg?fit=1200%2C699&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12051,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/10\/la-educacion-y-la-ciencia-progresista-en-la-actualidad\/","url_meta":{"origin":13476,"position":4},"title":"La educaci\u00f3n y la ciencia progresista en la actualidad","date":"10 de junio de 2022","format":false,"excerpt":"La educaci\u00f3n es la bandera de lucha de varias organizaciones, grupos de ciudadanos autonombrados comprometidos con la educaci\u00f3n, as\u00ed como organismos internacionales. Se los identifica por sus programas de asesoramiento en temas relacionados a la ni\u00f1ez y la educaci\u00f3n, por lo cual, la lista es extensa. Se camuflan con supuestas\u2026","rel":"","context":"En \u00abCultura\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/lgbtI-escuela.jpg?fit=1138%2C604&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7209,"url":"https:\/\/informatepy.com\/2021\/2021\/09\/19\/entrevista-exclusiva-con-miklos-lukacs\/","url_meta":{"origin":13476,"position":5},"title":"Entrevista exclusiva con Miklos Lukacs: \u00abLos organismos supranacionales son una argucia de democracia\u00bb","date":"19 de septiembre de 2021","format":false,"excerpt":"Miklos Lukacs de Pereny es PhD en Management de la Universidad de Manchester en el Reino Unido. Actualmente es Profesor Principal de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n de la Universidad de San Mart\u00edn de Porres en Lima, Per\u00fa. Tambi\u00e9n ha sido profesor en las universidades de Essex y Manchester en el\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/entrevista-miklos-lukacs1-scaled.jpg?fit=1200%2C829&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=13476"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13476\/revisions"}],"predecessor-version":[{"id":13478,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13476\/revisions\/13478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/13477"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=13476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=13476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=13476"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=13476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}