{"id":13409,"date":"2022-08-17T15:51:19","date_gmt":"2022-08-17T18:51:19","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=13409"},"modified":"2022-08-17T16:34:05","modified_gmt":"2022-08-17T19:34:05","slug":"el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/","title":{"rendered":"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">En horas de la tarde, el ex ministro de educaci\u00f3n, <strong>Eduardo Petta<\/strong>, mencion\u00f3 que el Tribunal Electoral Partidario (TEP) del Partido Colorado, le neg\u00f3 a su movimiento <strong>\u00abEducaci\u00f3n Primero\u00bb<\/strong>, la sustituci\u00f3n de un candidato al senado por renuncia.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En la comunicaci\u00f3n del TEP, le comunicaron a Petta que resolvieron <strong>NO HACER LUGAR<\/strong> a su pedido por ser \u00e9ste <strong>EXTEMPOR\u00c1NEO<\/strong> y, para solucionar la situaci\u00f3n, <strong>debi\u00f3 reposicionar a sus candidatos para cubrir los espacios.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En pocas palabras, los antecedentes del propio TEP de la ANR indicar\u00edan que, si actuaran conforme a derecho, a la ley; <strong>para hacer lugar a la renuncia de Hugo Vel\u00e1zquez, el movimiento Fuerza Republicana deber\u00eda reposicionar sus candidatos, <\/strong>dejando como \u00fanica dupla viable a<strong> Juan Manuel Brunetti Presidente, Derlis Ozorio Vicepresidente .<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">El Movimiento Educaci\u00f3n Primero ( MEP-ANR ) hizo sustituci\u00f3n por RENUNCIA en la lista senado . El TEP resolvi\u00f3 \ud83d\udc46\ud83c\udffc \u201cRECHAZAR por EXTEMPOR\u00c1NEO\u201d y tuve que plantear REPOSICI\u00d3N. <a href=\"https:\/\/t.co\/hzGhrhDjd4\">pic.twitter.com\/hzGhrhDjd4<\/a><\/p>&mdash; Eduardo Petta (@petta08) <a href=\"https:\/\/twitter.com\/petta08\/status\/1559930434238222343?ref_src=twsrc%5Etfw\">August 17, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En horas de la tarde, el ex ministro de educaci\u00f3n, Eduardo Petta, mencion\u00f3 que el Tribunal Electoral Partidario (TEP) del Partido Colorado, le neg\u00f3 a su movimiento \u00abEducaci\u00f3n Primero\u00bb, la sustituci\u00f3n de un candidato al senado por renuncia. En la comunicaci\u00f3n del TEP, le comunicaron a Petta que resolvieron NO HACER LUGAR a su pedido [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13410,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[267,1036,360,1587,423],"ppma_author":[1051],"class_list":["post-13409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-anr","tag-destacada","tag-eduardo-petta","tag-elecciones-2023","tag-partido-colorado"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta - Informatepy\" \/>\n<meta property=\"og:description\" content=\"En horas de la tarde, el ex ministro de educaci\u00f3n, Eduardo Petta, mencion\u00f3 que el Tribunal Electoral Partidario (TEP) del Partido Colorado, le neg\u00f3 a su movimiento \u00abEducaci\u00f3n Primero\u00bb, la sustituci\u00f3n de un candidato al senado por renuncia. En la comunicaci\u00f3n del TEP, le comunicaron a Petta que resolvieron NO HACER LUGAR a su pedido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-17T18:51:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-17T19:34:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/eduardo-petta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1016\" \/>\n\t<meta property=\"og:image:height\" content=\"677\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta\",\"datePublished\":\"2022-08-17T18:51:19+00:00\",\"dateModified\":\"2022-08-17T19:34:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/\"},\"wordCount\":155,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/eduardo-petta.jpg?fit=1016%2C677&ssl=1\",\"keywords\":[\"anr\",\"destacada\",\"eduardo petta\",\"elecciones 2023\",\"partido colorado\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/\",\"name\":\"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/eduardo-petta.jpg?fit=1016%2C677&ssl=1\",\"datePublished\":\"2022-08-17T18:51:19+00:00\",\"dateModified\":\"2022-08-17T19:34:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/eduardo-petta.jpg?fit=1016%2C677&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/eduardo-petta.jpg?fit=1016%2C677&ssl=1\",\"width\":1016,\"height\":677},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/","og_locale":"es_ES","og_type":"article","og_title":"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta - Informatepy","og_description":"En horas de la tarde, el ex ministro de educaci\u00f3n, Eduardo Petta, mencion\u00f3 que el Tribunal Electoral Partidario (TEP) del Partido Colorado, le neg\u00f3 a su movimiento \u00abEducaci\u00f3n Primero\u00bb, la sustituci\u00f3n de un candidato al senado por renuncia. En la comunicaci\u00f3n del TEP, le comunicaron a Petta que resolvieron NO HACER LUGAR a su pedido [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-08-17T18:51:19+00:00","article_modified_time":"2022-08-17T19:34:05+00:00","og_image":[{"width":1016,"height":677,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/eduardo-petta.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta","datePublished":"2022-08-17T18:51:19+00:00","dateModified":"2022-08-17T19:34:05+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/"},"wordCount":155,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/eduardo-petta.jpg?fit=1016%2C677&ssl=1","keywords":["anr","destacada","eduardo petta","elecciones 2023","partido colorado"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/","url":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/","name":"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/eduardo-petta.jpg?fit=1016%2C677&ssl=1","datePublished":"2022-08-17T18:51:19+00:00","dateModified":"2022-08-17T19:34:05+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/eduardo-petta.jpg?fit=1016%2C677&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/eduardo-petta.jpg?fit=1016%2C677&ssl=1","width":1016,"height":677},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/eduardo-petta.jpg?fit=1016%2C677&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1625,"url":"https:\/\/informatepy.com\/2021\/2019\/11\/22\/mas-de-5-000-candidaturas-ingresaron-por-orden-judicial-en-la-juventud-de-la-anr\/","url_meta":{"origin":13409,"position":0},"title":"M\u00e1s de 5.000 candidaturas ingresaron por orden judicial en la Juventud de la ANR","date":"22 de noviembre de 2019","format":false,"excerpt":"Un total de 5.402 candidaturas entraron al Tribunal Electoral Partidario (TEP) de la Asociaci\u00f3n Nacional Republicana (ANR) por orden judicial, posterior a la oficializaci\u00f3n de las postulaciones, seg\u00fan el cronograma de las elecciones de la Comisi\u00f3n Central de la Juventud Colorada. 550 personas no cumplen con las exigencias establecidas en\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/jovenes-anr-inscripcion.jpg?fit=730%2C478&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13447,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/19\/juan-manuel-brunetti-destaca-decision-del-tep-y-reconoce-ventaja-de-santiago-pena-para-las-internas\/","url_meta":{"origin":13409,"position":1},"title":"Juan Manuel Brunetti destaca decisi\u00f3n del TEP y reconoce ventaja de Santiago Pe\u00f1a para las internas","date":"19 de agosto de 2022","format":false,"excerpt":"Juan Manuel Brunetti, precandidato a la vicepresidencia por Fuerza Republicana (ANR) se\u00f1al\u00f3, en comunicaci\u00f3n con la radio 780 AM, que fue coherente la decisi\u00f3n del Tribunal Electoral Partidario (TEP) de la Asociaci\u00f3n Nacional Republicana (ANR) al habilitar la inscripci\u00f3n de la nueva chapa para las internas. \u201cNosotros confi\u00e1bamos en que\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/Juan-Manuel-Brunetti.jpg?fit=679%2C395&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13275,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/12\/como-queda-fuerza-republicana-con-la-renuncia-de-hugo-velazquez\/","url_meta":{"origin":13409,"position":2},"title":"\u00bfC\u00f3mo queda Fuerza Republicana con la renuncia de Hugo Vel\u00e1zquez?","date":"12 de agosto de 2022","format":false,"excerpt":"Apenas conocida la renuncia del vicepresidente, Hugo Vel\u00e1zquez, a su precandidatura presidencial, en redes sociales se origin\u00f3 el debate acerca de como quedaba Fuerza Republicana al verse descabezada. Antes las posturas encontradas, consultamos a integrantes del Tribunal Electoral Partidario (TEP) de la Asociaci\u00f3n Nacional Republicana (ANR) sobre cual es la\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/edificio-anr.jpg?fit=1200%2C731&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1692,"url":"https:\/\/informatepy.com\/2021\/2019\/12\/13\/denuncian-a-marcelo-centurion-por-privacion-ilegitima-de-la-libertad\/","url_meta":{"origin":13409,"position":3},"title":"Denuncian a Marcelo Centuri\u00f3n por privaci\u00f3n ileg\u00edtima de la libertad","date":"13 de diciembre de 2019","format":false,"excerpt":"El apoderado de la Asociaci\u00f3n Nacional Republicana (ANR), Eduardo Gonz\u00e1lez, present\u00f3 este jueves una denuncia ante el Ministerio P\u00fablico contra Marcelo Centuri\u00f3n, candidato del movimiento Fuerza Renovadora Republicana para las elecciones juveniles. La denuncia es por privaci\u00f3n ileg\u00edtima de libertad, coacci\u00f3n, coacci\u00f3n grave, y perturbaci\u00f3n a la paz p\u00fablica, esto\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/centurion-y-mario-abdo-paraguari.jpg?fit=1020%2C781&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9271,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/lilian-samaniego-el-tep-de-la-anr-no-da-garantias\/","url_meta":{"origin":13409,"position":4},"title":"Lilian Samaniego: \u00abEl TEP de la ANR no da garant\u00edas\u00bb","date":"6 de enero de 2022","format":false,"excerpt":"Seg\u00fan el criterio de la senadora Lilian Samaniego, el Tribunal Electoral Partidario de la ANR no da garant\u00edas para el proceso electoral. Destac\u00f3, adem\u00e1s, que todas las autoridades tanto del Tribunal como de los miembros de la junta y todas las autoridades de la estructura del partido se encuentran con\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/lilian-samaniego.png?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":900,"url":"https:\/\/informatepy.com\/2021\/2019\/03\/19\/anr-tiene-todo-organizado-para-elecciones-internas-en-cde\/","url_meta":{"origin":13409,"position":5},"title":"La ANR tiene todo organizado para elecciones internas en CDE","date":"19 de marzo de 2019","format":false,"excerpt":"El Tribunal Electoral de la Asociaci\u00f3n Nacional Republicana (ANR), expuso en conferencia de prensa, todos los detalles que conlleva la organizaci\u00f3n de las elecciones internas del partido colorado para elegir al candidato a intendente que los representar\u00e1 en los comicios de Ciudad del Este. Santiago Brizuela, miembro titular, y el\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/tribunal-electoral-cde-colorados.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=13409"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13409\/revisions"}],"predecessor-version":[{"id":13411,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13409\/revisions\/13411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/13410"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=13409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=13409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=13409"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=13409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}