{"id":13350,"date":"2022-08-15T09:37:34","date_gmt":"2022-08-15T12:37:34","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=13350"},"modified":"2022-08-15T09:37:34","modified_gmt":"2022-08-15T12:37:34","slug":"la-batalla-de-acosta-nu-y-las-batallas-actuales","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/","title":{"rendered":"La batalla de Acosta \u00d1\u00fa y las batallas actuales"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">\u00bfQui\u00e9n no estudi\u00f3, ley\u00f3 o escuch\u00f3 los relatos de la ignominiosa Batalla de Acosta \u00d1u? Como paraguayos, cada vez que recordamos el vil ataque y muerte de nuestros ni\u00f1os, en el campo de batalla, se nos arruga el coraz\u00f3n, se nos agrieta el esp\u00edritu. M\u00e1s de 100 a\u00f1os pasaron y hoy cada 16 de agosto, celebramos el d\u00eda del ni\u00f1o en Paraguay, en memoria de aquellos peque\u00f1os ca\u00eddos a manos de los sanguinarios e inmisericordes enemigos.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Hoy nuevamente vivimos tiempos de amenazas contra nuestros chicos y j\u00f3venes, no estamos en una guerra convencional pero s\u00ed libramos una guerra cultural declarada, y no menos peligrosa o amenazante. Hoy los enemigos no atacan por medio de ej\u00e9rcitos convencionales, hoy los ej\u00e9rcitos son ONG, bien financiadas desde el extranjero y sus c\u00f3mplices funcionarios p\u00fablicos ignorantes, indolentes o \u00e1vidos de m\u00e1s fondos y presupuesto. Las armas hoy no son las de fuego, las nuevas armas son las ideas, y con mayor precisi\u00f3n, las ideolog\u00edas.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La nueva estrategia de destrucci\u00f3n, no es la militar, es la \u201cAGENDA GLOBALISTA\u201d, uno de los puntos centrales de esta nueva estrategia, es la IDEOLOG\u00cdA DE G\u00c9NERO, que disfrazada bajo el nombre de EDUCACI\u00d3N SEXUAL INTEGRAL, ENFOQUE DE GENERO, ENFOQUE DE DERECHOS, ENFOQUE DE INTERCULTURALIDAD, ENFOQUE DE INCLUSI\u00d3N, se pretende implantar en nuestro sistema educativo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/t.co\/QwpsBVuuiC\">https:\/\/t.co\/QwpsBVuuiC<\/a><br>Fragmento de la transmisi\u00f3n de la ONG CDIA, desde su p\u00e1g de FB<br>Educaci\u00f3n Sexual Integral fuera de las escuelas, Club de Adolescentes<br>Compromiso con el Enfoque de Derechos, la Participaci\u00f3n Protag\u00f3nica, el Enfoque de G\u00e9nero y la Diversidad <a href=\"https:\/\/t.co\/ru9XFE7Vlm\">pic.twitter.com\/ru9XFE7Vlm<\/a><\/p>&mdash; Vale Insfran (@ValeInsfran4) <a href=\"https:\/\/twitter.com\/ValeInsfran4\/status\/1558044429096722433?ref_src=twsrc%5Etfw\">August 12, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">\u00bfQu\u00e9 implica la ense\u00f1anza en ideolog\u00eda de g\u00e9nero? Implica que a tu hijo, nieto, sobrino, escolarizado y sea la edad que tenga, se le ense\u00f1e que aunque haya nacido var\u00f3n puede elegir ser nena y viceversa. Pone de moda la homosexualidad y paulatinamente promueve probar de todo sexualmente. Esta es la explicaci\u00f3n m\u00e1s coloquial que puedo dar.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/t.co\/KGk2kPhHEm\">https:\/\/t.co\/KGk2kPhHEm<\/a><br>A confesi\u00f3n de parte, relevo de pruebas<br>Desde la p\u00e1gina de FB de la ONG CDIA, miembro del Consejo Nacional de Ni\u00f1ez y Adolescencia, se confirman las denuncias que los padres estamos haciendo contra la Transformaci\u00f3n Educativa <a href=\"https:\/\/t.co\/bvE7xC3ru3\">https:\/\/t.co\/bvE7xC3ru3<\/a> <a href=\"https:\/\/t.co\/Quvojw4GLz\">pic.twitter.com\/Quvojw4GLz<\/a><\/p>&mdash; Vale Insfran (@ValeInsfran4) <a href=\"https:\/\/twitter.com\/ValeInsfran4\/status\/1558036361613131777?ref_src=twsrc%5Etfw\">August 12, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">\u00bfC\u00f3mo la definen los estudiosos? Es un conjunto de ideas anticient\u00edficas, que con prop\u00f3sitos pol\u00edticos, autoritarios, desarraigan a la sexualidad humana de su naturaleza y la explican monop\u00f3licamente por la cultura. Pretende que el hecho biol\u00f3gico de haber nacido var\u00f3n o mujer no resulta determinante, es reversible e incluso debe ser le\u00eddo como un episodio m\u00e1s de la lucha de clases, pretende cambiar la naturaleza humana a la que atribuye no un origen natural sino pol\u00edtico. La ideolog\u00eda de g\u00e9nero implicar\u00e1 el final de la naturaleza biol\u00f3gica del ser humano y con ello el final de los sexos como los conocemos. Es la deconstrucci\u00f3n sistem\u00e1tica de las pr\u00e1cticas sexuales naturales y del sistema de sexos. Es una subversi\u00f3n cultural.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Esta potente amenaza contra nuestra ni\u00f1ez, tiene efectos devastadores, f\u00edsica, ps\u00edquica y espiritualmente. La IDEOLOG\u00cdA DE G\u00c9NERO una vez m\u00e1s se camufla bajo apariencia de libertad y progresismo, cuando realmente est\u00e1 basada en puro libertinaje, desorden y negaci\u00f3n de la propia biolog\u00eda humana. Si algo tiene de progresista es que su ense\u00f1anza avanza progresivamente hasta convertirse en obligatoria, no discrimina escuelas p\u00fablicas o privadas, cat\u00f3licas o laicas, tampoco le importa el consentimiento de los padres. As\u00ed es que, en otros pa\u00edses, donde su implementaci\u00f3n est\u00e1 m\u00e1s desarrollada, los padres que se oponen a que sus hijos sean adoctrinados en ella, son penados con la p\u00e9rdida de la patria potestad.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"352\" style=\"aspect-ratio: 640 \/ 352;\" width=\"640\" controls src=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/WhatsApp-Video-2022-08-14-at-7.17.58-PM.mp4\"><\/video><\/figure>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Ma\u00f1ana 16 de agosto, celebraremos como siempre el d\u00eda del ni\u00f1o. Recordaremos a los ni\u00f1os de Acosta \u00d1u, que pelearon defendiendo la Patria porque ya sus padres hab\u00edan sido aniquilados por las fuerzas aliadas, otros pelearon a lado de sus padres y continuaron empu\u00f1ando las armas, cuando durante aquella batalla, sus padres ca\u00edan muertos a su lado.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La batalla, que hace 153 a\u00f1os, libraron los ni\u00f1os del Paraguay, porque el genocidio hab\u00eda pr\u00e1cticamente acabado con los adultos, hoy la damos los padres, los abuelos, los t\u00edos y cada ciudadano consciente de la responsabilidad que como sociedad tenemos hacia los menores. No dejaremos de denunciar los atropellos, ni de se\u00f1alar a los responsables y c\u00f3mplices de implementar pol\u00edticas p\u00fablicas que lesionan irreparablemente a los chicos y j\u00f3venes de nuestra naci\u00f3n.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Sabemos que desde el Gobierno se avanza con la Transformaci\u00f3n Educativa, incluso con los conceptos de genero objetados y que dicen haber retirado del plan. Aqu\u00ed les dejo un video de la semana pasada, funcionarios p\u00fablicos expresamente lo afirman. Fue en el marco de la Semana por los derechos de ni\u00f1as, ni\u00f1os y adolescentes, transmitida desde la p\u00e1g. de Facebook de la ONG CDIA. Y llegado el momento el pa\u00eds se va a levantar en contra de las aberraciones que pretenden imponernos, vengan y prueben. Una vez m\u00e1s les recordaremos de qu\u00e9 est\u00e1 hecho el paraguayo, su alta dignidad, su valent\u00eda, su patriotismo y su amor infinito a sus hijos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9n no estudi\u00f3, ley\u00f3 o escuch\u00f3 los relatos de la ignominiosa Batalla de Acosta \u00d1u? Como paraguayos, cada vez que recordamos el vil ataque y muerte de nuestros ni\u00f1os, en el campo de batalla, se nos arruga el coraz\u00f3n, se nos agrieta el esp\u00edritu. M\u00e1s de 100 a\u00f1os pasaron y hoy cada 16 de agosto, [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":13352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":false},"categories":[177],"tags":[1036,463,1193],"ppma_author":[1339],"class_list":["post-13350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-destacada","tag-ideologia-de-genero","tag-lgbt"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La batalla de Acosta \u00d1\u00fa y las batallas actuales - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La batalla de Acosta \u00d1\u00fa y las batallas actuales - Informatepy\" \/>\n<meta property=\"og:description\" content=\"\u00bfQui\u00e9n no estudi\u00f3, ley\u00f3 o escuch\u00f3 los relatos de la ignominiosa Batalla de Acosta \u00d1u? Como paraguayos, cada vez que recordamos el vil ataque y muerte de nuestros ni\u00f1os, en el campo de batalla, se nos arruga el coraz\u00f3n, se nos agrieta el esp\u00edritu. M\u00e1s de 100 a\u00f1os pasaron y hoy cada 16 de agosto, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-15T12:37:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/ideologia-genero.jpg?fit=1281%2C701&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1281\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valeria Insfran\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valeria Insfran\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/\"},\"author\":{\"name\":\"Valeria Insfran\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/b3b98d57fb375b5ae5aab608d88526be\"},\"headline\":\"La batalla de Acosta \u00d1\u00fa y las batallas actuales\",\"datePublished\":\"2022-08-15T12:37:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/\"},\"wordCount\":841,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/ideologia-genero.jpg?fit=1281%2C701&ssl=1\",\"keywords\":[\"destacada\",\"ideologia de genero\",\"lgbt\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/\",\"name\":\"La batalla de Acosta \u00d1\u00fa y las batallas actuales - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/ideologia-genero.jpg?fit=1281%2C701&ssl=1\",\"datePublished\":\"2022-08-15T12:37:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/ideologia-genero.jpg?fit=1281%2C701&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/ideologia-genero.jpg?fit=1281%2C701&ssl=1\",\"width\":1281,\"height\":701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/15\\\/la-batalla-de-acosta-nu-y-las-batallas-actuales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La batalla de Acosta \u00d1\u00fa y las batallas actuales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/b3b98d57fb375b5ae5aab608d88526be\",\"name\":\"Valeria Insfran\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Valeria-Insfran.jpg?fit=54%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Valeria-Insfran.jpg?fit=54%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Valeria-Insfran.jpg?fit=54%2C96&ssl=1\",\"caption\":\"Valeria Insfran\"},\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/vinsfran\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La batalla de Acosta \u00d1\u00fa y las batallas actuales - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/","og_locale":"es_ES","og_type":"article","og_title":"La batalla de Acosta \u00d1\u00fa y las batallas actuales - Informatepy","og_description":"\u00bfQui\u00e9n no estudi\u00f3, ley\u00f3 o escuch\u00f3 los relatos de la ignominiosa Batalla de Acosta \u00d1u? Como paraguayos, cada vez que recordamos el vil ataque y muerte de nuestros ni\u00f1os, en el campo de batalla, se nos arruga el coraz\u00f3n, se nos agrieta el esp\u00edritu. M\u00e1s de 100 a\u00f1os pasaron y hoy cada 16 de agosto, [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/","og_site_name":"Informatepy","article_published_time":"2022-08-15T12:37:34+00:00","og_image":[{"width":1281,"height":701,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/ideologia-genero.jpg?fit=1281%2C701&ssl=1","type":"image\/jpeg"}],"author":"Valeria Insfran","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Valeria Insfran","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/"},"author":{"name":"Valeria Insfran","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/b3b98d57fb375b5ae5aab608d88526be"},"headline":"La batalla de Acosta \u00d1\u00fa y las batallas actuales","datePublished":"2022-08-15T12:37:34+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/"},"wordCount":841,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/ideologia-genero.jpg?fit=1281%2C701&ssl=1","keywords":["destacada","ideologia de genero","lgbt"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/","url":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/","name":"La batalla de Acosta \u00d1\u00fa y las batallas actuales - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/ideologia-genero.jpg?fit=1281%2C701&ssl=1","datePublished":"2022-08-15T12:37:34+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/ideologia-genero.jpg?fit=1281%2C701&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/ideologia-genero.jpg?fit=1281%2C701&ssl=1","width":1281,"height":701},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/15\/la-batalla-de-acosta-nu-y-las-batallas-actuales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"La batalla de Acosta \u00d1\u00fa y las batallas actuales"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/b3b98d57fb375b5ae5aab608d88526be","name":"Valeria Insfran","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/Valeria-Insfran.jpg?fit=54%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/Valeria-Insfran.jpg?fit=54%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/Valeria-Insfran.jpg?fit=54%2C96&ssl=1","caption":"Valeria Insfran"},"url":"https:\/\/informatepy.com\/2021\/author\/vinsfran\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/ideologia-genero.jpg?fit=1281%2C701&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":8525,"url":"https:\/\/informatepy.com\/2021\/2021\/11\/27\/familicidio-acosta-nu-2021\/","url_meta":{"origin":13350,"position":0},"title":"Familicidio, Acosta \u00d1\u00fa 2021","date":"27 de noviembre de 2021","format":false,"excerpt":"Periodistas por la verdad nos deja un interesante art\u00edculo, sobre el \u201cAcuerdo de Transformaci\u00f3n Educativa\u201d del Ministerio de Educaci\u00f3n y Ciencias, que apunta a renovar las pol\u00edticas educativas de nuestro pa\u00eds.","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/con-los-ninos-no.jpg?fit=1140%2C759&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13589,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/25\/inauguran-mejoras-en-el-hospital-ninos-de-acosta-nu\/","url_meta":{"origin":13350,"position":1},"title":"Inauguran mejoras en el hospital \u201cNi\u00f1os de Acosta \u00d1u\u201d","date":"25 de agosto de 2022","format":false,"excerpt":"Se habilitaron una serie de mejoras en el Hospital General Pedi\u00e1trico \u201cNi\u00f1os de Acosta \u00d1u\u201d en las \u00e1reas de Terapia Intensiva, Oncohematolog\u00eda y Medicina Interna con el objetivo de brindar una mayor respuesta a los pacientes y con ello optimizar la atenci\u00f3n. En la tarde de ayer se realiz\u00f3 el\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/hosp-acosta-nu.jpg?fit=761%2C452&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11000,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/05\/la-batalla-cultural-incomprendida\/","url_meta":{"origin":13350,"position":2},"title":"La Batalla Cultural incomprendida","date":"5 de abril de 2022","format":false,"excerpt":"Por Rodney Campos Es imposible dar la denominada batalla cultural si aquellos grupos que pretenden darla no la comprenden al punto de caer en la ret\u00f3rica del progresismo y repetir las mismas falacias, con lo cual la batalla cultural antes de darla se encontrar\u00eda perdida, con todas las consecuencias que\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/batalla-cultural.jpg?fit=1200%2C627&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13102,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/rubio-nu-durmio-al-ciclon-de-un-solo-golpe\/","url_meta":{"origin":13350,"position":3},"title":"Rubio \u00d1u durmi\u00f3 al Cicl\u00f3n de un solo golpe","date":"3 de agosto de 2022","format":false,"excerpt":"A pesar de que en la previa del encuentro disputado en el Arsenio Erico, Cerro Porte\u00f1o era el favorito para llevarse el triunfo, los muchachos del barrio Sant\u00edsima Trinidad demostraron tener mucha m\u00e1s actitud y se alzaron con la clasificaci\u00f3n a octavos de final de la Copa Paraguay. El albiverde\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/rubio-nu-cerro.jpg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4326,"url":"https:\/\/informatepy.com\/2021\/2021\/04\/04\/guerra-sin-cuartel\/","url_meta":{"origin":13350,"position":4},"title":"Guerra sin cuartel","date":"4 de abril de 2021","format":false,"excerpt":"Una guerra sin igual se est\u00e1 viviendo, y los prisioneros de guerra son los ciudadanos, est\u00e1 batalla es en muchos \u00e1mbitos el principal de ellos la excusa del virus por parte de los gobiernos para utilizar decretos dictatoriales, adem\u00e1s de aumentar la corrupci\u00f3n y desigualdad. Un sector de la prensa\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/guerra-mentiras.jpg?fit=1200%2C843&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8234,"url":"https:\/\/informatepy.com\/2021\/2021\/11\/10\/la-kurepizacion-de-la-mente\/","url_meta":{"origin":13350,"position":5},"title":"La kurepizaci\u00f3n de la mente","date":"10 de noviembre de 2021","format":false,"excerpt":"Un legendario referente del heavy metal paraguayo, Mariano Hicell Gonz\u00e1lez m\u00e1s conocido como Micr\u00f3n the Machine, antiguo guerrero contra el \u201cNuevo Orden Mundial\u201d y que falleci\u00f3 el 30 de enero de 2020, ten\u00eda un discurso que lleg\u00f3 a hacerse viral en las redes sociales. Compartimos en varias ocasiones por motivos\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/la-comadre.jpeg?fit=800%2C600&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1339,"user_id":24,"is_guest":0,"slug":"vinsfran","display_name":"Valeria Insfran","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/Valeria-Insfran.jpg?fit=54%2C96&ssl=1","first_name":"Valeria","last_name":"Insfran","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=13350"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13350\/revisions"}],"predecessor-version":[{"id":13354,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13350\/revisions\/13354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/13352"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=13350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=13350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=13350"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=13350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}