{"id":13239,"date":"2022-08-11T08:13:41","date_gmt":"2022-08-11T11:13:41","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=13239"},"modified":"2022-08-11T08:13:43","modified_gmt":"2022-08-11T11:13:43","slug":"por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/","title":{"rendered":"Por no defender la soberan\u00eda energ\u00e9tica de Paraguay, cuestionan al presidente por derecha y por izquierda"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">La mala negociaci\u00f3n del gobierno de Mario Abdo, disfrazada de baja de tarifas, fue cuestionada por todo el espectro pol\u00edtico paraguayo por no haber sabido defender la soberan\u00eda paraguaya.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>Lea Gim\u00e9nez<\/strong>, ex ministra de Hacienda y pre candidata a senadora por Honor Colorado, critic\u00f3 duramente al Gobierno por haber aceptado una tarifa intermedia de la energ\u00eda de Itaip\u00fa, beneficiando de esa forma al Brasil.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">A trav\u00e9s de sus redes sociales, Gim\u00e9nez manifest\u00f3: <strong><em>\u201cNi una onza de verg\u00fcenza tienen. Gente inescrupulosa e incapaz de pensar en nada m\u00e1s que en fatos no puede llegar a la Presidencia. La responsabilidad es demasiado grande; votemos por gente id\u00f3nea y con vocaci\u00f3n de servicio\u201d.<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Desde el otro extremo, el parlamentario del Mercosur por el Frente Guas\u00fa, <strong>Ricardo Canese<\/strong>, expres\u00f3 que el presidente de la Rep\u00fablica, Mario Abdo Ben\u00edtez, se neg\u00f3 a ejercer la soberan\u00eda de Paraguay, aceptando la propuesta de Brasil sobre la tarifa de Itaip\u00fa.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong><em>\u201cLa reducci\u00f3n de la tarifa anunciada en realidad es una reducci\u00f3n de la tarifa con la que Brasil compra la energ\u00eda. En concreto, lo que le regala Abdo Ben\u00edtez a Bolsonaro son 94 millones de d\u00f3lares que tendr\u00eda que haber ingresado para la ANDE\u201d<\/em><\/strong>, agreg\u00f3 el parlasuriano.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El ex presidente de la Ande, Pedro Ferreira, asegur\u00f3 que el Paraguay arriesgar\u00e1 US$ 1.000 millones por a\u00f1o con reducci\u00f3n de la tarifa de Itaip\u00fa. <strong><em>\u201cPara Bolsonaro esto es un \u00e9xito y para nuestro pa\u00eds esto me parece triste porque en cuatro meses de rebaja arriesgamos una negociaci\u00f3n por US$ 1.000 millones por a\u00f1o\u201d<\/em><\/strong>, destac\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mala negociaci\u00f3n del gobierno de Mario Abdo, disfrazada de baja de tarifas, fue cuestionada por todo el espectro pol\u00edtico paraguayo por no haber sabido defender la soberan\u00eda paraguaya. Lea Gim\u00e9nez, ex ministra de Hacienda y pre candidata a senadora por Honor Colorado, critic\u00f3 duramente al Gobierno por haber aceptado una tarifa intermedia de la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[562,502,1036,666,667,332],"ppma_author":[1051],"class_list":["post-13239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-bolsonaro","tag-brasil","tag-destacada","tag-itaipu","tag-jair-bolsonaro","tag-mario-abdo"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Por no defender la soberan\u00eda energ\u00e9tica de Paraguay, cuestionan al presidente por derecha y por izquierda - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por no defender la soberan\u00eda energ\u00e9tica de Paraguay, cuestionan al presidente por derecha y por izquierda - Informatepy\" \/>\n<meta property=\"og:description\" content=\"La mala negociaci\u00f3n del gobierno de Mario Abdo, disfrazada de baja de tarifas, fue cuestionada por todo el espectro pol\u00edtico paraguayo por no haber sabido defender la soberan\u00eda paraguaya. Lea Gim\u00e9nez, ex ministra de Hacienda y pre candidata a senadora por Honor Colorado, critic\u00f3 duramente al Gobierno por haber aceptado una tarifa intermedia de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-11T11:13:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-11T11:13:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/itaipu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Por no defender la soberan\u00eda energ\u00e9tica de Paraguay, cuestionan al presidente por derecha y por izquierda\",\"datePublished\":\"2022-08-11T11:13:41+00:00\",\"dateModified\":\"2022-08-11T11:13:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/\"},\"wordCount\":294,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/itaipu.jpg?fit=1280%2C720&ssl=1\",\"keywords\":[\"bolsonaro\",\"brasil\",\"destacada\",\"itaipu\",\"jair bolsonaro\",\"mario abdo\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/\",\"name\":\"Por no defender la soberan\u00eda energ\u00e9tica de Paraguay, cuestionan al presidente por derecha y por izquierda - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/itaipu.jpg?fit=1280%2C720&ssl=1\",\"datePublished\":\"2022-08-11T11:13:41+00:00\",\"dateModified\":\"2022-08-11T11:13:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/itaipu.jpg?fit=1280%2C720&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/itaipu.jpg?fit=1280%2C720&ssl=1\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/11\\\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por no defender la soberan\u00eda energ\u00e9tica de Paraguay, cuestionan al presidente por derecha y por izquierda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por no defender la soberan\u00eda energ\u00e9tica de Paraguay, cuestionan al presidente por derecha y por izquierda - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/","og_locale":"es_ES","og_type":"article","og_title":"Por no defender la soberan\u00eda energ\u00e9tica de Paraguay, cuestionan al presidente por derecha y por izquierda - Informatepy","og_description":"La mala negociaci\u00f3n del gobierno de Mario Abdo, disfrazada de baja de tarifas, fue cuestionada por todo el espectro pol\u00edtico paraguayo por no haber sabido defender la soberan\u00eda paraguaya. Lea Gim\u00e9nez, ex ministra de Hacienda y pre candidata a senadora por Honor Colorado, critic\u00f3 duramente al Gobierno por haber aceptado una tarifa intermedia de la [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-08-11T11:13:41+00:00","article_modified_time":"2022-08-11T11:13:43+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/itaipu.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Por no defender la soberan\u00eda energ\u00e9tica de Paraguay, cuestionan al presidente por derecha y por izquierda","datePublished":"2022-08-11T11:13:41+00:00","dateModified":"2022-08-11T11:13:43+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/"},"wordCount":294,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/itaipu.jpg?fit=1280%2C720&ssl=1","keywords":["bolsonaro","brasil","destacada","itaipu","jair bolsonaro","mario abdo"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/","url":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/","name":"Por no defender la soberan\u00eda energ\u00e9tica de Paraguay, cuestionan al presidente por derecha y por izquierda - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/itaipu.jpg?fit=1280%2C720&ssl=1","datePublished":"2022-08-11T11:13:41+00:00","dateModified":"2022-08-11T11:13:43+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/itaipu.jpg?fit=1280%2C720&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/itaipu.jpg?fit=1280%2C720&ssl=1","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/11\/por-no-defender-la-soberania-energetica-de-paraguay-cuestionan-al-presidente-por-derecha-y-por-izquierda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Por no defender la soberan\u00eda energ\u00e9tica de Paraguay, cuestionan al presidente por derecha y por izquierda"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/itaipu.jpg?fit=1280%2C720&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":8828,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/13\/abdo-y-bolsonaro-se-reunen-hoy-sin-una-definicion-sobre-la-tarifa-de-itaipu\/","url_meta":{"origin":13239,"position":0},"title":"Abdo y Bolsonaro se re\u00fanen hoy sin una definici\u00f3n sobre la tarifa de Itaip\u00fa","date":"13 de diciembre de 2021","format":false,"excerpt":"El presidente Abdo y su par de Brasil, Jair Bolsonaro se reunir\u00e1n hoy en Puerto Murtinho, Brasil y, seguramente, se tratar\u00e1 la tarifa de Itaip\u00fa para el 2022. Mientras que Paraguay pretende mantener el precio mientras que Bolsonaro prometi\u00f3 que bajar\u00eda, como parte de su campa\u00f1a por la reelecci\u00f3n presidencial.\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/abdo-bolsonaro.jpg?fit=780%2C405&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13212,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/09\/bolsonaro-2-marito-0\/","url_meta":{"origin":13239,"position":1},"title":"Bolsonaro 2 &#8211; Marito 0","date":"9 de agosto de 2022","format":false,"excerpt":"Lo que muchos sab\u00edamos que iba a pasar, pas\u00f3. Manuel Mar\u00eda C\u00e1ceres, Director (paraguayo) de la Itaip\u00fa Binacional confirm\u00f3 la tarifa que regir\u00e1 lo que queda de este a\u00f1o, con lo que Brasil se sali\u00f3 con la suya, tal como lo hab\u00eda anunciado el ex gerente t\u00e9cnico de la ANDE,\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/itaipu.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11367,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/27\/cuestionan-la-inaccion-del-gobierno-en-el-caso-itaipu\/","url_meta":{"origin":13239,"position":2},"title":"Cuestionan la inacci\u00f3n del gobierno en el caso Itaip\u00fa","date":"27 de abril de 2022","format":false,"excerpt":"Cecilia Vuyk representante de la campa\u00f1a Itaip\u00fa \u00d1ane Mba\u2019e, se\u00f1al\u00f3 este martes que preocupa la inacci\u00f3n del Gobierno sobre las negociaciones y lament\u00f3 que hasta el momento no haya ning\u00fan avance. \u201cTenemos un silencio preocupante del Gobierno y lo importante son las acciones y en ella tenemos a un Brasil\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5142,"url":"https:\/\/informatepy.com\/2021\/2021\/06\/01\/anexo-c-paraguay-aun-no-sabe-lo-que-pretende-y-debio-definirlo-hace-dos-anos\/","url_meta":{"origin":13239,"position":3},"title":"Anexo C: Paraguay a\u00fan no sabe lo que pretende y debi\u00f3 definirlo hace dos a\u00f1os","date":"1 de junio de 2021","format":false,"excerpt":"El ingeniero y experto energ\u00e9tico, \u00c1ngel Mar\u00eda Recalde, explic\u00f3 este lunes que la renegociaci\u00f3n del Anexo C del Tratado de Itaip\u00fa ser\u00e1 clave para el pa\u00eds porque trata sobre las bases financieras de la entidad y lament\u00f3 que hasta el momento Paraguay no sepa lo que pretende. \u201cEstamos en presencia\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/Ing-Angel-Maria-Recalde.jpg?fit=660%2C330&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1390,"url":"https:\/\/informatepy.com\/2021\/2019\/08\/01\/hoy-paraguay-fue-extorsionado\/","url_meta":{"origin":13239,"position":4},"title":"Hoy, Paraguay fue extorsionado","date":"1 de agosto de 2019","format":false,"excerpt":"En un tramo del discurso pronunciado por el presidente Mario Abdo en la \u00e1lgida jornada de hoy, manifest\u00f3 un especial agradecimiento a los lideres de la regi\u00f3n que le manifestaron su apoyo: \u201c Quiero agradecer tambi\u00e9n a todos los lideres de la regi\u00f3n y del mundo que demostraron su preocupaci\u00f3n\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/EXTORSION.png?fit=769%2C662&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1385,"url":"https:\/\/informatepy.com\/2021\/2019\/08\/01\/nos-quieren-tomar-de-boludos\/","url_meta":{"origin":13239,"position":5},"title":"Nos quieren tomar de boludos","date":"1 de agosto de 2019","format":false,"excerpt":"En pol\u00edtica las casualidades no existen, tampoco los improvisados o, al menos, estos no llegan a Presidente y Vicepresidente de un pa\u00eds; a lo sumo, son asesores de segunda l\u00ednea que se ganan sus monedas agrediendo a los \"disidentes del r\u00e9gimen\" por las redes sociales. Toda esta cuesti\u00f3n del acta\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/abdo-bolsonaro.jpg?fit=780%2C405&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=13239"}],"version-history":[{"count":3,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13239\/revisions"}],"predecessor-version":[{"id":13256,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13239\/revisions\/13256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/13214"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=13239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=13239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=13239"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=13239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}