{"id":13085,"date":"2022-08-03T16:49:54","date_gmt":"2022-08-03T19:49:54","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=13085"},"modified":"2022-08-03T16:49:57","modified_gmt":"2022-08-03T19:49:57","slug":"bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/","title":{"rendered":"Bolsonaro se burla de la \u00abpol\u00edtica inclusiva\u00bb argentina: \u201cAhora hay desabastecimiente, pobreze y desemplee\u201d"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">El mandatario brasile\u00f1o, Jair Bolsonaro, lament\u00f3 la crisis econ\u00f3mica que atraviesa Argentina pero aprovech\u00f3 la oportunidad para atacar al ex presidente Lula, quien tambi\u00e9n ha defendido la implementaci\u00f3n oficial del lenguaje inclusivo.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El mandatario brasile\u00f1o public\u00f3 a trav\u00e9s de su cuenta en la red social de Twitter, una serie de mensajes en los que\u00a0<strong>lament\u00f3 el foco del gobierno en el \u201clenguaje neutral\u201d<\/strong>, como se le dice en Brasil, porque <strong>que este tipo de pr\u00e1cticas no ayudan a los argentinos en un tiempo de crisis<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">\u201c<strong>Lamento la oficializaci\u00f3n del uso del \u2018lenguaje inclusivo\u2019 en Argentina. \u00bfC\u00f3mo ayuda eso a su gente?\u201d<\/strong>, se pregunt\u00f3 Bolsonaro, y agreg\u00f3 con cierta iron\u00eda: \u201c<strong>Lo \u00fanico que cambi\u00f3 es que ahora hay desabastecimiente, pobreze y desemplee<\/strong>\u201c. Y complet\u00f3: \u201c<strong>Que Dios proteja a nuestros hermanos argentinos y los ayude a salir de esta dif\u00edcil situaci\u00f3n<\/strong>\u201c.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mandatario brasile\u00f1o, Jair Bolsonaro, lament\u00f3 la crisis econ\u00f3mica que atraviesa Argentina pero aprovech\u00f3 la oportunidad para atacar al ex presidente Lula, quien tambi\u00e9n ha defendido la implementaci\u00f3n oficial del lenguaje inclusivo. El mandatario brasile\u00f1o public\u00f3 a trav\u00e9s de su cuenta en la red social de Twitter, una serie de mensajes en los que\u00a0lament\u00f3 el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[173],"tags":[679,502,1036,1157],"ppma_author":[1051],"class_list":["post-13085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-argentina","tag-brasil","tag-destacada","tag-lenguaje-inclusivo"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolsonaro se burla de la &quot;pol\u00edtica inclusiva&quot; argentina: \u201cAhora hay desabastecimiente, pobreze y desemplee\u201d - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolsonaro se burla de la &quot;pol\u00edtica inclusiva&quot; argentina: \u201cAhora hay desabastecimiente, pobreze y desemplee\u201d - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El mandatario brasile\u00f1o, Jair Bolsonaro, lament\u00f3 la crisis econ\u00f3mica que atraviesa Argentina pero aprovech\u00f3 la oportunidad para atacar al ex presidente Lula, quien tambi\u00e9n ha defendido la implementaci\u00f3n oficial del lenguaje inclusivo. El mandatario brasile\u00f1o public\u00f3 a trav\u00e9s de su cuenta en la red social de Twitter, una serie de mensajes en los que\u00a0lament\u00f3 el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-03T19:49:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-03T19:49:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/jair-bolsonaro.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Bolsonaro se burla de la \u00abpol\u00edtica inclusiva\u00bb argentina: \u201cAhora hay desabastecimiente, pobreze y desemplee\u201d\",\"datePublished\":\"2022-08-03T19:49:54+00:00\",\"dateModified\":\"2022-08-03T19:49:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/\"},\"wordCount\":166,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/jair-bolsonaro.jpeg?fit=1200%2C675&ssl=1\",\"keywords\":[\"argentina\",\"brasil\",\"destacada\",\"lenguaje inclusivo\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/\",\"name\":\"Bolsonaro se burla de la \\\"pol\u00edtica inclusiva\\\" argentina: \u201cAhora hay desabastecimiente, pobreze y desemplee\u201d - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/jair-bolsonaro.jpeg?fit=1200%2C675&ssl=1\",\"datePublished\":\"2022-08-03T19:49:54+00:00\",\"dateModified\":\"2022-08-03T19:49:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/jair-bolsonaro.jpeg?fit=1200%2C675&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/jair-bolsonaro.jpeg?fit=1200%2C675&ssl=1\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/08\\\/03\\\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolsonaro se burla de la \u00abpol\u00edtica inclusiva\u00bb argentina: \u201cAhora hay desabastecimiente, pobreze y desemplee\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolsonaro se burla de la \"pol\u00edtica inclusiva\" argentina: \u201cAhora hay desabastecimiente, pobreze y desemplee\u201d - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/","og_locale":"es_ES","og_type":"article","og_title":"Bolsonaro se burla de la \"pol\u00edtica inclusiva\" argentina: \u201cAhora hay desabastecimiente, pobreze y desemplee\u201d - Informatepy","og_description":"El mandatario brasile\u00f1o, Jair Bolsonaro, lament\u00f3 la crisis econ\u00f3mica que atraviesa Argentina pero aprovech\u00f3 la oportunidad para atacar al ex presidente Lula, quien tambi\u00e9n ha defendido la implementaci\u00f3n oficial del lenguaje inclusivo. El mandatario brasile\u00f1o public\u00f3 a trav\u00e9s de su cuenta en la red social de Twitter, una serie de mensajes en los que\u00a0lament\u00f3 el [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-08-03T19:49:54+00:00","article_modified_time":"2022-08-03T19:49:57+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/jair-bolsonaro.jpeg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Bolsonaro se burla de la \u00abpol\u00edtica inclusiva\u00bb argentina: \u201cAhora hay desabastecimiente, pobreze y desemplee\u201d","datePublished":"2022-08-03T19:49:54+00:00","dateModified":"2022-08-03T19:49:57+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/"},"wordCount":166,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/jair-bolsonaro.jpeg?fit=1200%2C675&ssl=1","keywords":["argentina","brasil","destacada","lenguaje inclusivo"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/","url":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/","name":"Bolsonaro se burla de la \"pol\u00edtica inclusiva\" argentina: \u201cAhora hay desabastecimiente, pobreze y desemplee\u201d - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/jair-bolsonaro.jpeg?fit=1200%2C675&ssl=1","datePublished":"2022-08-03T19:49:54+00:00","dateModified":"2022-08-03T19:49:57+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/jair-bolsonaro.jpeg?fit=1200%2C675&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/jair-bolsonaro.jpeg?fit=1200%2C675&ssl=1","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/bolsonaro-se-burla-de-la-politica-inclusiva-argentina-ahora-hay-desabastecimiente-pobreze-y-desemplee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Bolsonaro se burla de la \u00abpol\u00edtica inclusiva\u00bb argentina: \u201cAhora hay desabastecimiente, pobreze y desemplee\u201d"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/jair-bolsonaro.jpeg?fit=1200%2C675&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":5669,"url":"https:\/\/informatepy.com\/2021\/2021\/07\/07\/bolsonaro-asumira-la-presidencia-del-mercosur-cuando-hay-riesgos-de-ruptura\/","url_meta":{"origin":13085,"position":0},"title":"Bolsonaro asumir\u00e1 la presidencia del Mercosur cuando hay riesgos de ruptura","date":"7 de julio de 2021","format":false,"excerpt":"Ma\u00f1ana, en un acto virtual encabezado por el presidente argentino,\u00a0Alberto Fern\u00e1ndez, su hom\u00f3logo brasile\u00f1o,\u00a0Jair Bolsonaro, asumir\u00e1 la presidencia pro t\u00e9mpore del\u00a0Mercosur. Al margen de las diferencias ideol\u00f3gicas entre los mandatarios de cada pa\u00eds, hay temas oponen a los socios del bloque regional a tal punto de muchos temen que, si\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/mercosur.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13630,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/27\/eduardo-bolsonaro-cruzo-a-santiago-cafiero-con-una-despiadada-burla\/","url_meta":{"origin":13085,"position":1},"title":"Eduardo Bolsonaro cruz\u00f3 a Santiago Cafiero con una despiadada burla","date":"27 de agosto de 2022","format":false,"excerpt":"El diputado brasile\u00f1o Eduardo Bolsonaro, hijo del presidente Jair Bolsonaro, se burl\u00f3 del canciller argentino, quien lo hab\u00eda llamado \"ignorante\".","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/eduardo-bolsonaro.jpg?fit=1200%2C592&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12139,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/14\/la-izquierda-en-argentina-se-opone-a-la-prohibicion-del-lenguaje-inclusivo\/","url_meta":{"origin":13085,"position":2},"title":"La izquierda en Argentina se opone a la prohibici\u00f3n del \u00ablenguaje inclusivo\u00bb","date":"14 de junio de 2022","format":false,"excerpt":"Las referentes del Frente de Izquierda (Argentina),\u00a0Celeste Fierro y Vanesa Gagliardi, presentaron un recurso de amparo contra la resoluci\u00f3n que\u00a0regula el uso de lenguaje inclusivo en las escuelas porte\u00f1as. Seg\u00fan las dirigentes, la decisi\u00f3n tomada por el Ministerio de Educaci\u00f3n de la Ciudad\u00a0\u201creduce la libertad de expresi\u00f3n y los derechos\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/frente-de-izquierda-lenguaje-inclusivo.webp?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12665,"url":"https:\/\/informatepy.com\/2021\/2022\/07\/14\/bolsonaro-arregla-con-rusia-para-comprar-petroleo-a-bajo-costo-y-bajar-los-precios-en-brasil\/","url_meta":{"origin":13085,"position":3},"title":"Bolsonaro arregla con Rusia para comprar petr\u00f3leo a bajo costo y bajar los precios en Brasil","date":"14 de julio de 2022","format":false,"excerpt":"El Gobierno brasile\u00f1o apunta a abaratar el precio de la energ\u00eda mediante un nuevo acuerdo con Rusia. Las medidas tendr\u00e1n un fuerte impacto sobre el 30% de la demanda brasile\u00f1a de gasoil que se abastece con importaciones. El presidente Jair Bolsonaro anunci\u00f3 un inminente acuerdo con la Rusia de Vladimir\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/bolsonaro-time-magazine.jpg?fit=1200%2C763&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7091,"url":"https:\/\/informatepy.com\/2021\/2021\/09\/13\/amo-al-presidente-de-brasil-trabaja-duro-declaro-trump\/","url_meta":{"origin":13085,"position":4},"title":"\u00abAmo al presidente de Brasil, trabaja duro\u00bb, declar\u00f3 Trump","date":"13 de septiembre de 2021","format":false,"excerpt":"El republicano estadounidense Donald Trump elogi\u00f3 al presidente brasile\u00f1o\u00a0Jair Bolsonaro\u00a0este domingo por la ma\u00f1ana (12). La declaraci\u00f3n se hizo durante el evento de boxeo 'Triller Fight Club Legends II' en Florida.\u00a0El expresidente actu\u00f3 como uno de los comentaristas de la festividad. Al mencionar a Jair Bolsonaro, Donald Trump se llen\u00f3\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/bolsonaro-y-trump.jpg?fit=1200%2C672&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9455,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/15\/contundente-bolsonaro-no-ira-a-la-asuncion-de-boric-en-chile\/","url_meta":{"origin":13085,"position":5},"title":"CONTUNDENTE: Bolsonaro no ir\u00e1 a la asunci\u00f3n de Boric en Chile","date":"15 de enero de 2022","format":false,"excerpt":"Jair Bolsonaro confirm\u00f3 durante una entrevista radial que no asistir\u00e1 a la posesi\u00f3n de cargo del izquierdista Gabriel Boric en Chile. Consultado sobre el tema, el mandatario brasile\u00f1o respondi\u00f3 que \u201cNo voy a entrar en detalles porque\u00a0no quiero crear problemas en las relaciones exteriores, pero \u00bfQui\u00e9n asistir\u00e1 a la toma\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/jair-bolsonaro.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=13085"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13085\/revisions"}],"predecessor-version":[{"id":13086,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13085\/revisions\/13086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/9456"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=13085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=13085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=13085"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=13085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}