{"id":1307,"date":"2019-07-01T20:19:00","date_gmt":"2019-07-01T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1307"},"modified":"2021-02-08T23:32:02","modified_gmt":"2021-02-08T23:32:02","slug":"autocritica-cero","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/","title":{"rendered":"Autocr\u00edtica cero"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Esta ma\u00f1ana, el Presidente de la Rep\u00fablica, Mario Abdo Ben\u00edtez cumpli\u00f3 con el deber que le manda la Constituci\u00f3n Nacional y brind\u00f3 su informe de gesti\u00f3n ante ala bicameral del Congreso Nacional. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese marco, el presidente se refiri\u00f3 a la crisis econ\u00f3mica que atraviesa nuestro pa\u00eds pero, en todo momento, se refiri\u00f3 a agentes externos a su gobierno como las causales de la misma, evitando en todo momento el reconocimiento de varios errores cometidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Habl\u00f3 de las inclemencias clim\u00e1ticas, que menguaron la producci\u00f3n agropecuaria<\/strong>. Manifest\u00f3 que tanto&nbsp;<strong>Brasil como Argentina no pasan por un buen momento econ\u00f3mico<\/strong>, lo que impacta de manera negativa con los vecinos. Cit\u00f3 el conflicto comercial en el que est\u00e1n enfrentados Estados Unidos y China y, en este sentido, afirm\u00f3 que la situaci\u00f3n influy\u00f3 en la reducci\u00f3n de los precios de soja y carne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3, tambi\u00e9n, que sumada a la menor producci\u00f3n los precios de los commodities se redujeron. \u201c<strong>Nos toc\u00f3 a todos los paraguayos<\/strong>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, siempre refiri\u00e9ndose a lo econ\u00f3mico, record\u00f3 que desde el ejecutivo nacional se impulsa la ley de \u201cmodernizaci\u00f3n\u201d impositiva que tiene como objetivo que los que \u201c<strong>ganan m\u00e1s, paguen m\u00e1s<\/strong>\u201d, algo que no surge del an\u00e1lisis del proyecto presentado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta ma\u00f1ana, el Presidente de la Rep\u00fablica, Mario Abdo Ben\u00edtez cumpli\u00f3 con el deber que le manda la Constituci\u00f3n Nacional y brind\u00f3 su informe de gesti\u00f3n ante ala bicameral del Congreso Nacional. En ese marco, el presidente se refiri\u00f3 a la crisis econ\u00f3mica que atraviesa nuestro pa\u00eds pero, en todo momento, se refiri\u00f3 a agentes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1308,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[642,332],"ppma_author":[1039],"class_list":["post-1307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-crisis-economica","tag-mario-abdo"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autocr\u00edtica cero - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autocr\u00edtica cero - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Esta ma\u00f1ana, el Presidente de la Rep\u00fablica, Mario Abdo Ben\u00edtez cumpli\u00f3 con el deber que le manda la Constituci\u00f3n Nacional y brind\u00f3 su informe de gesti\u00f3n ante ala bicameral del Congreso Nacional. En ese marco, el presidente se refiri\u00f3 a la crisis econ\u00f3mica que atraviesa nuestro pa\u00eds pero, en todo momento, se refiri\u00f3 a agentes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-01T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T23:32:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/mario-abdo-asamblea-legislativa.png?fit=853%2C505&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"853\" \/>\n\t<meta property=\"og:image:height\" content=\"505\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Autocr\u00edtica cero\",\"datePublished\":\"2019-07-01T20:19:00+00:00\",\"dateModified\":\"2021-02-08T23:32:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/\"},\"wordCount\":225,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/mario-abdo-asamblea-legislativa.png?fit=853%2C505&ssl=1\",\"keywords\":[\"crisis economica\",\"mario abdo\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/\",\"name\":\"Autocr\u00edtica cero - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/mario-abdo-asamblea-legislativa.png?fit=853%2C505&ssl=1\",\"datePublished\":\"2019-07-01T20:19:00+00:00\",\"dateModified\":\"2021-02-08T23:32:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/mario-abdo-asamblea-legislativa.png?fit=853%2C505&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/mario-abdo-asamblea-legislativa.png?fit=853%2C505&ssl=1\",\"width\":853,\"height\":505,\"caption\":\"Presidente Mario Abdo ante la Asamblea Legislativa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/07\\\/01\\\/autocritica-cero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autocr\u00edtica cero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autocr\u00edtica cero - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/","og_locale":"es_ES","og_type":"article","og_title":"Autocr\u00edtica cero - Informatepy","og_description":"Esta ma\u00f1ana, el Presidente de la Rep\u00fablica, Mario Abdo Ben\u00edtez cumpli\u00f3 con el deber que le manda la Constituci\u00f3n Nacional y brind\u00f3 su informe de gesti\u00f3n ante ala bicameral del Congreso Nacional. En ese marco, el presidente se refiri\u00f3 a la crisis econ\u00f3mica que atraviesa nuestro pa\u00eds pero, en todo momento, se refiri\u00f3 a agentes [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/","og_site_name":"Informatepy","article_published_time":"2019-07-01T20:19:00+00:00","article_modified_time":"2021-02-08T23:32:02+00:00","og_image":[{"width":853,"height":505,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/mario-abdo-asamblea-legislativa.png?fit=853%2C505&ssl=1","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Autocr\u00edtica cero","datePublished":"2019-07-01T20:19:00+00:00","dateModified":"2021-02-08T23:32:02+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/"},"wordCount":225,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/mario-abdo-asamblea-legislativa.png?fit=853%2C505&ssl=1","keywords":["crisis economica","mario abdo"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/","url":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/","name":"Autocr\u00edtica cero - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/mario-abdo-asamblea-legislativa.png?fit=853%2C505&ssl=1","datePublished":"2019-07-01T20:19:00+00:00","dateModified":"2021-02-08T23:32:02+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/mario-abdo-asamblea-legislativa.png?fit=853%2C505&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/mario-abdo-asamblea-legislativa.png?fit=853%2C505&ssl=1","width":853,"height":505,"caption":"Presidente Mario Abdo ante la Asamblea Legislativa"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/07\/01\/autocritica-cero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Autocr\u00edtica cero"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/mario-abdo-asamblea-legislativa.png?fit=853%2C505&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":7947,"url":"https:\/\/informatepy.com\/2021\/2021\/10\/25\/mario-abdo-propone-una-candidatura-testimonial-a-la-presidencia-de-la-anr\/","url_meta":{"origin":1307,"position":0},"title":"Mario Abdo propone una candidatura \u00abtestimonial\u00bb a la presidencia de la ANR","date":"25 de octubre de 2021","format":false,"excerpt":"Consciente del vac\u00edo de poder con el que se va a encontrar cuando deje el sill\u00f3n presidencial, el presidente Mario Abdo propuso esta ma\u00f1ana una candidatura testimonial a la presidencia de la Asociaci\u00f3n Nacional Republicana. En declaraciones a la 780 AM, Abdo afirm\u00f3 que, para no violar la Constituci\u00f3n Nacional,\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/mario-abdo-cansado.jpg?fit=1200%2C861&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9937,"url":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/carlos-rejala-sobre-abdo-es-el-presidente-de-la-republica-mas-corrupto-de-la-historia-de-nuestra-breve-democracia\/","url_meta":{"origin":1307,"position":1},"title":"Carlos Rejala sobre Abdo: \u00abEs el presidente de la Rep\u00fablica m\u00e1s corrupto de la historia de nuestra breve democracia\u201d","date":"4 de febrero de 2022","format":false,"excerpt":"El diputado del Partido Hagamos y aspirante a la Presidencia de la Rep\u00fablica, Carlos Rejala, tild\u00f3 al presidente de la Rep\u00fablica, Mario Abdo Ben\u00edtez, como el m\u00e1s corrupto de la \u00e9poca democr\u00e1tica. Dijo que es el principal culpable de la instalaci\u00f3n de un narcoestado en Paraguay. \u201cNo tenemos que mentirnos\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/carlos-rejala.jpg?fit=902%2C601&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3847,"url":"https:\/\/informatepy.com\/2021\/2021\/03\/06\/las-ambiciones-de-celeste-amarilla-haran-caer-el-posible-juicio-politico-a-mario-abdo\/","url_meta":{"origin":1307,"position":2},"title":"Las ambiciones de Celeste Amarilla har\u00e1n caer el posible juicio pol\u00edtico a Mario Abdo","date":"6 de marzo de 2021","format":false,"excerpt":"La diputada por el Partido Liberal Radical Aut\u00e9ntico (PLRA), Celeste Amarilla, en una entrevista con Radio 1000, confirm\u00f3 que los bloques del PLRA decidieron impulsar el juicio pol\u00edtico al presidente de la Rep\u00fablica, Mario Abdo Ben\u00edtez pero, al momento de desarrollar la idea, afirm\u00f3 que el juicio pol\u00edtico deber\u00eda ser\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/celeste-amarilla.jpg?fit=1020%2C625&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7952,"url":"https:\/\/informatepy.com\/2021\/2021\/10\/25\/cale-galaverna-firma-el-certificado-de-defuncion-de-anetete\/","url_meta":{"origin":1307,"position":3},"title":"Cal\u00e9 Galaverna firma el certificado de defunci\u00f3n de A\u00f1etet\u00e9","date":"25 de octubre de 2021","format":false,"excerpt":"'Cal\u00e9' Galaverna, sostuvo que el movimiento A\u00f1etete fue desintegrado y responsabiliz\u00f3 al presidente Mario Abdo Ben\u00edtez.","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3880,"url":"https:\/\/informatepy.com\/2021\/2021\/03\/08\/buzarquis-partidos-de-la-oposicion-ya-resolvieron-el-juicio-politico-para-el-presidente-y-el-vice\/","url_meta":{"origin":1307,"position":4},"title":"Buzarquis: \u00abPartidos de la oposici\u00f3n ya resolvieron el juicio pol\u00edtico para el presidente y el vice\u201d","date":"8 de marzo de 2021","format":false,"excerpt":"Existe una profunda crisis nacional, que algunos pretend\u00edan limitar a que iba a durar un d\u00eda o dos, seg\u00fan el senador liberal Salyn Buzarquis, quien dijo que la oposici\u00f3n decidi\u00f3 el juicio pol\u00edtico al presidente y al vicepresidente, aunque Hugo Vel\u00e1zquez no haya tenido protagonismo en nada de lo ocurrido,\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/salyn-buzarquis.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12768,"url":"https:\/\/informatepy.com\/2021\/2022\/07\/21\/mario-abdo-se-mostro-reacio-a-las-negociaciones-individuales-fuera-del-mercosur\/","url_meta":{"origin":1307,"position":5},"title":"Mario Abdo se mostr\u00f3 reacio a las negociaciones individuales fuera del Mercosur","date":"21 de julio de 2022","format":false,"excerpt":"El presidente Mario Abdo Ben\u00edtez particip\u00f3 de la Cumbre del Mercosur que se desarroll\u00f3 en nuestro pa\u00eds, en la ciudad de Luque y sostuvo, acertadamente, que para abrir el bloque al mundo las decisiones que se tomen deben ser consensuadas a trav\u00e9s de negociaciones comerciales. Destac\u00f3 entre los logros, el\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/abdo-mercosur.jpg?fit=592%2C324&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1307"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1307\/revisions"}],"predecessor-version":[{"id":2881,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1307\/revisions\/2881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1308"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1307"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}