{"id":12825,"date":"2022-07-24T14:37:16","date_gmt":"2022-07-24T17:37:16","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=12825"},"modified":"2022-07-24T14:37:19","modified_gmt":"2022-07-24T17:37:19","slug":"intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/","title":{"rendered":"Intentaron acuchillar al candidato trumpista a gobernador de Nueva York"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">El candidato republicano (trumpista) a gobernador de Nueva York,\u00a0<strong>Lee Zeldin<\/strong>, fue atacado por un hombre en un evento de campa\u00f1a.\u00a0<strong>El terrorista subi\u00f3 al escenario con un elemento punzante en mano y le dijo <em>\u201cTerminaste, est\u00e1s acabado\u201d<\/em>, antes de intentar apu\u00f1alarlo<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Zeldin, quien fren\u00f3 el discurso para escuchar lo que el hombre ten\u00eda para decir,&nbsp;<strong>le fren\u00f3 la mano al atacante con el pu\u00f1al y logr\u00f3 tirarlo al piso<\/strong>. Momento en el que los agentes de seguridad se tiraron encima de la persona y le quitaron el arma blanca de la mano.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El hombre fue arrestado, y pas\u00f3 la noche en un calabozo. Sin embargo, seg\u00fan la polic\u00eda de Nueva York, como Zeldin est\u00e1 ileso y su personal de campa\u00f1a no sufri\u00f3 heridas,\u00a0<strong>el terrorista ya est\u00e1 libre<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Here is video of the attack involving Rep. Zeldin from witness Cody Crippen <a href=\"https:\/\/t.co\/Ur1CfpkdsS\">pic.twitter.com\/Ur1CfpkdsS<\/a><\/p>&mdash; Nick Reisman (@NickReisman) <a href=\"https:\/\/twitter.com\/NickReisman\/status\/1550292941461151746?ref_src=twsrc%5Etfw\">July 22, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El candidato republicano (trumpista) a gobernador de Nueva York,\u00a0Lee Zeldin, fue atacado por un hombre en un evento de campa\u00f1a.\u00a0El terrorista subi\u00f3 al escenario con un elemento punzante en mano y le dijo \u201cTerminaste, est\u00e1s acabado\u201d, antes de intentar apu\u00f1alarlo. Zeldin, quien fren\u00f3 el discurso para escuchar lo que el hombre ten\u00eda para decir,&nbsp;le fren\u00f3 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[173],"tags":[1036,464,832,1452,742,224],"ppma_author":[1051],"class_list":["post-12825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-destacada","tag-donald-trump","tag-estados-unidos","tag-nueva-york","tag-terrorismo","tag-trump"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intentaron acuchillar al candidato trumpista a gobernador de Nueva York - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intentaron acuchillar al candidato trumpista a gobernador de Nueva York - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El candidato republicano (trumpista) a gobernador de Nueva York,\u00a0Lee Zeldin, fue atacado por un hombre en un evento de campa\u00f1a.\u00a0El terrorista subi\u00f3 al escenario con un elemento punzante en mano y le dijo \u201cTerminaste, est\u00e1s acabado\u201d, antes de intentar apu\u00f1alarlo. Zeldin, quien fren\u00f3 el discurso para escuchar lo que el hombre ten\u00eda para decir,&nbsp;le fren\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-24T17:37:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-24T17:37:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/Lee-Zeldin.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Intentaron acuchillar al candidato trumpista a gobernador de Nueva York\",\"datePublished\":\"2022-07-24T17:37:16+00:00\",\"dateModified\":\"2022-07-24T17:37:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/\"},\"wordCount\":153,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Lee-Zeldin.png?fit=800%2C450&ssl=1\",\"keywords\":[\"destacada\",\"donald trump\",\"estados unidos\",\"nueva york\",\"terrorismo\",\"trump\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/\",\"name\":\"Intentaron acuchillar al candidato trumpista a gobernador de Nueva York - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Lee-Zeldin.png?fit=800%2C450&ssl=1\",\"datePublished\":\"2022-07-24T17:37:16+00:00\",\"dateModified\":\"2022-07-24T17:37:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Lee-Zeldin.png?fit=800%2C450&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Lee-Zeldin.png?fit=800%2C450&ssl=1\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/24\\\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intentaron acuchillar al candidato trumpista a gobernador de Nueva York\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intentaron acuchillar al candidato trumpista a gobernador de Nueva York - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/","og_locale":"es_ES","og_type":"article","og_title":"Intentaron acuchillar al candidato trumpista a gobernador de Nueva York - Informatepy","og_description":"El candidato republicano (trumpista) a gobernador de Nueva York,\u00a0Lee Zeldin, fue atacado por un hombre en un evento de campa\u00f1a.\u00a0El terrorista subi\u00f3 al escenario con un elemento punzante en mano y le dijo \u201cTerminaste, est\u00e1s acabado\u201d, antes de intentar apu\u00f1alarlo. Zeldin, quien fren\u00f3 el discurso para escuchar lo que el hombre ten\u00eda para decir,&nbsp;le fren\u00f3 [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-07-24T17:37:16+00:00","article_modified_time":"2022-07-24T17:37:19+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/Lee-Zeldin.png","type":"image\/png"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Intentaron acuchillar al candidato trumpista a gobernador de Nueva York","datePublished":"2022-07-24T17:37:16+00:00","dateModified":"2022-07-24T17:37:19+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/"},"wordCount":153,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/Lee-Zeldin.png?fit=800%2C450&ssl=1","keywords":["destacada","donald trump","estados unidos","nueva york","terrorismo","trump"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/","url":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/","name":"Intentaron acuchillar al candidato trumpista a gobernador de Nueva York - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/Lee-Zeldin.png?fit=800%2C450&ssl=1","datePublished":"2022-07-24T17:37:16+00:00","dateModified":"2022-07-24T17:37:19+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/Lee-Zeldin.png?fit=800%2C450&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/Lee-Zeldin.png?fit=800%2C450&ssl=1","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Intentaron acuchillar al candidato trumpista a gobernador de Nueva York"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/Lee-Zeldin.png?fit=800%2C450&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":6544,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/18\/donald-ha-vuelto-como-donhammed-trumpistan\/","url_meta":{"origin":12825,"position":0},"title":"Donald ha vuelto a Twitter&#8230; como Donhammed Trumpistan","date":"18 de agosto de 2021","format":false,"excerpt":"Donald Trump -bloqueado de Twitter- vuelve a meterse en la red social disfrazado de Talib\u00e1n (permitidos en Twitter): Donhammed Trumpistan.","rel":"","context":"En \u00abCiencia y Tecnolog\u00eda\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/donhammed-trumpistan.jpg?fit=1200%2C679&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13281,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/12\/cumplieron-la-fatua-salman-rushdie-fue-apunalado-en-un-evento-en-nueva-york\/","url_meta":{"origin":12825,"position":1},"title":"Cumplieron la fatua: Salman Rushdie fue apu\u00f1alado en un evento en Nueva York","date":"12 de agosto de 2022","format":false,"excerpt":"El autor Salman Rushdie, cuyo trabajo (Los versos Sat\u00e1nicos) le ha valido amenazas de muerte y una fatua isl\u00e1mica, fue\u00a0\u00a0apu\u00f1alado en el cuello\u00a0\u00a0en un evento literario en el norte del estado de Nueva York el viernes, cuando un agresor irrumpi\u00f3 en el escenario poco despu\u00e9s de su presentaci\u00f3n. Seg\u00fan la\u2026","rel":"","context":"En \u00abCultura\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/salman-rushdie.webp?fit=1200%2C676&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5165,"url":"https:\/\/informatepy.com\/2021\/2021\/06\/02\/trump-espera-ser-reinstalado-como-presidente-en-agosto-afirma-maggie-haberman-del-new-york-times\/","url_meta":{"origin":12825,"position":2},"title":"Trump espera ser reinstalado como presidente en agosto, afirma Maggie Haberman del New York Times","date":"2 de junio de 2021","format":false,"excerpt":"Maggie Haberman, analista de CNN y corresponsal en Washington del New York Times, gener\u00f3 controversia en las redes sociales despu\u00e9s de que afirm\u00f3 que el ex presidente Donald Trump le ha dicho a la gente que pronto regresar\u00e1 a la presidencia. \"Trump le ha dicho a varias personas con las\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/trump.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7284,"url":"https:\/\/informatepy.com\/2021\/2021\/09\/22\/donald-trump-presenta-una-demanda-de-100-millones-contra-el-new-york-times\/","url_meta":{"origin":12825,"position":3},"title":"Donald Trump presenta una demanda de $ 100 millones de d\u00f3lares contra el New York Times","date":"22 de septiembre de 2021","format":false,"excerpt":"Donald Trump es conocido como un estratega y aparentemente ha estado esperando el momento oportuno mientras recibe muchas flechas de detractores y enemigos pol\u00edticos desde que dej\u00f3 el cargo. El mi\u00e9rcoles, los informes se\u00f1alaron que Trump present\u00f3 una demanda de $ 100 millones contra The New York Times y su\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/trump-bailando.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9718,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/25\/un-juez-de-nueva-york-dicta-que-la-obligatoriedad-de-usar-mascarilla-en-interiores-es-inconstitucional\/","url_meta":{"origin":12825,"position":4},"title":"Un juez de Nueva York dicta que la obligatoriedad de usar mascarilla en interiores es inconstitucional","date":"25 de enero de 2022","format":false,"excerpt":"Thomas Rademacher, magistrado del condado de Nassau, tumb\u00f3 as\u00ed la orden impuesta por la gobernadora del estado Nueva York, Kathy Hochul, por la que la\u00a0mascarilla era obligatoria\u00a0en espacios interiores p\u00fablicos -como colegios, residencias o transporte p\u00fablico- y que obligaba a las empresas tambi\u00e9n a exigir la protecci\u00f3n u obligaci\u00f3n de\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/tapabocas.jpg?fit=864%2C486&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12800,"url":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/un-informe-del-mossad-desliga-a-iran-de-los-atentados-a-la-amia-y-la-embajada-de-israel-en-argentina\/","url_meta":{"origin":12825,"position":5},"title":"Un informe del Mossad desliga a Ir\u00e1n de los atentados a la AMIA y la Embajada de Israel\u00a0en Argentina","date":"24 de julio de 2022","format":false,"excerpt":"La investigaci\u00f3n fue publicada en The New York Times y va en contra de la postura hist\u00f3rica de Israel.","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/atentado-amia.jpg?fit=1004%2C565&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=12825"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12825\/revisions"}],"predecessor-version":[{"id":12827,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12825\/revisions\/12827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/12826"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=12825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=12825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=12825"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=12825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}