{"id":12778,"date":"2022-07-22T08:07:57","date_gmt":"2022-07-22T11:07:57","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=12778"},"modified":"2022-07-22T08:08:00","modified_gmt":"2022-07-22T11:08:00","slug":"diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/","title":{"rendered":"Diputado abdista aparece vinculado en una investigaci\u00f3n sobre tr\u00e1fico de drogas"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\"><em>En el marco de la investigaci\u00f3n denominada Belia sobre tr\u00e1fico internacional de drogas peligrosas, la Secretar\u00eda Nacional Antidrogas (SENAD), intercept\u00f3 llamadas telef\u00f3nicas entre el diputado abdista Ever Aparicio Noguera y Hugo Antonio Meza Huespe, alias HM, miembro de la banda liderada por el jefe narco Miguel \u00c1ngel Serv\u00edn Palacios. Este grupo criminal estuvo involucrado en el tr\u00e1fico de sustancias il\u00edcitas al continente europeo en bolsas de carb\u00f3n vegetal embarcadas en contenedores y llevadas a los principales puertos fluviales para su ingreso al mercado europeo. Se trata del caso en el que tambi\u00e9n fue procesado Cristian Turrini quien manten\u00eda v\u00ednculos con Serv\u00edn Palacios. La Senad se\u00f1ala que Noguera tambi\u00e9n oper\u00f3 para la designaci\u00f3n de una jueza quien ayud\u00f3 a la organizaci\u00f3n criminal y tambi\u00e9n obtuvo en forma ilegal vacunas contra el covid-19 para \u00e9l y su familia.&nbsp; Los informes de inteligencia de la Senad fueron remitidos a fiscal\u00eda y al poder judicial el pasado 4 de julio de este a\u00f1o.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por Jorge Torres Romero<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Seg\u00fan se desprende de las investigaciones realizadas por la SENAD, el integrante de la banda criminal Hugo Meza -quien actualmente se encuentra pr\u00f3fugo- participaba de manera activa, constante y continua como administrador del esquema de lavado de activos y fue el encargado de proveer todo el soporte necesario para el ocultamiento del origen il\u00edcito de los fondos manejados por la estructura.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Lo llamativo es que, en varias intercepciones telef\u00f3nicas, aparecen registradas conversaciones con el diputado abdista Ever Noguera, quien al parecer tambi\u00e9n le brindaba protecci\u00f3n pol\u00edtica y en ocasiones participaba del esquema de lavado con su empresa Itapoty SA. Asimismo, le pidi\u00f3 su ayuda pol\u00edtica para interceder en la designaci\u00f3n de una magistrada que formaba parte de una terna en el Poder Judicial, con lo que adem\u00e1s se configura el tr\u00e1fico de influencias.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Seg\u00fan la SENAD, Meza utilizaba las empresas Mecha Import SA, Trig\u00f3n SA, Al Frente Import Export SA y la playa de veh\u00edculos HM Automotores para la obtenci\u00f3n de bienes, muebles e inmuebles, producto de las actividades il\u00edcitas del l\u00edder del grupo.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.adndigital.com.py\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/noguera3\/\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/adnpy.nyc3.digitaloceanspaces.com\/wp-content\/uploads\/2022\/07\/noguera3.jpg?w=740&#038;ssl=1\" alt=\"\" data-recalc-dims=\"1\"\/><\/a><figcaption>Estas son las personas identificadas en la investigaci\u00f3n de la operaci\u00f3n Belia de la Senad y la Fiscal\u00eda. Hugo Meza Huespe es uno de los integrantes de la banda criminal cuyo tel\u00e9fono fue interceptado y en donde aparecen las conversaciones con el diputado abdista Ever Noguera.<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En una conversaci\u00f3n de fecha 30-08-2021, siendo las 15:25, Hugo Meza convers\u00f3 con el diputado Noguera y le dijo: \u201cDipu, ahora agarr\u00e9, en el sobre hay una parte donde dice Noguera, cuando yo romp\u00ed, figura 3 y parece un 7, 3.700 pero 3.600 nom\u00e1s hay. &nbsp;S\u00e9 que 3.800 y cerrado vino sobre, pero 3.600 hay\u201d.&nbsp; Ever le contest\u00f3: \u201cPerfecto. Si, est\u00e1 bien, se ten\u00eda que colaborar un 100 estoy seguro y si dice 700 all\u00ed est\u00e1 bien\u201d. Hugo le respondi\u00f3: \u201c6, pero parec\u00eda 7\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Ever le contest\u00f3: \u201cVar\u00eda, depende del cambio ellos var\u00edan\u201d. Hugo le respondi\u00f3: \u201cpesado son, la pr\u00f3xima vez decile que te den azul (serie nueva de los d\u00f3lares). Ever le contest\u00f3: \u201cjajaja, ese es de Sao Paulo (los d\u00f3lares provienen del exterior), decime, no me retes, eso no quiero, no hay para hacer milagro, dinero r\u00e1pido, no, no, estoy buscando, a mi me falta, estoy buscando, esper\u00e1, es m\u00e1s, mir\u00e1 tu WhatsApp. Hola si quer\u00e9s vas a darle el que vos ten\u00edas\u201d.&nbsp; Hugo le respondi\u00f3: \u201cnecesito cerrar para que no baje mi calificaci\u00f3n y me falta eso nom\u00e1s, a todo el mundo le ped\u00ed, amigos, enemigos\u201d. Ever le contest\u00f3: \u201cun cheque, yo pens\u00e9 un cheque del Dipu\u201d. Hugo le respondi\u00f3: \u201cno, no, un cheque al d\u00eda, voy a completar con ese, est\u00e1n viendo si va a servir eso y hay me dijo para la diferencia porque no consegu\u00ed m\u00e1s. Ever le contest\u00f3: \u201cEse podemos tirar en ITAPOTY (empresa SA). Hugo le respondi\u00f3: \u201cclaro que s\u00ed, ya te estoy viendo ese. Ever le contest\u00f3: \u201cdale por favor\u201d. Hugo le respondi\u00f3: \u201cdale papito, no te vayas a preocupar\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Para los investigadores de la SENAD, a trav\u00e9s de esa llamada se infiere que Hugo Meza recibi\u00f3 3.600 d\u00f3lares con series anteriores a los d\u00f3lares azules (series nuevas) en un sobre proveniente de Ever Noguera que afirma que vinieron de Sao Paulo. Ever Noguera le solicita a Hugo Meza que deposite el dinero o un cheque a la cuenta de la empresa Itapoty, vinculada a Noguera quien demuestra el control sobre la empresa.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En otra comunicaci\u00f3n telef\u00f3nica de fecha 30-09-2021 a las 15:55 Ever Noguera le expresa su preocupaci\u00f3n a Hugo Meza por una operaci\u00f3n realizada con su empresa Itapoty y le dice: \u201cEse de Itapoty me quebranta, c\u00f3mo podemos hacer para borrar el sello, los dos sellos que tiene est\u00e1 regularizado al d\u00eda siguiente porque en las dos ocasiones la transferencia lleg\u00f3 tarde, pero lleg\u00f3 en el mismo d\u00eda\u201d. Hugo le respondi\u00f3: \u201cAhora mismo le voy a llamar\u201d. Ever le contest\u00f3: \u201cLlamale y vamos a hacer desaparecer del sistema ese\u201d. Hugo le respondi\u00f3: \u201cTengo mi primo que es asesor jur\u00eddico del BCP\u201d. Ever le contest\u00f3: \u201cPuede fijarse el n\u00famero del cheque, al d\u00eda siguiente fue regularizado, si o s\u00ed\u201d. Hugo le respondi\u00f3: \u201cahora le llamo\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Para la SENAD, Meza cuenta con varios contactos en instituciones financieras p\u00fablicas y privadas a quienes recurre como intermediador ante irregularidades administrativas con la finalidad de favorecer al diputado Ever Noguera.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.adndigital.com.py\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/noguera4\/\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/adnpy.nyc3.digitaloceanspaces.com\/wp-content\/uploads\/2022\/07\/noguera4.jpg?w=740&#038;ssl=1\" alt=\"\" data-recalc-dims=\"1\"\/><\/a><figcaption>En la pag. 48 del informe de la Senad remitido a fiscal\u00eda y al juez de la causa por tr\u00e1fico de droga, se menciona detalles de la conversaci\u00f3n entre Hugo Meza y el diputado abdista Ever Noguera. Hablan de la necesidad de borrar un sello de unos cheques. Meza le dice que tiene un primo en el BCP que puede ayudar. Senad dice que Meza intercede para favorecer al diputado Noguera.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Narco le pide \u201cun favorazo\u201d<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Seg\u00fan los investigadores de la SENAD, por medio de las vinculaciones pol\u00edticas del diputado Noguera, el narco Hugo Meza tambi\u00e9n busc\u00f3 favorecer en una terna del Poder Judicial a una magistrada a cambio de la liberaci\u00f3n de una documentaci\u00f3n. En la llamada interceptada de fecha 6 de setiembre de 2021, siendo las 18:47, Hugo Meza le dice a Noguera: \u201c\u00bfvos no est\u00e1s ocupado? \u00bfno te puedo pedir un favorazo? \u00daltimo favor, rotura de bolas\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ever le respondi\u00f3: \u201cS\u00ed, qu\u00e9 pas\u00f3\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Hugo le contest\u00f3: \u201cma\u00f1ana se trata la Terna de la Jueza tembo rova de la se\u00f1ora de Molinas y no le di ni un poquitito de bola, pero yo, te cont\u00e9 que estoy haciendo algo con ella y necesito de \u00e9l ahora, me tiene que liberar algo, unos documentos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ever le respondi\u00f3: \u201cYo habl\u00e9 con \u00e9l, estoy en comunicaci\u00f3n con \u00e9l\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hugo le contest\u00f3: \u201cllamale na ahora, no s\u00e9, pod\u00e9s mentir, ay\u00fadame con eso\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ever le respondi\u00f3: \u201cahorait\u00e9 le llamo\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Hugo le contest\u00f3: \u201cHugo no me deja en paz, porque ma\u00f1ana ya se trata la terna y yo habl\u00e9 con Hugo y ten\u00e9s la bendici\u00f3n de \u00e9l, llamale na ahora y av\u00edsame qu\u00e9 te dice\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ever le respondi\u00f3: \u201cdale, ahora le llamo\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.adndigital.com.py\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/noguera5\/\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/adnpy.nyc3.digitaloceanspaces.com\/wp-content\/uploads\/2022\/07\/noguera5.jpg?w=740&#038;ssl=1\" alt=\"\" data-recalc-dims=\"1\"\/><\/a><figcaption>En la p\u00e1gina 39 del informe de Senad se vuelve a mencionar al diputado Abdista, Ever Noguera. Hugo Meza le pide un favor al diputado Noguera sobre la terna de una jueza esposa de un tal Molinas. El diputado se compromete en ayudar.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Caso Vacunas VIP<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En fecha 23 de agosto de 2021, el diputado oficialista Ever Noguera vuelve a conversar con Hugo Meza, esta vez salta el caso de las vacunas VIP contra el Covid donde personas que no se encontraban en la franja etaria correspondiente para la aplicaci\u00f3n de las dosis seg\u00fan disponibilidad del Ministerio de Salud. Fue en medio de la crisis que se hab\u00eda desatado por la falta de vacunas. Hugo Meza le dice a Noguera: \u201cJusto te iba a llamar hoy, tenemos que ponernos la segunda dosis. Voy a organizar todo eso esta semana con tu hijo\u201d. Ever le contesta: \u201cYo estoy ac\u00e1 ahora\u201d. Hugo le respondi\u00f3: \u201cAhora voy a ver si se puede estirar el l\u00edquido vital y te aviso \u00bfy tu hijo?\u201d. Ever le contest\u00f3: \u201cest\u00e1 ac\u00e1 en San Lorenzo\u201d. Hugo le responde: \u201cDe lujo, ahora organizo\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Para los analistas de la SENAD, se infiere en esta conversaci\u00f3n que el diputado Noguera recibi\u00f3 la vacuna contra el Covid por medio de Hugo Meza y deb\u00eda aplicarse la segunda dosis al igual que su hijo. Los hechos que se describen en la llamada demuestran las reiteradas tipolog\u00edas delictivas de Hugo Meza en este caso para continuar con la protecci\u00f3n judicial y pol\u00edtica del diputado Noguera. La provisi\u00f3n de vacunas era administrada con ayuda de un funcionario del Instituto de Previsi\u00f3n Social (IPS) de nombre Marco Arturo Borne Torres, quien coordinaba con Meza la lista de los que iban a acceder irregularmente a las dosis.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.adndigital.com.py\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/noguera6\/\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/adnpy.nyc3.digitaloceanspaces.com\/wp-content\/uploads\/2022\/07\/noguera6.jpg?w=740&#038;ssl=1\" alt=\"\" data-recalc-dims=\"1\"\/><\/a><figcaption>El pasado 4 de julio de este a\u00f1o, desde la Senad remiten al juez penal de Garant\u00edas, Gustavo Amarilla, parte del informe de inteligencia en el marco de la causa \u201cTr\u00e1fico Internacional de Drogas Peligrosas\u201d, donde aparece el nombre del diputado abdista Ever Noguera.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.adndigital.com.py\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/noguera7\/\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/adnpy.nyc3.digitaloceanspaces.com\/wp-content\/uploads\/2022\/07\/noguera7.jpg?w=740&#038;ssl=1\" alt=\"\" data-recalc-dims=\"1\"\/><\/a><figcaption>El 1 de julio de este a\u00f1o, inteligencia de la Senad remite los detalles de las intercepciones telef\u00f3nicas en soporte magn\u00e9ticos a sus superiores para luego remitirse a la fiscal\u00eda y al juez de la causa \u201cTr\u00e1fico Internacional de Drogas Peligrosas\u201d y \u201cMiguel Angel Serv\u00edn Palacios y otros sobre Tr\u00e1fico de Drogas\u201d.<\/figcaption><\/figure>\n\n\n\n<h6 class=\"wp-block-heading\" style=\"font-style:normal;font-weight:300\">ADN Digital<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la investigaci\u00f3n denominada Belia sobre tr\u00e1fico internacional de drogas peligrosas, la Secretar\u00eda Nacional Antidrogas (SENAD), intercept\u00f3 llamadas telef\u00f3nicas entre el diputado abdista Ever Aparicio Noguera y Hugo Antonio Meza Huespe, alias HM, miembro de la banda liderada por el jefe narco Miguel \u00c1ngel Serv\u00edn Palacios. Este grupo criminal estuvo involucrado en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[1036,1285,665,332,180],"ppma_author":[1051],"class_list":["post-12778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-destacada","tag-ever-noguera","tag-hugo-velazquez","tag-mario-abdo","tag-narcotrafico"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diputado abdista aparece vinculado en una investigaci\u00f3n sobre tr\u00e1fico de drogas - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diputado abdista aparece vinculado en una investigaci\u00f3n sobre tr\u00e1fico de drogas - Informatepy\" \/>\n<meta property=\"og:description\" content=\"En el marco de la investigaci\u00f3n denominada Belia sobre tr\u00e1fico internacional de drogas peligrosas, la Secretar\u00eda Nacional Antidrogas (SENAD), intercept\u00f3 llamadas telef\u00f3nicas entre el diputado abdista Ever Aparicio Noguera y Hugo Antonio Meza Huespe, alias HM, miembro de la banda liderada por el jefe narco Miguel \u00c1ngel Serv\u00edn Palacios. Este grupo criminal estuvo involucrado en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-22T11:07:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-22T11:08:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/ever-noguera2-hugo-velazquez.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Diputado abdista aparece vinculado en una investigaci\u00f3n sobre tr\u00e1fico de drogas\",\"datePublished\":\"2022-07-22T11:07:57+00:00\",\"dateModified\":\"2022-07-22T11:08:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/\"},\"wordCount\":1653,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ever-noguera2-hugo-velazquez.jpg?fit=660%2C330&ssl=1\",\"keywords\":[\"destacada\",\"ever noguera\",\"hugo velazquez\",\"mario abdo\",\"narcotrafico\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/\",\"name\":\"Diputado abdista aparece vinculado en una investigaci\u00f3n sobre tr\u00e1fico de drogas - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ever-noguera2-hugo-velazquez.jpg?fit=660%2C330&ssl=1\",\"datePublished\":\"2022-07-22T11:07:57+00:00\",\"dateModified\":\"2022-07-22T11:08:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ever-noguera2-hugo-velazquez.jpg?fit=660%2C330&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ever-noguera2-hugo-velazquez.jpg?fit=660%2C330&ssl=1\",\"width\":660,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/22\\\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diputado abdista aparece vinculado en una investigaci\u00f3n sobre tr\u00e1fico de drogas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diputado abdista aparece vinculado en una investigaci\u00f3n sobre tr\u00e1fico de drogas - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/","og_locale":"es_ES","og_type":"article","og_title":"Diputado abdista aparece vinculado en una investigaci\u00f3n sobre tr\u00e1fico de drogas - Informatepy","og_description":"En el marco de la investigaci\u00f3n denominada Belia sobre tr\u00e1fico internacional de drogas peligrosas, la Secretar\u00eda Nacional Antidrogas (SENAD), intercept\u00f3 llamadas telef\u00f3nicas entre el diputado abdista Ever Aparicio Noguera y Hugo Antonio Meza Huespe, alias HM, miembro de la banda liderada por el jefe narco Miguel \u00c1ngel Serv\u00edn Palacios. Este grupo criminal estuvo involucrado en [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-07-22T11:07:57+00:00","article_modified_time":"2022-07-22T11:08:00+00:00","og_image":[{"width":660,"height":330,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/ever-noguera2-hugo-velazquez.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Diputado abdista aparece vinculado en una investigaci\u00f3n sobre tr\u00e1fico de drogas","datePublished":"2022-07-22T11:07:57+00:00","dateModified":"2022-07-22T11:08:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/"},"wordCount":1653,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/ever-noguera2-hugo-velazquez.jpg?fit=660%2C330&ssl=1","keywords":["destacada","ever noguera","hugo velazquez","mario abdo","narcotrafico"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/","url":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/","name":"Diputado abdista aparece vinculado en una investigaci\u00f3n sobre tr\u00e1fico de drogas - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/ever-noguera2-hugo-velazquez.jpg?fit=660%2C330&ssl=1","datePublished":"2022-07-22T11:07:57+00:00","dateModified":"2022-07-22T11:08:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/ever-noguera2-hugo-velazquez.jpg?fit=660%2C330&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/ever-noguera2-hugo-velazquez.jpg?fit=660%2C330&ssl=1","width":660,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/07\/22\/diputado-abdista-aparece-vinculado-en-una-investigacion-sobre-trafico-de-drogas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Diputado abdista aparece vinculado en una investigaci\u00f3n sobre tr\u00e1fico de drogas"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/ever-noguera2-hugo-velazquez.jpg?fit=660%2C330&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":5822,"url":"https:\/\/informatepy.com\/2021\/2021\/07\/16\/caso-merienda-escolar-sin-desafuero-de-diputado-no-puede-avanzar-proceso-de-investigacion\/","url_meta":{"origin":12778,"position":0},"title":"Caso merienda escolar: sin desafuero de diputado no puede avanzar proceso de investigaci\u00f3n","date":"16 de julio de 2021","format":false,"excerpt":"Sobre la acusaci\u00f3n al senador Rodolfo Friedmann y su esposa Marly Figueredo, por lavado de dinero, administraci\u00f3n en provecho propio, cohecho pasivo agravado y asociaci\u00f3n criminal, el fiscal Osmar Legal, cont\u00f3 que el obst\u00e1culo sigue siendo con relaci\u00f3n al diputado Ever Noguera, quien no fue desaforado en la causa y\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/FRIEDMANN-NOGUERA-1.jpg?fit=800%2C500&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2097,"url":"https:\/\/informatepy.com\/2021\/2020\/08\/01\/le-diste-a-navarro-su-parte-friedmann-gerenciaba-hasta-el-pago-de-las-coimas\/","url_meta":{"origin":12778,"position":1},"title":"\u00bfLe diste a Navarro su parte? Friedmann gerenciaba hasta el pago de las coimas","date":"1 de agosto de 2020","format":false,"excerpt":"El intendente de la Municipalidad de Villarrica, Gustavo Navarro, quien forma parte del equipo pol\u00edtico del exgobernador guaire\u00f1o y actual ministro de Agricultura y Ganader\u00eda, Rodolfo Max Friedmann, fue uno de los que favoreci\u00f3 a la empresa Essa con un contrato de 455 millones de guaran\u00edes para la provisi\u00f3n de\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/friedmann-coimas.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2136,"url":"https:\/\/informatepy.com\/2021\/2020\/08\/31\/rolfi-y-marly-expuestos-a-una-condena-de-10-anos\/","url_meta":{"origin":12778,"position":2},"title":"Rolfi y Marly expuestos a una condena de 10 a\u00f1os","date":"31 de agosto de 2020","format":false,"excerpt":"La Fiscal\u00eda confirm\u00f3 que Rodolfo Friedmann y Marly Figueredo se exponen a unos 10 a\u00f1os de c\u00e1rcel por la estructura organizada para lavar dinero mediante la empresa Eventos y Servicios S.A. (ESSA). Entre las evidencias existen cheques emitidos por esa firma para el pago de cuotas de veh\u00edculos 0 km\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/rodolfo-y-marly.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2498,"url":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/salvado\/","url_meta":{"origin":12778,"position":3},"title":"Salvado","date":"3 de febrero de 2021","format":false,"excerpt":"Los diputados trataron este mi\u00e9rcoles en sesi\u00f3n extraordinaria el pedido de censura para el jefe de Gabinete Civil de la Presidencia, Juan Ernesto Villamayor. Tras un largo debate, 52 legisladores votaron a favor del voto de censura y 19 votaron en contra. En tanto que hubo 9 ausentes en ese\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/villamayor-salvado-scaled-1.jpg?fit=1200%2C663&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8986,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/23\/mario-ferreiro-a-juicio-oral\/","url_meta":{"origin":12778,"position":4},"title":"Mario Ferreiro a Juicio Oral","date":"23 de diciembre de 2021","format":false,"excerpt":"El exintendente de Asunci\u00f3n, Mario Ferreiro, y otras seis personas, afrontar\u00e1n juicio oral y p\u00fablico por la presunta recaudaci\u00f3n paralela en la Municipalidad de Asunci\u00f3n, a trav\u00e9s del grupo de Telegram \u201cAsado de fin de semana\u201d. La acusaci\u00f3n es por coacci\u00f3n y coacci\u00f3n grave, lesi\u00f3n de confianza y tr\u00e1fico de\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/mario-ferreiro-meme.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11657,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/16\/insisten-con-la-imputacion-y-desafuero-de-kattya-gonzalez-por-trafico-de-influencias\/","url_meta":{"origin":12778,"position":5},"title":"Insisten con la imputaci\u00f3n y desafuero de Kattya Gonz\u00e1lez por tr\u00e1fico de influencias","date":"16 de mayo de 2022","format":false,"excerpt":"El empresario alem\u00e1n, Rauand Rauf Latif, insisti\u00f3 ante a fiscal\u00eda para que la diputada Kattya Gonz\u00e1lez sea imputada por el\u00a0presunto delito de uso indebido de influencias y\/o tr\u00e1fico de influencias. En el escrito presentado esta ma\u00f1ana, el empresario argumenta que \"dentro del marco de la investigaci\u00f3n fiscal, se cuenta con\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/rauand-rauf-kattya-gonzalez.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=12778"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12778\/revisions"}],"predecessor-version":[{"id":12780,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12778\/revisions\/12780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/12779"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=12778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=12778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=12778"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=12778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}