{"id":1275,"date":"2019-06-21T20:19:00","date_gmt":"2019-06-21T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1275"},"modified":"2021-02-08T23:42:36","modified_gmt":"2021-02-08T23:42:36","slug":"plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/","title":{"rendered":"PLRA evita informar c\u00f3mo ingres\u00f3 esposa del senador Buzarquis al TSJE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En la nucleaci\u00f3n pol\u00edtica hacen caso omiso a la consulta y se desentienden de explicar la raz\u00f3n por la cual recomen\u00addaron a la esposa del senador Salyn Buzarquis para el cargo de coordinadora general de la Unidad de G\u00e9nero de la Justi\u00adcia Electoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los ministros del TSJE se prestan para mantener en secreto los antecedentes del nombramiento y el vocero de la instituci\u00f3n nos pidi\u00f3 que le realicemos la consulta a un funcionario de nombre Primio Arce. \u201c\u00c9l es el representante del PLRA en la Justicia Elec\u00adtoral, va a explicar el tema\u201d, fue la indicaci\u00f3n que brindaron en la unidad de prensa de la ins\u00adtituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, Primio Arce no respondi\u00f3 las llamadas ni los mensajes que le enviamos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente del PLRA, Efra\u00edn Alegre, tambi\u00e9n se llam\u00f3 a un severo silencio cuando le lla\u00admamos y enviamos mensajes preguntando sobre el pedido de incorporaci\u00f3n que realiz\u00f3 su partido, seg\u00fan nos confir\u00admaron en el TSJE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mujer evidentemente es una privilegiada. Tiene un ingreso de unos G. 15 millones al mes y accedi\u00f3 a un cargo de jerarqu\u00eda gracias a la recomendaci\u00f3n del Partido Liberal, organismo en el cual integra el Directorio su influyente esposo, el senador Salyn Buzarquis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe recordar que adem\u00e1s de la esposa del senador, otras se\u00f1oras Buzarquis est\u00e1n muy bien ubicadas en la funci\u00f3n p\u00fablica. Griselda Mar\u00eda Mai\u00addana Sosa, esposa de V\u00edctor Abdel (funcionario comisio\u00adnado de Diputados), percibe unos G. 20 millones al mes entre sus ingresos en el Minis\u00adterio de la Defensa P\u00fablica y su rubro de \u201cprofesora asistente\u201d en la Universidad Nacional de Caaguaz\u00fa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed tambi\u00e9n, F\u00e1tima Rafaela Lird, segunda pareja oficial del diputado Enrique Antonio Buzarquis, ingres\u00f3 a la Con\u00adtralor\u00eda de la Rep\u00fablica el a\u00f1o pasado y meses despu\u00e9s consi\u00adgui\u00f3 un cargo en el Consejo de Administraci\u00f3n del Instituto de Previsi\u00f3n Social con sueldo de G. 12 millones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la nucleaci\u00f3n pol\u00edtica hacen caso omiso a la consulta y se desentienden de explicar la raz\u00f3n por la cual recomen\u00addaron a la esposa del senador Salyn Buzarquis para el cargo de coordinadora general de la Unidad de G\u00e9nero de la Justi\u00adcia Electoral. Los ministros del TSJE se prestan para mantener en secreto los antecedentes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[547,434,548,631],"ppma_author":[1039],"class_list":["post-1275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-partido-liberal","tag-plra","tag-salyn-buzarquis","tag-tsje"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PLRA evita informar c\u00f3mo ingres\u00f3 esposa del senador Buzarquis al TSJE - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PLRA evita informar c\u00f3mo ingres\u00f3 esposa del senador Buzarquis al TSJE - Informatepy\" \/>\n<meta property=\"og:description\" content=\"En la nucleaci\u00f3n pol\u00edtica hacen caso omiso a la consulta y se desentienden de explicar la raz\u00f3n por la cual recomen\u00addaron a la esposa del senador Salyn Buzarquis para el cargo de coordinadora general de la Unidad de G\u00e9nero de la Justi\u00adcia Electoral. Los ministros del TSJE se prestan para mantener en secreto los antecedentes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-21T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T23:42:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/fiorella-forestieri-esposa-buzarquis.jpg?fit=760%2C420&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"PLRA evita informar c\u00f3mo ingres\u00f3 esposa del senador Buzarquis al TSJE\",\"datePublished\":\"2019-06-21T20:19:00+00:00\",\"dateModified\":\"2021-02-08T23:42:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/fiorella-forestieri-esposa-buzarquis.jpg?fit=760%2C420&ssl=1\",\"keywords\":[\"partido liberal\",\"plra\",\"salyn buzarquis\",\"TSJE\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/\",\"name\":\"PLRA evita informar c\u00f3mo ingres\u00f3 esposa del senador Buzarquis al TSJE - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/fiorella-forestieri-esposa-buzarquis.jpg?fit=760%2C420&ssl=1\",\"datePublished\":\"2019-06-21T20:19:00+00:00\",\"dateModified\":\"2021-02-08T23:42:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/fiorella-forestieri-esposa-buzarquis.jpg?fit=760%2C420&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/fiorella-forestieri-esposa-buzarquis.jpg?fit=760%2C420&ssl=1\",\"width\":760,\"height\":420,\"caption\":\"Fiorella Forestieri, esposa del senador Salyn Buzarquis.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/21\\\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PLRA evita informar c\u00f3mo ingres\u00f3 esposa del senador Buzarquis al TSJE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PLRA evita informar c\u00f3mo ingres\u00f3 esposa del senador Buzarquis al TSJE - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/","og_locale":"es_ES","og_type":"article","og_title":"PLRA evita informar c\u00f3mo ingres\u00f3 esposa del senador Buzarquis al TSJE - Informatepy","og_description":"En la nucleaci\u00f3n pol\u00edtica hacen caso omiso a la consulta y se desentienden de explicar la raz\u00f3n por la cual recomen\u00addaron a la esposa del senador Salyn Buzarquis para el cargo de coordinadora general de la Unidad de G\u00e9nero de la Justi\u00adcia Electoral. Los ministros del TSJE se prestan para mantener en secreto los antecedentes [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/","og_site_name":"Informatepy","article_published_time":"2019-06-21T20:19:00+00:00","article_modified_time":"2021-02-08T23:42:36+00:00","og_image":[{"width":760,"height":420,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/fiorella-forestieri-esposa-buzarquis.jpg?fit=760%2C420&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"PLRA evita informar c\u00f3mo ingres\u00f3 esposa del senador Buzarquis al TSJE","datePublished":"2019-06-21T20:19:00+00:00","dateModified":"2021-02-08T23:42:36+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/fiorella-forestieri-esposa-buzarquis.jpg?fit=760%2C420&ssl=1","keywords":["partido liberal","plra","salyn buzarquis","TSJE"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/","url":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/","name":"PLRA evita informar c\u00f3mo ingres\u00f3 esposa del senador Buzarquis al TSJE - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/fiorella-forestieri-esposa-buzarquis.jpg?fit=760%2C420&ssl=1","datePublished":"2019-06-21T20:19:00+00:00","dateModified":"2021-02-08T23:42:36+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/fiorella-forestieri-esposa-buzarquis.jpg?fit=760%2C420&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/fiorella-forestieri-esposa-buzarquis.jpg?fit=760%2C420&ssl=1","width":760,"height":420,"caption":"Fiorella Forestieri, esposa del senador Salyn Buzarquis."},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/plra-evita-informar-como-ingreso-esposa-del-senador-buzarquis-al-tsje\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"PLRA evita informar c\u00f3mo ingres\u00f3 esposa del senador Buzarquis al TSJE"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/fiorella-forestieri-esposa-buzarquis.jpg?fit=760%2C420&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":11771,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/24\/salyn-buzarquis-plantea-devolver-las-ternas-de-candidatos-del-tsje\/","url_meta":{"origin":1275,"position":0},"title":"Salyn Buzarquis plantea devolver las ternas de candidatos del TSJE","date":"24 de mayo de 2022","format":false,"excerpt":"La\u00a0C\u00e1mara de Senadores\u00a0debe definir si elegir a los integrantes de las ternas conformadas para ocupar los dos cargos en el TSJE o devolverlas nuevamente al\u00a0Consejo de la Magistratura\u00a0(CM) para una nueva integraci\u00f3n. En ese sentido, el senador Salyn Buzarquis afirm\u00f3 que \"Por m\u00ed, devolver\u00eda la terna inmediatamente. Se actu\u00f3 con\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/salyn-buzarquis1.jpg?fit=900%2C700&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10858,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/29\/buzarquis-el-tercer-liberal-en-oficializar-su-postulacion\/","url_meta":{"origin":1275,"position":1},"title":"Buzarquis, el tercer liberal en oficializar su postulaci\u00f3n al TSJE","date":"29 de marzo de 2022","format":false,"excerpt":"Los senadores liberales parecen tomar a la C\u00e1mara Alta como un trampol\u00edn para conseguir otros cargos, quiz\u00e1s m\u00e1s beneficiosos. Primero fue V\u00edctor R\u00edos quien, a pesar de haber sido elegido hasta el 2023, se postul\u00f3 y consigui\u00f3 ser nombrado ministro de la Corte Suprema de Justicia. Ahora, la convocatoria a\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/salyn-buzarquis1.jpg?fit=900%2C700&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10530,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/09\/salyn-buzarquis-buscara-reducir-impuestos-y-evitar-nuevos-aumentos-en-el-combustible\/","url_meta":{"origin":1275,"position":2},"title":"Salyn Buzarquis buscar\u00e1 reducir impuestos y evitar nuevos aumentos en el combustible","date":"9 de marzo de 2022","format":false,"excerpt":"El senador liberal Salyn Buzarquis anunci\u00f3 que presentar\u00e1 un proyecto de ley para paliar el aumento del combustible y que el planteamiento buscar\u00e1 la reducci\u00f3n del impuesto, en busca de favorecer al consumidor. \u201cVamos a presentar un proyecto para paliar la suba del precio de los combustibles. Ser\u00e1 una alternativa\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/salyn-buzarquis1.jpg?fit=900%2C700&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4990,"url":"https:\/\/informatepy.com\/2021\/2021\/05\/23\/buzarquis-confia-en-derrotar-a-efrain-alegre-en-las-internas-del-plra\/","url_meta":{"origin":1275,"position":3},"title":"Buzarquis conf\u00eda en derrotar a Efra\u00edn Alegre en las internas del PLRA","date":"23 de mayo de 2021","format":false,"excerpt":"El senador liberal Enrique Salyn Buzarquis manifest\u00f3 p\u00fablicamente que nadie cree en el presidente del PLRA, Efra\u00edn Alegre, que no tiene chances de ganar las pr\u00f3ximas elecciones internas. Y agreg\u00f3: \u201cEstamos convencidos de que vamos a ganar el 20 de junio. Estamos trabajando a pesar de la pandemia. El pueblo\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/alegre-y-buzarquis.jpg?fit=1016%2C615&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3604,"url":"https:\/\/informatepy.com\/2021\/2021\/02\/25\/el-tsje-admiten-que-crisis-del-plra-pone-en-jaque-a-sus-candidatos-a-municipales\/","url_meta":{"origin":1275,"position":4},"title":"El TSJE admiten que crisis del PLRA pone en jaque a sus candidatos a municipales","date":"25 de febrero de 2021","format":false,"excerpt":"El Director de Procesos Electorales del TSJE, Carlos Mar\u00eda Ljubetic, admiti\u00f3 que la crisis en que se encuentra el PLRA, pone una alta cuota de incertidumbre al proceso liberal. \u201cEs toda una inc\u00f3gnita, porque se supone que una elecci\u00f3n de un movimiento, partido o concertaci\u00f3n, debe tener un Tribunal Electoral,\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/PLRA.jpg?fit=1200%2C626&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8982,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/22\/salyn-buzarquis-payo-cubas\/","url_meta":{"origin":1275,"position":5},"title":"\u00bfSalyn Buzarquis &#8211; Payo Cubas 2023?","date":"22 de diciembre de 2021","format":false,"excerpt":"Sigue la danza de nombres para las chapas presidenciales del 2023. La \u00faltima en sumarse es la que podr\u00eda conformarse entre el senador del Partido Liberal Salyn Buzarquis y el ex senador \"Payo\" Cubas. Salyn Buzarquis, confirm\u00f3 a Radio \u00d1andut\u00ed que no descarta formar una dupla presidencial con el exsenador\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1275"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1275\/revisions"}],"predecessor-version":[{"id":2895,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1275\/revisions\/2895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1276"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1275"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}