{"id":12473,"date":"2022-07-01T08:30:00","date_gmt":"2022-07-01T11:30:00","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=12473"},"modified":"2022-06-30T23:11:41","modified_gmt":"2022-07-01T02:11:41","slug":"semana-entre-cumbres-g7-otan","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/","title":{"rendered":"Semana entre Cumbres: G7 + OTAN"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Desde el pasado domingo, los mandatarios de los pa\u00edses m\u00e1s poderosos del mundo se reuni\u00f3n en el tradicional c\u00f3nclave denominado <strong>Grupo de los 7<\/strong>, integrado por <strong>Canad\u00e1, USA, Jap\u00f3n<\/strong> m\u00e1s cuatro pa\u00edses europeos tales como <strong>Reino Unido, Alemania, Francia e Italia.<\/strong> En esta ocasi\u00f3n, Alemania le correspondi\u00f3 ser el pa\u00eds anfitri\u00f3n por lo que la misma tuvo lugar en el lujoso castillo de Elmau en la ciudad de Baviera.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La cumbre de este a\u00f1o, el <strong>Canciller alem\u00e1n Olaf Scholz<\/strong> extendi\u00f3 invitaciones a <strong>Argentina<\/strong>, quien al parecer el propio presidente Alberto Fern\u00e1ndez le pidi\u00f3 ser invitado durante la cumbre que sostuvieron ambos mandatarios en mayo de este a\u00f1o, aunque, el potencial energ\u00e9tico del pa\u00eds austral le vali\u00f3 para ganarse un cupo en la cumbre de los m\u00e1s poderosos, Adicionalmente, participaron <strong>Ucrania <\/strong>(v\u00eda telem\u00e1tica), <strong>India <\/strong>e <strong>Indonesia <\/strong>por Asia y <strong>Senegal <\/strong>y <strong>Sud\u00e1frica <\/strong>por \u00c1frica. Por cierto, India y Sud\u00e1frica <strong>son miembros del BRICS<\/strong> (grupo relativamente antag\u00f3nico al G7), no obstante, su inclusi\u00f3n en la reuni\u00f3n de este a\u00f1o tal vez sirvi\u00f3 para tratar de mantener una suerte de canal de comunicaci\u00f3n en temas claves.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Comenzando el an\u00e1lisis de \u00e9sta, quiero subrayar lo referido a los ausentes, pues, tradicionalmente se hablaba en los c\u00edrculos acad\u00e9micos <strong>G7 + Rusia<\/strong>, justamente Rusia fue uno de los grandes ausentes, as\u00ed como igualmente <strong>Brasil<\/strong>, el gigante latinoamericano que sol\u00eda estar presente en tal selecto grupo. <strong>Por tercer a\u00f1o consecutivo Brasil no fue invitado,<\/strong> su no inclusi\u00f3n a nuestro juicio <strong>no se debe a que la naci\u00f3n amaz\u00f3nica haya perdido su caracter\u00edsticas econ\u00f3mica del mayor mercado de latinoamericano, sino tal vez, estrib\u00f3 en las diferencias<\/strong> \u2013por no decir fricciones- <strong>de los l\u00edderes del grupo con el presidente Jair Bolsonaro<\/strong> y su pol\u00edtica exterior m\u00e1s estrecha hacia Mosc\u00fa.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Englobando, esta cumbre \u2013como casi todos los eventos diplom\u00e1ticos este a\u00f1o- est\u00e1n marcados por la crisis internacional generada por la invasi\u00f3n de Rusia a Ucrania y las sub-crisis derivadas de \u00e9sta, tales como la crisis energ\u00e9tica y la alimentaria. En todo caso, se observ\u00f3 un grupo realmente muy cohesionado en torno a su posici\u00f3n respecto a Rusia y los esfuerzos de los pa\u00edses del G7 para paliar aspectos referidos a la econom\u00eda mundial, la inflaci\u00f3n y las energ\u00edas alternativas.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Dicha cohesi\u00f3n se puede evidenciar en la declaraci\u00f3n de la Cumbre <em><strong>\u201cG7 Leaders Statement\u201d<\/strong><\/em> documento que dedica al menos dos tercios al conflicto ruso-ucraniano, al que condenaron en\u00e9rgicamente, incluyeron persecuci\u00f3n ante la Corte Penal Internacional, exigieron la inmediata habilitaci\u00f3n de corredores humanitarios, agregaron sanciones a las transacciones del oro ruso y manifestaron su preocupaci\u00f3n por el potencial uso de armas de destrucci\u00f3n masiva. Por todo ello, <em>continuar\u00e1n apoyando indefinidamente a Ucrania.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El \u00faltimo tercio del documento lo dedican a temas varios, tales como reducir la dependencia energ\u00e9tica de Rusia, procurar el incremento de producci\u00f3n de crudo a los pa\u00edses de la OPEC, como fortalecer sus esfuerzos en las energ\u00edas sustentables concatenado con los objetivos del Acuerdo de Par\u00eds, cerrando con una b\u00fasqueda para impulsar la econom\u00eda global y la gesti\u00f3n de la crisis alimentaria, consecuencias \u00e9stas de las sanciones impuestas a Rusia. <strong>En s\u00edntesis: Rusia, energ\u00eda, ambiente y econom\u00eda marcaron la agenda de la Cumbre G7 del a\u00f1o 2022.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Para cerrar, sobre lo referido a la Cumbre de la OTAN \u2013 Madrid 2022,\u00a0 el rol de anfitri\u00f3n le correspondi\u00f3 al <strong>Presidente Pedro S\u00e1nchez<\/strong>, aqu\u00ed b\u00e1sicamente los tres grandes elementos resaltantes fueron: USA recupera su papel protag\u00f3nico y de liderazgo de la organizaci\u00f3n con importantes anuncios hechos por el Presidente Biden, tal como fue la promesa de<strong> 800 millones de d\u00f3lares m\u00e1s para Ucrania<\/strong>, el despliegue total de <strong>100 mil soldados estadunidenses en Europa<\/strong> y la ampliaci\u00f3n de los escuadrones de F35; adem\u00e1s de la incorporaci\u00f3n de Suecia y Finlandia a la OTAN tras la declinaci\u00f3n del veto por parte de Turqu\u00eda y; finalmente el cambio de concepto estrat\u00e9gico de la OTAN, este \u00faltimo tema lo analizaremos en profundidad en nuestra pr\u00f3xima entrega.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el pasado domingo, los mandatarios de los pa\u00edses m\u00e1s poderosos del mundo se reuni\u00f3n en el tradicional c\u00f3nclave denominado Grupo de los 7, integrado por Canad\u00e1, USA, Jap\u00f3n m\u00e1s cuatro pa\u00edses europeos tales como Reino Unido, Alemania, Francia e Italia. En esta ocasi\u00f3n, Alemania le correspondi\u00f3 ser el pa\u00eds anfitri\u00f3n por lo que la [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":8512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":false},"categories":[248],"tags":[1036,832,1357],"ppma_author":[1291],"class_list":["post-12473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-destacada","tag-estados-unidos","tag-otan"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semana entre Cumbres: G7 + OTAN - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semana entre Cumbres: G7 + OTAN - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Desde el pasado domingo, los mandatarios de los pa\u00edses m\u00e1s poderosos del mundo se reuni\u00f3n en el tradicional c\u00f3nclave denominado Grupo de los 7, integrado por Canad\u00e1, USA, Jap\u00f3n m\u00e1s cuatro pa\u00edses europeos tales como Reino Unido, Alemania, Francia e Italia. En esta ocasi\u00f3n, Alemania le correspondi\u00f3 ser el pa\u00eds anfitri\u00f3n por lo que la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-01T11:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/nahem.png?fit=1281%2C701&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1281\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nahem Reyes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nahem_360\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nahem Reyes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/\"},\"author\":{\"name\":\"Nahem Reyes\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/13c4021f6b762c195fe2d7431371023a\"},\"headline\":\"Semana entre Cumbres: G7 + OTAN\",\"datePublished\":\"2022-07-01T11:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/\"},\"wordCount\":732,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/nahem.png?fit=1281%2C701&ssl=1\",\"keywords\":[\"destacada\",\"estados unidos\",\"otan\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/\",\"name\":\"Semana entre Cumbres: G7 + OTAN - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/nahem.png?fit=1281%2C701&ssl=1\",\"datePublished\":\"2022-07-01T11:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/nahem.png?fit=1281%2C701&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/nahem.png?fit=1281%2C701&ssl=1\",\"width\":1281,\"height\":701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/07\\\/01\\\/semana-entre-cumbres-g7-otan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Semana entre Cumbres: G7 + OTAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/13c4021f6b762c195fe2d7431371023a\",\"name\":\"Nahem Reyes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Nahem-Reyes.jpg?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Nahem-Reyes.jpg?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Nahem-Reyes.jpg?fit=96%2C96&ssl=1\",\"caption\":\"Nahem Reyes\"},\"description\":\"Nahem Reyes es doctor en Historia de la Universidad Cat\u00f3lica Andr\u00e9s Bello y miembro asociado del Centro de Estudios de Am\u00e9rica de la Universidad Central de Venezuela. Analista pol\u00edtico\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nahem_360\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/nreyes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semana entre Cumbres: G7 + OTAN - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/","og_locale":"es_ES","og_type":"article","og_title":"Semana entre Cumbres: G7 + OTAN - Informatepy","og_description":"Desde el pasado domingo, los mandatarios de los pa\u00edses m\u00e1s poderosos del mundo se reuni\u00f3n en el tradicional c\u00f3nclave denominado Grupo de los 7, integrado por Canad\u00e1, USA, Jap\u00f3n m\u00e1s cuatro pa\u00edses europeos tales como Reino Unido, Alemania, Francia e Italia. En esta ocasi\u00f3n, Alemania le correspondi\u00f3 ser el pa\u00eds anfitri\u00f3n por lo que la [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/","og_site_name":"Informatepy","article_published_time":"2022-07-01T11:30:00+00:00","og_image":[{"width":1281,"height":701,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/nahem.png?fit=1281%2C701&ssl=1","type":"image\/png"}],"author":"Nahem Reyes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nahem_360","twitter_misc":{"Escrito por":"Nahem Reyes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/"},"author":{"name":"Nahem Reyes","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/13c4021f6b762c195fe2d7431371023a"},"headline":"Semana entre Cumbres: G7 + OTAN","datePublished":"2022-07-01T11:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/"},"wordCount":732,"commentCount":1,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/nahem.png?fit=1281%2C701&ssl=1","keywords":["destacada","estados unidos","otan"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/","url":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/","name":"Semana entre Cumbres: G7 + OTAN - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/nahem.png?fit=1281%2C701&ssl=1","datePublished":"2022-07-01T11:30:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/nahem.png?fit=1281%2C701&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/nahem.png?fit=1281%2C701&ssl=1","width":1281,"height":701},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/07\/01\/semana-entre-cumbres-g7-otan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Semana entre Cumbres: G7 + OTAN"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/13c4021f6b762c195fe2d7431371023a","name":"Nahem Reyes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/Nahem-Reyes.jpg?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/Nahem-Reyes.jpg?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/Nahem-Reyes.jpg?fit=96%2C96&ssl=1","caption":"Nahem Reyes"},"description":"Nahem Reyes es doctor en Historia de la Universidad Cat\u00f3lica Andr\u00e9s Bello y miembro asociado del Centro de Estudios de Am\u00e9rica de la Universidad Central de Venezuela. Analista pol\u00edtico","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Nahem_360"],"url":"https:\/\/informatepy.com\/2021\/author\/nreyes\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/nahem.png?fit=1281%2C701&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":12389,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/28\/la-otan-prepara-un-fuerte-documento-contra-china\/","url_meta":{"origin":12473,"position":0},"title":"La OTAN prepara un \u00abfuerte\u00bb documento contra China","date":"28 de junio de 2022","format":false,"excerpt":"Seg\u00fan la Agencia Reuters, Estados Unidos conf\u00eda en que el nuevo documento de estrategia de la OTAN incluir\u00e1 un lenguaje \"fuerte\" sobre China, dijo el domingo un funcionario de la Casa Blanca, y agreg\u00f3 que las negociaciones sobre c\u00f3mo referirse a Beijing a\u00fan estaban en curso. La alianza militar est\u00e1\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/05\/otan-bandera.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9773,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/27\/cumbre-de-dirigentes-de-la-derecha-europea\/","url_meta":{"origin":12473,"position":1},"title":"Cumbre de dirigentes de la derecha europea","date":"27 de enero de 2022","format":false,"excerpt":"Los caprichos de las agendas han provocado que el presidente de\u00a0Vox,\u00a0Santiago Abascal, 'abra' la campa\u00f1a electoral de\u00a0Castilla y Le\u00f3n\u00a0con una cumbre de l\u00edderes de derechas europeos a la que asistir\u00e1n, entre otros, los primeros ministros de Hungr\u00eda,\u00a0Viktor Orban, y Polonia,\u00a0Mateusz Morawiecki. Este acto, previsto desde el pasado mes de diciembre\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/abascal-orban.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7229,"url":"https:\/\/informatepy.com\/2021\/2021\/09\/20\/cumbre-de-la-celac-el-fallido-intento-de-lopez-obrador-de-crear-un-nuevo-foro-de-sao-paulo\/","url_meta":{"origin":12473,"position":2},"title":"Cumbre de la CELAC: el fallido intento de L\u00f3pez Obrador de crear un nuevo Foro de Sao Paulo","date":"20 de septiembre de 2021","format":false,"excerpt":"La sexta Cumbre de la Comunidad de Estados Latinoamericanos y Caribe\u00f1os\u00a0(CELAC), que tuvo lugar el pasado s\u00e1bado en M\u00e9xico, llam\u00f3 la atenci\u00f3n no por los planes positivos que ah\u00ed pretend\u00edan generarse \u2013sobre fondos para cat\u00e1strofes y vacunaci\u00f3n- sino por la presencia de dos dictadores comunistas:\u00a0Nicol\u00e1s Maduro, de Venezuela, y\u00a0Miguel D\u00edaz\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/lopez-obrador.jpg?fit=1104%2C622&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11651,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/16\/foro-de-sao-paulo-pide-por-la-presencia-de-las-dictaduras-en-la-cumbre-de-las-americas\/","url_meta":{"origin":12473,"position":3},"title":"Foro de Sao Paulo pide por la presencia de las dictaduras en la Cumbre de las Am\u00e9ricas","date":"16 de mayo de 2022","format":false,"excerpt":"La organizaci\u00f3n de izquierda conocida como Foro de Sao Paulo pidi\u00f3, a trav\u00e9s de un comunicado, por la presencia de las dictaduras \u00a0de Cuba, Nicaragua y Venezuela en la Cumbre de las Am\u00e9ricas que se llevar\u00e1 a cabo entre el 6 y el 10 de junio, en la ciudad de\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/foro-sao-pablo.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12602,"url":"https:\/\/informatepy.com\/2021\/2022\/07\/10\/la-otan-y-su-nuevo-concepto-de-seguridad-estrategica\/","url_meta":{"origin":12473,"position":4},"title":"La OTAN y su nuevo concepto de \u201cseguridad estrat\u00e9gica\u201d","date":"10 de julio de 2022","format":false,"excerpt":"Tal como les promet\u00ed en mi entrega anterior, hoy abordaremos lo referido al nuevo \u201cconcepto de seguridad estrat\u00e9gica\u201d de la OTAN, el cual, surgi\u00f3 a ra\u00edz de la m\u00e1s reciente cumbre celebrada en Madrid de 2022. Entre las novedades m\u00e1s relevantes de esta cubre, vale destacar que estuvo marcada ante\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/nahem.png?fit=1200%2C657&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7203,"url":"https:\/\/informatepy.com\/2021\/2021\/09\/18\/los-presidentes-de-paraguay-y-uruguay-reclaman-a-lopez-obrador-la-presencia-de-maduro-y-diaz-canel-en-cumbre-de-la-celac\/","url_meta":{"origin":12473,"position":5},"title":"Los presidentes de Paraguay y Uruguay reclaman a L\u00f3pez Obrador la presencia de Maduro y D\u00edaz-Canel en cumbre de la Celac","date":"18 de septiembre de 2021","format":false,"excerpt":"El presidente de Uruguay,\u00a0Luis Lacalle, y el presidente de Paraguay,\u00a0Mario Abdo Ben\u00edtez, reclamaron este viernes la presencia tanto del presidente de Venezuela,\u00a0Nicol\u00e1s Maduro, como la del presidente de Cuba,\u00a0Miguel D\u00edaz-Canel, en la cumbre de la Celac. Tras el saludo de rigor, Mario Abdo Ben\u00edtez dispar\u00f3 contra Maduro, quien tambi\u00e9n estaba\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/abdo-lacalle-pou.jpg?fit=1006%2C622&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1291,"user_id":15,"is_guest":0,"slug":"nreyes","display_name":"Nahem Reyes","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/Nahem-Reyes.jpg?fit=96%2C96&ssl=1","first_name":"Nahem","last_name":"Reyes","user_url":"","description":"Profesor en geograf\u00eda e historia por la Universidad Cat\u00f3lica Andr\u00e9s Bello, Venezuela. Analista pol\u00edtico"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=12473"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12473\/revisions"}],"predecessor-version":[{"id":12474,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12473\/revisions\/12474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/8512"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=12473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=12473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=12473"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=12473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}