{"id":1228,"date":"2019-06-01T20:19:00","date_gmt":"2019-06-01T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1228"},"modified":"2021-02-09T00:06:51","modified_gmt":"2021-02-09T00:06:51","slug":"ventas-en-cde-caen-un-70","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/","title":{"rendered":"Ventas en CDE caen un 70 %"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El titular de la Federaci\u00f3n de C\u00e1maras de Comercio (Fedec\u00e1maras), Tony Santamar\u00eda, confirm\u00f3 que el Banco Central del Brasil prohibi\u00f3 la compra de reales provenientes de Paraguay, ante la investigaci\u00f3n del Lava Jato que supuestamente salpica a tres bancos locales (Atlas, Continental y Basa), por un excedente en la transferencia de reales, con indicios de serias irregularidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs una situaci\u00f3n que no puede continuar, las circunstancias nos est\u00e1n llevando contra la pared, si nosotros no podemos depositar los reales en los bancos locales, que son los que tienen que remitirlos al Brasil, estamos atados de manos\u201d, explic\u00f3 Santamar\u00eda en entrevista con la 650 AM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Advirti\u00f3 que se requiere de manera urgente una reuni\u00f3n con el Banco Central del Paraguay, para que al menos explique lo que sucede y tome una determinaci\u00f3n inmediata para mitigar el impacto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santamar\u00eda estim\u00f3 que las ventas en la frontera cayeron al 70 % y explic\u00f3 que esta dificultad ya es lo suficientemente grande como para soportar una m\u00e1s, como lo es la restricci\u00f3n de el env\u00edo de reales al vecino pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anunci\u00f3 que ante la falta de respuesta necesariamente se ver\u00e1n obligados a comenzar a despedir empleados, pues el dinero empieza a escasear y ya no alcanza para cubrir los salarios de los empleados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNosotros somos parte del pueblo paraguayo, no somos un mont\u00f3n de piedras\u201d, insisti\u00f3 Santamar\u00eda y a la espera de recibir alguna salida de parte del Gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las restricci\u00f3n de la banca matriz brasile\u00f1a a la importaci\u00f3n de reales de Paraguay hace que los bancos locales dejen de recibir esta moneda. Con esto, los comerciantes no tienen manera de desagotar sus reales.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El titular de la Federaci\u00f3n de C\u00e1maras de Comercio (Fedec\u00e1maras), Tony Santamar\u00eda, confirm\u00f3 que el Banco Central del Brasil prohibi\u00f3 la compra de reales provenientes de Paraguay, ante la investigaci\u00f3n del Lava Jato que supuestamente salpica a tres bancos locales (Atlas, Continental y Basa), por un excedente en la transferencia de reales, con indicios de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[483],"tags":[290,564],"ppma_author":[1039],"class_list":["post-1228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipales","tag-cde","tag-ciudad-del-este"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ventas en CDE caen un 70 % - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ventas en CDE caen un 70 % - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El titular de la Federaci\u00f3n de C\u00e1maras de Comercio (Fedec\u00e1maras), Tony Santamar\u00eda, confirm\u00f3 que el Banco Central del Brasil prohibi\u00f3 la compra de reales provenientes de Paraguay, ante la investigaci\u00f3n del Lava Jato que supuestamente salpica a tres bancos locales (Atlas, Continental y Basa), por un excedente en la transferencia de reales, con indicios de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-01T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-09T00:06:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/CDE.jpg?fit=760%2C420&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Ventas en CDE caen un 70 %\",\"datePublished\":\"2019-06-01T20:19:00+00:00\",\"dateModified\":\"2021-02-09T00:06:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/\"},\"wordCount\":293,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/CDE.jpg?fit=760%2C420&ssl=1\",\"keywords\":[\"CDE\",\"ciudad del este\"],\"articleSection\":[\"Municipales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/\",\"name\":\"Ventas en CDE caen un 70 % - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/CDE.jpg?fit=760%2C420&ssl=1\",\"datePublished\":\"2019-06-01T20:19:00+00:00\",\"dateModified\":\"2021-02-09T00:06:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/CDE.jpg?fit=760%2C420&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/CDE.jpg?fit=760%2C420&ssl=1\",\"width\":760,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/06\\\/01\\\/ventas-en-cde-caen-un-70\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ventas en CDE caen un 70 %\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ventas en CDE caen un 70 % - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/","og_locale":"es_ES","og_type":"article","og_title":"Ventas en CDE caen un 70 % - Informatepy","og_description":"El titular de la Federaci\u00f3n de C\u00e1maras de Comercio (Fedec\u00e1maras), Tony Santamar\u00eda, confirm\u00f3 que el Banco Central del Brasil prohibi\u00f3 la compra de reales provenientes de Paraguay, ante la investigaci\u00f3n del Lava Jato que supuestamente salpica a tres bancos locales (Atlas, Continental y Basa), por un excedente en la transferencia de reales, con indicios de [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/","og_site_name":"Informatepy","article_published_time":"2019-06-01T20:19:00+00:00","article_modified_time":"2021-02-09T00:06:51+00:00","og_image":[{"width":760,"height":420,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/CDE.jpg?fit=760%2C420&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Ventas en CDE caen un 70 %","datePublished":"2019-06-01T20:19:00+00:00","dateModified":"2021-02-09T00:06:51+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/"},"wordCount":293,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/CDE.jpg?fit=760%2C420&ssl=1","keywords":["CDE","ciudad del este"],"articleSection":["Municipales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/","url":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/","name":"Ventas en CDE caen un 70 % - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/CDE.jpg?fit=760%2C420&ssl=1","datePublished":"2019-06-01T20:19:00+00:00","dateModified":"2021-02-09T00:06:51+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/CDE.jpg?fit=760%2C420&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/CDE.jpg?fit=760%2C420&ssl=1","width":760,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/06\/01\/ventas-en-cde-caen-un-70\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Ventas en CDE caen un 70 %"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/CDE.jpg?fit=760%2C420&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1165,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/20\/banco-basa-niega-relacion-con-el-caso-lava-jato\/","url_meta":{"origin":1228,"position":0},"title":"Banco Basa niega relaci\u00f3n con el caso Lava Jato","date":"20 de mayo de 2019","format":false,"excerpt":"En charla con la 970 AM Ocampos reconoci\u00f3 que el Banco Paulista hab\u00eda importado de Paraguay la suma de 1.600 millones de d\u00f3lares, pero recalc\u00f3 que esto es completamente l\u00edcito en el sistema bancario, ya que estas operaciones son conocidas como \u201cbanknotes\u201d y consisten en la reexportaci\u00f3n de divisas al\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/banco-Basa.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11794,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/26\/bancos-y-financieras-quieren-cobrar-por-operaciones-sipap\/","url_meta":{"origin":1228,"position":1},"title":"Bancos y Financieras quieren cobrar por operaciones SIPAP","date":"26 de mayo de 2022","format":false,"excerpt":"Bancos y financieras asociadas en ASOBAN y ABAFI remitieron una nota a Jos\u00e9 Cantero, Presidente del Banco Central de Paraguay (BCP) con un tarifario para las operaciones SPI - SIPAP en moneda nacional. El argumento empleado por ASOBAN y ABAFI es que con lo recaudado apoyar\u00e1n el \"sostenimiento de las\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/05\/SIPAP-BANCOS.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6005,"url":"https:\/\/informatepy.com\/2021\/2021\/07\/29\/denuncia-de-conmebol-allanaron-el-banco-central-por-primera-vez-en-la-historia\/","url_meta":{"origin":1228,"position":2},"title":"Denuncia de Conmebol: allanaron el Banco Central por primera vez en la historia","date":"29 de julio de 2021","format":false,"excerpt":"La presentaci\u00f3n legal de Alejandro Dom\u00ednguez es en el marco de la causa FIFA-Gate, en la que se desviaron fondos por hasta U$S 200 millones. La Justicia paraguaya intervino el Central por no otorgar informaci\u00f3n \"crucial\" en la investigaci\u00f3n por \"maniobras sospechadas de constituir lavado de dinero\". Fue poco despu\u00e9s\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/bcp.jpg?fit=768%2C512&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1185,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/22\/adaptarse-o-morir\/","url_meta":{"origin":1228,"position":3},"title":"Adaptarse&#8230; o morir","date":"22 de mayo de 2019","format":false,"excerpt":"Pocas cosas molestan tanto al lector avezado, como cuando a quien escribe un art\u00edculo period\u00edstico se le notan los hilos; y a pocos medios se le notan lo hilos como a ABC. Cierto es, digamos todo, que ABC es el medio de mayor circulaci\u00f3n en nuestro pa\u00eds pero, eso no\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/tapa-abc.jpg?fit=1200%2C586&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10409,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/03\/la-inflacion-interanual-de-febrero-fue-del-93\/","url_meta":{"origin":1228,"position":4},"title":"La inflaci\u00f3n interanual de febrero fue del 9,3%","date":"3 de marzo de 2022","format":false,"excerpt":"La inflaci\u00f3n interanual en Paraguay subi\u00f3 a un 9,3 % en febrero, impulsada por los precios de los combustibles y alimentos. Se trata del mayor \u00edndice registrado en m\u00e1s de una d\u00e9cada, seg\u00fan el Banco Central. \u201cLa inflaci\u00f3n se est\u00e1 volviendo un poco m\u00e1s persistente de lo que en un\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/inflacion.jpg?fit=800%2C453&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10467,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/06\/china-sigue-ganando-terreno-los-bancos-rusos-emitiran-tarjetas-con-unionpay-de-china\/","url_meta":{"origin":1228,"position":5},"title":"China sigue ganando terreno: Los bancos rusos emitir\u00e1n tarjetas con UnionPay de China","date":"6 de marzo de 2022","format":false,"excerpt":"Las tarjetas de cr\u00e9dito emitidas por bancos rusos que utilizan los sistemas de pago Visa y Mastercard dejar\u00e1n de funcionar en el extranjero despu\u00e9s del 9 de marzo, dijo el domingo el banco central de Rusia, y agreg\u00f3 que algunos proveedores locales buscar\u00edan utilizar el sistema UnionPay de China en\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/unionpay.jpg?fit=830%2C576&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1228"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1228\/revisions"}],"predecessor-version":[{"id":2925,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1228\/revisions\/2925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1229"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1228"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}