{"id":12245,"date":"2022-06-20T10:29:02","date_gmt":"2022-06-20T13:29:02","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=12245"},"modified":"2022-06-20T13:07:54","modified_gmt":"2022-06-20T16:07:54","slug":"combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/","title":{"rendered":"Combustible a 10.000 para que Lichi contrate operadores por 48.600 millones\u00a0en Petropar"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Mientras acogota a los ciudadanos con los precios cada vez m\u00e1s insostenibles del combustible de Petropar, su presidente, <strong>Denis Lichi, que aspira ser gobernador de Cordillera por el oficialismo,<\/strong> anunci\u00f3 con absoluto desparpajo que <strong>prev\u00e9 utilizar 48.600 millones de guaran\u00edes de las arcas del Estado para contratar personal en la petrolera estatal.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Esto, traducido a la realidad, es que casi 50 mil millones de guaran\u00edes estar\u00e1n destinados a la contrataci\u00f3n de operadores pol\u00edticos para su campa\u00f1a en una vergonzosa utilizaci\u00f3n de los recursos p\u00fablicos con fines electoralistas.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Petropar realiza un llamado a licitaci\u00f3n para la <em><strong>\u201cContrataci\u00f3n de firma especializada para el apoyo en la gesti\u00f3n de recursos humanos temporales\u201d<\/strong><\/em>, con la que se piensa incorporar personal a trav\u00e9s de la tercerizaci\u00f3n, que tendr\u00e1 la consecuencia de llenar la petrolera con operadores pol\u00edticos.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La excusa es que se contratar\u00e1 personal para la apertura de nuevas estaciones de servicio, lo que parece innecesario porque Petropar tiene un contrato vigente hasta el pr\u00f3ximo a\u00f1o con la empresa Dynamus, responsable de las contrataciones.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" style=\"font-style:normal;font-weight:300\">Con informaci\u00f3n de ADN Digital<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Mientras acogota a los ciudadanos con los precios cada vez m\u00e1s insostenibles del combustible de Petropar, su presidente, Denis Lichi, que aspira ser gobernador de Cordillera por el oficialismo, anunci\u00f3 con absoluto desparpajo que prev\u00e9 utilizar 48.600 millones de guaran\u00edes de las arcas del Estado para contratar personal en la petrolera estatal. Esto, traducido a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[470,1237,1844,1036,582,471],"ppma_author":[1051],"class_list":["post-12245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-combustible","tag-combustibles","tag-denis-lichi","tag-destacada","tag-inflacion","tag-petropar"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Combustible a 10.000 para que Lichi contrate operadores por 48.600 millones\u00a0en Petropar - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Combustible a 10.000 para que Lichi contrate operadores por 48.600 millones\u00a0en Petropar - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Mientras acogota a los ciudadanos con los precios cada vez m\u00e1s insostenibles del combustible de Petropar, su presidente, Denis Lichi, que aspira ser gobernador de Cordillera por el oficialismo, anunci\u00f3 con absoluto desparpajo que prev\u00e9 utilizar 48.600 millones de guaran\u00edes de las arcas del Estado para contratar personal en la petrolera estatal. Esto, traducido a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-20T13:29:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-20T16:07:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/denis-lichi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"646\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Combustible a 10.000 para que Lichi contrate operadores por 48.600 millones\u00a0en Petropar\",\"datePublished\":\"2022-06-20T13:29:02+00:00\",\"dateModified\":\"2022-06-20T16:07:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/\"},\"wordCount\":201,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/denis-lichi.jpg?fit=900%2C646&ssl=1\",\"keywords\":[\"combustible\",\"combustibles\",\"denis lichi\",\"destacada\",\"inflacion\",\"petropar\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/\",\"name\":\"Combustible a 10.000 para que Lichi contrate operadores por 48.600 millones\u00a0en Petropar - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/denis-lichi.jpg?fit=900%2C646&ssl=1\",\"datePublished\":\"2022-06-20T13:29:02+00:00\",\"dateModified\":\"2022-06-20T16:07:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/denis-lichi.jpg?fit=900%2C646&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/denis-lichi.jpg?fit=900%2C646&ssl=1\",\"width\":900,\"height\":646},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/20\\\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Combustible a 10.000 para que Lichi contrate operadores por 48.600 millones\u00a0en Petropar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Combustible a 10.000 para que Lichi contrate operadores por 48.600 millones\u00a0en Petropar - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/","og_locale":"es_ES","og_type":"article","og_title":"Combustible a 10.000 para que Lichi contrate operadores por 48.600 millones\u00a0en Petropar - Informatepy","og_description":"Mientras acogota a los ciudadanos con los precios cada vez m\u00e1s insostenibles del combustible de Petropar, su presidente, Denis Lichi, que aspira ser gobernador de Cordillera por el oficialismo, anunci\u00f3 con absoluto desparpajo que prev\u00e9 utilizar 48.600 millones de guaran\u00edes de las arcas del Estado para contratar personal en la petrolera estatal. Esto, traducido a [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-06-20T13:29:02+00:00","article_modified_time":"2022-06-20T16:07:54+00:00","og_image":[{"width":900,"height":646,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/denis-lichi.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Combustible a 10.000 para que Lichi contrate operadores por 48.600 millones\u00a0en Petropar","datePublished":"2022-06-20T13:29:02+00:00","dateModified":"2022-06-20T16:07:54+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/"},"wordCount":201,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/denis-lichi.jpg?fit=900%2C646&ssl=1","keywords":["combustible","combustibles","denis lichi","destacada","inflacion","petropar"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/","url":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/","name":"Combustible a 10.000 para que Lichi contrate operadores por 48.600 millones\u00a0en Petropar - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/denis-lichi.jpg?fit=900%2C646&ssl=1","datePublished":"2022-06-20T13:29:02+00:00","dateModified":"2022-06-20T16:07:54+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/denis-lichi.jpg?fit=900%2C646&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/denis-lichi.jpg?fit=900%2C646&ssl=1","width":900,"height":646},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/06\/20\/combustible-a-10-000-para-que-lichi-contrate-operadores-por-48-600-millones-en-petropar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Combustible a 10.000 para que Lichi contrate operadores por 48.600 millones\u00a0en Petropar"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/denis-lichi.jpg?fit=900%2C646&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":13332,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/14\/petropar-no-reducira-aun-costo-de-combustibles\/","url_meta":{"origin":12245,"position":0},"title":"Petropar no reducir\u00e1 a\u00fan costo de combustibles","date":"14 de agosto de 2022","format":false,"excerpt":"Denis Lichi, presidente de Petr\u00f3leos Paraguayos (Petropar), dijo que \u201ctodav\u00eda no se da el nivel\u201d que les gustar\u00eda para poder anunciar bajas importantes en los precios de los combustibles, pese a que el costo internacional del crudo est\u00e1 en sostenible descenso.\u00a0 Afirmo que \u201cHace aproximadamente 20 d\u00edas hemos tomado la\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/denis-lichi.jpg?fit=900%2C646&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13698,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/02\/petropar-avisa-no-bajara-el-precio-del-combustible\/","url_meta":{"origin":12245,"position":1},"title":"Petropar avisa: \u00abNo bajar\u00e1 el precio del combustible\u00bb","date":"2 de septiembre de 2022","format":false,"excerpt":"Aunque las informaciones muestran que en los pa\u00edses de la regi\u00f3n se ha reducido el precio del combustible, el presidente de Petropar, Denis Lichi, asegur\u00f3 lo contrario y adujo la\u00a0 inestabilidad del precio del petr\u00f3leo y la crisis mundial. https:\/\/twitter.com\/InformatePy1\/status\/1565478539608072193 \u201cNosotros tenemos el gas m\u00e1s barato del pa\u00eds, y vamos\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/denis-lichi.jpg?fit=900%2C646&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12458,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/30\/bandera-blanca-a-las-contrataciones-de-petropar-con-apoyo-de-oficialistas-y-oposicion\/","url_meta":{"origin":12245,"position":2},"title":"Bandera blanca a las contrataciones de Petropar con apoyo de oficialistas y oposici\u00f3n","date":"30 de junio de 2022","format":false,"excerpt":"El Senado resolvi\u00f3 postergar por 2 semanas el tratamiento del proyecto de Declaraci\u00f3n que insta a Petropar a suspender el llamado a licitaci\u00f3n para \u201cla contrataci\u00f3n de firma especializada para el apoyo en la gesti\u00f3n de recursos humanos temporales\u201d, lo que permitir\u00eda al presidente de la petrolera, Denis Lichi, a\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/petropar.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5077,"url":"https:\/\/informatepy.com\/2021\/2021\/05\/28\/petropar-anuncia-aumento-del-combustible-a-partir-de-manana\/","url_meta":{"origin":12245,"position":3},"title":"Petropar anuncia aumento del combustible a partir de ma\u00f1ana","date":"28 de mayo de 2021","format":false,"excerpt":"El presidente de Petr\u00f3leos Paraguayos (Petropar), Denis Lichi, confirm\u00f3 que desde este s\u00e1bado habr\u00e1 suba de precios en todos los combustibles, debido al alto costo a nivel internacional. \u201cDesde este s\u00e1bado vamos a tener un peque\u00f1o incremento en todos nuestros precios. V amos a tener que tocar los precios en\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/combustible.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14096,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/27\/lichi-se-burla-de-la-gente\/","url_meta":{"origin":12245,"position":4},"title":"Lichi se burla de la gente","date":"27 de septiembre de 2022","format":false,"excerpt":"Denis Lichi, presidente de Petropar, anunci\u00f3 con bombos y platillos que a partir de ma\u00f1ana se aplicar\u00e1 una reducci\u00f3n de G. 600 en el Diesel Tipo III y la Nafta 93 octanos en estaciones de servicio propias de la petrolera estatal. Cuando se conoci\u00f3 que los senadores rechazaron el proyecto\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/denis-lichi.jpg?fit=900%2C646&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13857,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/11\/conductores-de-plataformas-anuncian-movilizaciones-desde-este-lunes\/","url_meta":{"origin":12245,"position":5},"title":"Conductores de plataformas anuncian movilizaciones desde este lunes","date":"11 de septiembre de 2022","format":false,"excerpt":"Desde la Asociaci\u00f3n de Conductores del Paraguay, que aglutina a trabajadores de plataformas exigen que los precios de los combustibles tengan una reducci\u00f3n de precio en el pa\u00eds, es por eso que pretenden realizar movilizaciones desde el pr\u00f3ximo lunes. Basilio Duarte, representante del gremio, solicit\u00f3 al presidente de Petr\u00f3leos Paraguayos\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/conductores-de-plataformas-se-suman-a-protesta-de-camioneros.jpg?fit=600%2C338&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=12245"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12245\/revisions"}],"predecessor-version":[{"id":12250,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12245\/revisions\/12250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/12246"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=12245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=12245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=12245"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=12245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}