{"id":12112,"date":"2022-06-12T15:40:00","date_gmt":"2022-06-12T18:40:00","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=12112"},"modified":"2022-06-12T12:58:17","modified_gmt":"2022-06-12T15:58:17","slug":"biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/","title":{"rendered":"Biden y su democracia al estilo nicaraguense: Arrestan a candidato a gobernador del Partido Republicano"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Ryan Kelley, candidato a gobernador de Michigan por el Partido Republicano, fue arrestado este jueves por el FBI (Federal Bureau of Investigation) bajo la falsa premisa de que ingres\u00f3 al Capitolio y golpe\u00f3 polic\u00edas a pesar de que innumerables evidencias f\u00edlmicas hab\u00edan demostrado su inocencia.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>Ryan Kelley<\/strong>, quien era uno de los favoritos para convertirse en gobernador del Estado, enfrenta ahora\u00a0<strong>cuatro cargos por delitos menores relacionados con el ingreso indebido al Capitolio<\/strong>, que incluyen conducta desordenada.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Kelley lideraba las encuestas del Partido Republicano luego de que\u00a0<strong>James Craig, Perry Johnson\u00a0y otros tres candidatos republicanos sean inhabilitados para competir<\/strong>. De los <strong>cinco principales candidatos quedaron descalificados<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Kelley se hizo conocido masivamente por haber sido una importante voz contra la persecuci\u00f3n pol\u00edtica por el 6 de Enero y haber organziado protestas en contra de la cuarentena.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Los <strong>documentos judiciales aseguran que no pueden probar que Kelley haya ingresado al edificio<\/strong> pero, aun as\u00ed, el FBI lo imput\u00f3 por cargos de\u00a0<strong>entrar y permanecer en propiedad restringida a sabiendas<\/strong>,\u00a0<strong>alteraci\u00f3n del orden p\u00fablico en propiedad restringida<\/strong>,\u00a0<strong>participaci\u00f3n en actos violentos en propiedad restringida<\/strong>\u00a0y\u00a0<strong>da\u00f1o intencional a propiedad de los Estados Unidos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos arrestos constituyen la persecuci\u00f3n pol\u00edtica m\u00e1s grande de la historia de Estados Unidos desde las listas negras del macartismo. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Por ley, <strong>el ingreso indebido al Capitolio tiene como pena estipulada una multa de 500 d\u00f3lares<\/strong>, sin embargo, los fiscales de la Casa Blanca buscan instalar la narrativa que estas personas son \u201c<strong>insurreccionistas<\/strong>\u201d que intentaron hacer un golpe de Estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ryan Kelley, candidato a gobernador de Michigan por el Partido Republicano, fue arrestado este jueves por el FBI (Federal Bureau of Investigation) bajo la falsa premisa de que ingres\u00f3 al Capitolio y golpe\u00f3 polic\u00edas a pesar de que innumerables evidencias f\u00edlmicas hab\u00edan demostrado su inocencia. Ryan Kelley, quien era uno de los favoritos para convertirse [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12113,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[173],"tags":[1036,832,995,1833],"ppma_author":[1051],"class_list":["post-12112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-destacada","tag-estados-unidos","tag-fbi","tag-partido-republicano"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biden y su democracia al estilo nicaraguense: Arrestan a candidato a gobernador del Partido Republicano - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biden y su democracia al estilo nicaraguense: Arrestan a candidato a gobernador del Partido Republicano - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Ryan Kelley, candidato a gobernador de Michigan por el Partido Republicano, fue arrestado este jueves por el FBI (Federal Bureau of Investigation) bajo la falsa premisa de que ingres\u00f3 al Capitolio y golpe\u00f3 polic\u00edas a pesar de que innumerables evidencias f\u00edlmicas hab\u00edan demostrado su inocencia. Ryan Kelley, quien era uno de los favoritos para convertirse [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-12T18:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/ryan-kelley.jpg?fit=1280%2C720&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Biden y su democracia al estilo nicaraguense: Arrestan a candidato a gobernador del Partido Republicano\",\"datePublished\":\"2022-06-12T18:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/\"},\"wordCount\":277,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ryan-kelley.jpg?fit=1280%2C720&ssl=1\",\"keywords\":[\"destacada\",\"estados unidos\",\"fbi\",\"partido republicano\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/\",\"name\":\"Biden y su democracia al estilo nicaraguense: Arrestan a candidato a gobernador del Partido Republicano - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ryan-kelley.jpg?fit=1280%2C720&ssl=1\",\"datePublished\":\"2022-06-12T18:40:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ryan-kelley.jpg?fit=1280%2C720&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/ryan-kelley.jpg?fit=1280%2C720&ssl=1\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/06\\\/12\\\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biden y su democracia al estilo nicaraguense: Arrestan a candidato a gobernador del Partido Republicano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biden y su democracia al estilo nicaraguense: Arrestan a candidato a gobernador del Partido Republicano - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/","og_locale":"es_ES","og_type":"article","og_title":"Biden y su democracia al estilo nicaraguense: Arrestan a candidato a gobernador del Partido Republicano - Informatepy","og_description":"Ryan Kelley, candidato a gobernador de Michigan por el Partido Republicano, fue arrestado este jueves por el FBI (Federal Bureau of Investigation) bajo la falsa premisa de que ingres\u00f3 al Capitolio y golpe\u00f3 polic\u00edas a pesar de que innumerables evidencias f\u00edlmicas hab\u00edan demostrado su inocencia. Ryan Kelley, quien era uno de los favoritos para convertirse [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-06-12T18:40:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/ryan-kelley.jpg?fit=1280%2C720&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Biden y su democracia al estilo nicaraguense: Arrestan a candidato a gobernador del Partido Republicano","datePublished":"2022-06-12T18:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/"},"wordCount":277,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/ryan-kelley.jpg?fit=1280%2C720&ssl=1","keywords":["destacada","estados unidos","fbi","partido republicano"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/","url":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/","name":"Biden y su democracia al estilo nicaraguense: Arrestan a candidato a gobernador del Partido Republicano - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/ryan-kelley.jpg?fit=1280%2C720&ssl=1","datePublished":"2022-06-12T18:40:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/ryan-kelley.jpg?fit=1280%2C720&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/ryan-kelley.jpg?fit=1280%2C720&ssl=1","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Biden y su democracia al estilo nicaraguense: Arrestan a candidato a gobernador del Partido Republicano"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/ryan-kelley.jpg?fit=1280%2C720&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":13083,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/03\/se-esta-consumando-la-venganza-de-donald-trump-en-las-primarias-republicanas\/","url_meta":{"origin":12112,"position":0},"title":"Se est\u00e1 consumando la venganza de Donald Trump en las primarias republicanas","date":"3 de agosto de 2022","format":false,"excerpt":"Donald Trump hab\u00eda prometido'borrar el mapa' a los 10 republicanos que testificaron contra \u00e9l. Por ahora, la venganza se est\u00e1 consumando.","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/trump.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12825,"url":"https:\/\/informatepy.com\/2021\/2022\/07\/24\/intentaron-acuchillar-al-candidato-trumpista-a-gobernador-de-nueva-york\/","url_meta":{"origin":12112,"position":1},"title":"Intentaron acuchillar al candidato trumpista a gobernador de Nueva York","date":"24 de julio de 2022","format":false,"excerpt":"El candidato republicano (trumpista) a gobernador de Nueva York,\u00a0Lee Zeldin, fue atacado por un hombre en un evento de campa\u00f1a.\u00a0El terrorista subi\u00f3 al escenario con un elemento punzante en mano y le dijo \u201cTerminaste, est\u00e1s acabado\u201d, antes de intentar apu\u00f1alarlo. Zeldin, quien fren\u00f3 el discurso para escuchar lo que el\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/Lee-Zeldin.png?fit=800%2C450&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11261,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/21\/el-senado-de-florida-vota-para-despojar-a-disney-del-estado-especial-de-autogobierno\/","url_meta":{"origin":12112,"position":2},"title":"El Senado de Florida vota para despojar a Disney del estado especial de autogobierno","date":"21 de abril de 2022","format":false,"excerpt":"El Senado del estado de Florida vot\u00f3 para derogar una ley que permite a Walt Disney World operar un gobierno privado sobre sus propiedades en el estado, la \u00faltima andanada de una disputa entre el gobernador de Florida, Ron DeSantis, y el gigante del entretenimiento por lo que los cr\u00edticos\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/DeSantis-Disney.webp?fit=650%2C345&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10105,"url":"https:\/\/informatepy.com\/2021\/2022\/02\/15\/continua-el-desbande-de-integrantes-de-fuerza-republicana\/","url_meta":{"origin":12112,"position":3},"title":"Contin\u00faa el desbande de integrantes de Fuerza Republicana","date":"15 de febrero de 2022","format":false,"excerpt":"Maria Eugenia Crichigno, actual Parlasuriana, abandona las carpas del ofi\u00adcialismo y se suma al movimiento Honor Colorado. La estampida de dirigentes de carpas oficialistas a Honor Colorado no cesa, reforzando la pre candidatura de Santiago Pe\u00f1a para Presidente de la Rep\u00fablica y Horacio Cartes para Presidente de la Asociaci\u00f3n Nacional\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/maru-crichigno.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13496,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/22\/wiens-por-la-unidad-de-la-anr\/","url_meta":{"origin":12112,"position":4},"title":"Wiens por la unidad de la ANR","date":"22 de agosto de 2022","format":false,"excerpt":"En una entrevista exclusiva con Mina Feliciangeli, el candidato de Fuerza Republicana, Arnoldo Wiens lanz\u00f3 se\u00f1ales para la unidad de la Asociaci\u00f3n Nacional Republicana luego de las internas. \"Es doloroso como paraguayo, y es doloroso como colorado que le haya tocado (la designaci\u00f3n) a dos miembros de nuestro partido, es\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/wiens-mina.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3263,"url":"https:\/\/informatepy.com\/2021\/2021\/02\/13\/donald-trump-absuelto-en-el-juicio-politico-por-el-asalto-al-capitolio\/","url_meta":{"origin":12112,"position":5},"title":"Donald Trump: Absuelto en el juicio pol\u00edtico por el asalto al Capitolio","date":"13 de febrero de 2021","format":false,"excerpt":"El ex presidente estaba acusado de \u201cincitaci\u00f3n a la insurrecci\u00f3n\u201d en la jornada del 6 de enero El ex presidente republicano Donald Trump fue absuelto este s\u00e1bado de los cargos de \u201cincitaci\u00f3n a la insurrecci\u00f3n\u201d en los disturbios en el Capitolio en el juicio pol\u00edtico que se celebra en el\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/trump.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=12112"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12112\/revisions"}],"predecessor-version":[{"id":12115,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/12112\/revisions\/12115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/12113"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=12112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=12112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=12112"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=12112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}