{"id":11802,"date":"2022-05-27T08:30:00","date_gmt":"2022-05-27T11:30:00","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=11802"},"modified":"2022-05-26T20:18:10","modified_gmt":"2022-05-26T23:18:10","slug":"coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/","title":{"rendered":"Coram Deo y la respuesta de Jane Grahan (Una respuesta teologal a los acontecimientos actuales)"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Hace poco un amigo me hizo con toda seriedad una pregunta: <em><strong>\u00ab\u00bfCu\u00e1l es la gran idea de la vida cristiana?\u00bb <\/strong><\/em>Estaba interesado en el objetivo general y final de la vida cristiana. Para responder a su pregunta, reca\u00ed en la prerrogativa del te\u00f3logo y le di un t\u00e9rmino latino. Le dije: <em><strong>\u00abLa gran idea de la vida cristiana es coram Deo. Coram Deo captura la esencia de la vida cristiana, y enfatiza el porqu\u00e9 de nuestra problem\u00e1tica actual.\u00bb<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Esta frase se refiere literalmente a algo que tiene lugar en presencia de, o ante el rostro de Dios. Vivir el coram Deo es vivir toda la vida en la presencia de Dios, bajo la autoridad de Dios, para la gloria de Dios. Vivir en la presencia de Dios es entender, que hagamos todo lo que estamos haciendo y dondequiera que lo hagamos, actuamos bajo la mirada de Dios. Dios es omnipresente, omnisciente, omnipotente. No hay lugar tan remoto que podamos escapar de su mirada penetrante.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Coram Deo contrarresta todo lo que se ense\u00f1a en el mundo de hoy. Los medios de entretenimiento presentan constantemente una versi\u00f3n de la vida en la que Dios est\u00e1 totalmente ausente. La visi\u00f3n predominante de la sociedad es que debemos centrarnos en nosotros mismos y hacer lo que creemos que es correcto para nosotros. La popularidad, la fama y la fortuna son las actividades aceptables. Por el contrario, el coram Deo nos recuerda que vivimos para una audiencia de uno: Dios.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Cuando la gracia de Dios empez\u00f3 a trabajar en mi intelecto y en consecuencia, tambi\u00e9n en mi alma, durante mis a\u00f1os en el seminario, trajo un despertar doctrinal gradual que me llev\u00f3 a ir digiriendo mi vida hacia las grandes verdades escriturales que siempre hab\u00edan estado all\u00ed. Verdades que hubiese querido conocer desde el principio de mi acercamiento a las Sagradas Escrituras, sin embargo, la providencia de Dios es perfecta, Dios no llega a tiempo o es puntual como dicen algunos. El decreto de Dios est\u00e1 establecido y ese decreto divino incluye nuestro despertar para amar el estudio de las Escrituras e ir comprendiendo verdades transformadoras que traen un impacto eterno a nuestra alma y nuestra manera de vivir. La integridad se  encuentra donde los hombres y las mujeres viven sus vidas en un patr\u00f3n de consistencia. Es un patr\u00f3n que funciona de la misma manera b\u00e1sica en la iglesia y fuera de la iglesia. Es una vida abierta ante Dios. Es una vida vivida por principio, no por conveniencia; por humildad, no por desaf\u00edo. Es una vida vivida bajo la tutela de conciencia que es mantenida cautiva por la Palabra de Dios. Coram Deo\u2026 ante el rostro de Dios. Esa es la gran idea.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Junto a esta idea, nuestros otros objetivos y ambiciones se convierten en meras tonter\u00edas. El t\u00e9rmino Coram Deo es parte de la fraseolog\u00eda latina que surgi\u00f3 durante la Reforma Protestante, los reformadores esbozaron varios t\u00e9rminos y frases en lat\u00edn tales como <strong>Post Tenebras Lux<\/strong> (despu\u00e9s de la oscuridad, luz), <strong>Sola Scriptura<\/strong> (solo la Escritura), <strong>Sola Gratia<\/strong> (solo por gracia), <strong>Sola Fide<\/strong> (solo por fe), <strong>Solus Christus <\/strong>(solo Cristo), <strong>Soli Deo Gloria<\/strong> (solo a Dios la gloria), <strong>Simul Iustus Et Peccator<\/strong> (pecador y justo al mismo tiempo), <strong>Ecclesia Semper Reformanda Est<\/strong> (la Iglesia siempre reform\u00e1ndose), <strong>Ordus Salutis<\/strong> (el orden de la salvaci\u00f3n) entre otras.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Coram Deo son palabras que forman parte de ese conjunto de frases hermosas de las cuales estoy muy enamorado (no m\u00e1s que de Cristo, valga la aclaraci\u00f3n). Coram deriva del lat\u00edn cora (\u00abpupila del ojo\u00bb) y significa \u00aben persona\u00bb, \u00abcara a cara\u00bb, \u00aben presencia de uno\u00bb, \u00abante los propios ojos\u00bb, \u00aben presencia de\u00bb, \u00abdelante de\u00bb. Deo, en lat\u00edn, es Dios. Coram Deo, literalmente se refiere a algo que se lleva en la presencia de, o ante la presencia de Dios, es estar de cara o ante la faz de Dios. Coram Deo, es cuando la raz\u00f3n y el coraz\u00f3n est\u00e1n conscientes de la existencia y presencia de Dios, en donde quiera que estemos y en lo que sea que hagamos. Vivir toda la vida Coram Deo, es vivir una vida de integridad. Es una vida de integridad que encuentra su unidad y coherencia en la majestad de Dios. Una vida fragmentada es una vida de desintegraci\u00f3n. Est\u00e1 marcado por la incoherencia, la desarmon\u00eda, la confusi\u00f3n, el conflicto, la contradicci\u00f3n y el caos.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Aqu\u00ed, quisiera enlazar con la pregunta de Jane Clayson, a la hija del Pator Billy Grahan, Anne Grahan, en una entrevista que le hicieron en el programa estadounidense Early Show hace unos a\u00f1os, y que aqu\u00ed emplazo desde -DeadState-. Durante la entrevista, le hacen la siguiente pregunta: <strong><em>\u00bfC\u00f3mo puede permitir Dios tanto sufrimiento en el mundo, la destrucci\u00f3n de las Torres Gemelas, los ataques terroristas, los tiroteos en las escuelas, los huracanes, los movimientos s\u00edsmicos y los terremotos ocurran?.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lo cual, la hija de Billy Grahan, responde:<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" id=\"block-5910e4e2-224a-439c-934a-ba916987d0af\" style=\"font-size:16px\"><em>\u00abAl igual que nosotros, creo que Dios est\u00e1 profundamente triste por estos sucesos, pero durante a\u00f1os hemos estado dici\u00e9ndole a Dios que salga de nuestras escuelas, que se salga de nuestro gobierno y que se salga de nuestras vidas. \u00bfC\u00f3mo podemos esperar que Dios nos d\u00e9 Su bendici\u00f3n y Su protecci\u00f3n cuando le hemos exigido que nos deje estar solos?\u00bb   <\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" id=\"block-5910e4e2-224a-439c-934a-ba916987d0af\" style=\"font-size:16px\"><em>Luego alguien dijo que mejor no se leyera la Biblia en las escuelas&#8230; la Biblia dice no matar\u00e1s, no robar\u00e1s, amar\u00e1s a tu pr\u00f3jimo como a ti mismo. Y dijimos que estaba bien. <\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" id=\"block-5910e4e2-224a-439c-934a-ba916987d0af\" style=\"font-size:16px\"><em>Luego el Dr. Benjamin Spock dijo que no deb\u00edamos \u00abpegar\u00bb a nuestros hijos cuando se portan mal porque sus peque\u00f1as personalidades se truncar\u00edan y podr\u00edamos lastimar su autoestima (el hijo del Dr. Spock se suicid\u00f3). Dijimos que los expertos sab\u00edan lo que estaban diciendo. Y dijimos que estaba bien. <\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" id=\"block-5910e4e2-224a-439c-934a-ba916987d0af\" style=\"font-size:16px\"><em>Luego alguien dijo que los maestros y directores de los colegios no deber\u00edan disciplinar a nuestros hijos cuando se portan mal. Los administradores de las escuelas dijeron que m\u00e1s val\u00eda que ning\u00fan  miembro de la facultad de las escuelas tocara a ning\u00fan estudiante que se porte mal porque no queremos publicidad negativa y por supuesto no queremos que nos vayan a demandar (hay una gran  diferencia entre disciplinar, tocar, golpear, cachetear, humillar, patear, etc.). Y dijimos que estaba bien. <\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" id=\"block-5910e4e2-224a-439c-934a-ba916987d0af\" style=\"font-size:16px\"><em>Luego alguien dijo, dejemos que nuestras hijas aborten si quieren, y ni siquiera tienen que decirles a sus padres. Y dijimos que estaba bien. <\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" id=\"block-5910e4e2-224a-439c-934a-ba916987d0af\" style=\"font-size:16px\"><em>Luego uno de los consejeros del consejo de administraci\u00f3n de las escuelas dijo, ya que los muchachos siempre van a ser muchachos y de todos modos lo van a hacer, d\u00e9mosles a nuestros hijos todos los condones que quieran para que puedan divertirse al m\u00e1ximo, y no tenemos que decirle a sus padres que se los dimos en la escuela. Y dijimos que estaba bien. <\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" id=\"block-5910e4e2-224a-439c-934a-ba916987d0af\" style=\"font-size:16px\"><em>Luego algunos de nuestros principales funcionarios p\u00fablicos dijeron que no importa lo que hagamos en privado mientras cumplamos con nuestro trabajo. Estuvimos de acuerdo con ellos y dijimos, no me importa lo que nadie, incluyendo el presidente, haga en su vida privada mientras yo tenga un trabajo y la econom\u00eda est\u00e9 bien. <\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" id=\"block-5910e4e2-224a-439c-934a-ba916987d0af\" style=\"font-size:16px\"><em>Luego alguien dijo vamos a imprimir revistas con fotograf\u00edas de Mujeres desnudas y decir que esto es una apreciaci\u00f3n sana y realista de la belleza del cuerpo femenino. Y dijimos que estaba bien. <\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" id=\"block-5910e4e2-224a-439c-934a-ba916987d0af\" style=\"font-size:16px\"><em>Y luego alguien m\u00e1s llev\u00f3 m\u00e1s all\u00e1 esa apreciaci\u00f3n y public\u00f3 fotograf\u00edas de ni\u00f1os desnudos, llev\u00e1ndola a\u00fan m\u00e1s lejos cuando las coloc\u00f3 en Internet. Y dijimos que estaba bien, tienen derecho a  su libertad de expresi\u00f3n. <\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" id=\"block-5910e4e2-224a-439c-934a-ba916987d0af\" style=\"font-size:16px\"><em>Luego la industria de las diversiones dijo, hagamos shows por televisi\u00f3n y pel\u00edculas que promuevan lo profano, la violencia y el sexo il\u00edcito. Grabemos m\u00fasica que estimule las violaciones, las drogas, los suicidios y los temas sat\u00e1nicos. Y dijimos, no es m\u00e1s que diversi\u00f3n, no tiene efectos negativos, de todos modos nadie lo toma en serio, as\u00ed que adelante. <\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" id=\"block-5910e4e2-224a-439c-934a-ba916987d0af\" style=\"font-size:16px\"><em>Ahora nos preguntamos, \u00bfpor qu\u00e9 nuestros ni\u00f1os no tienen conciencia? \u00bfPor qu\u00e9 no saben distinguir entre el bien y el mal? \u00bfPor qu\u00e9 no les preocupa matar a desconocidos, a sus compa\u00f1eros de escuela, o a ellos mismos? <\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" id=\"block-5910e4e2-224a-439c-934a-ba916987d0af\" style=\"font-size:16px\"><em>Probablemente, si lo pensamos bien y despacio, encontraremos la respuesta, sembramos lo que recogemos. Si occidente no regresa a Dios, dijo, seguiremos viendo \u00absolo el caos en todos los niveles\u00bb&#8230;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00abNo os enga\u00f1\u00e9is; Dios no puede ser burlado: pues todo lo que el hombre sembrare, eso tambi\u00e9n segar\u00e1\u00bb. <\/p><cite>Galatas 6:7 (Reina Valera)<\/cite><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Vivamos siguiendo: <strong>CORAM DEO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace poco un amigo me hizo con toda seriedad una pregunta: \u00ab\u00bfCu\u00e1l es la gran idea de la vida cristiana?\u00bb Estaba interesado en el objetivo general y final de la vida cristiana. Para responder a su pregunta, reca\u00ed en la prerrogativa del te\u00f3logo y le di un t\u00e9rmino latino. Le dije: \u00abLa gran idea de [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":11109,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":false},"categories":[248],"tags":[1036],"ppma_author":[1728],"class_list":["post-11802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-destacada"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coram Deo y la respuesta de Jane Grahan (Una respuesta teologal a los acontecimientos actuales) - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coram Deo y la respuesta de Jane Grahan (Una respuesta teologal a los acontecimientos actuales) - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Hace poco un amigo me hizo con toda seriedad una pregunta: \u00ab\u00bfCu\u00e1l es la gran idea de la vida cristiana?\u00bb Estaba interesado en el objetivo general y final de la vida cristiana. Para responder a su pregunta, reca\u00ed en la prerrogativa del te\u00f3logo y le di un t\u00e9rmino latino. Le dije: \u00abLa gran idea de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-27T11:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1281%2C700&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1281\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arthur Charlan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ArthurCharlan\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur Charlan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/\"},\"author\":{\"name\":\"Arthur Charlan\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/fae5ed0c5294aed3b7c045adac96611c\"},\"headline\":\"Coram Deo y la respuesta de Jane Grahan (Una respuesta teologal a los acontecimientos actuales)\",\"datePublished\":\"2022-05-27T11:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/\"},\"wordCount\":1494,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Arthur-Charlan.png?fit=1281%2C700&ssl=1\",\"keywords\":[\"destacada\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/\",\"name\":\"Coram Deo y la respuesta de Jane Grahan (Una respuesta teologal a los acontecimientos actuales) - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Arthur-Charlan.png?fit=1281%2C700&ssl=1\",\"datePublished\":\"2022-05-27T11:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Arthur-Charlan.png?fit=1281%2C700&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Arthur-Charlan.png?fit=1281%2C700&ssl=1\",\"width\":1281,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/27\\\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coram Deo y la respuesta de Jane Grahan (Una respuesta teologal a los acontecimientos actuales)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/fae5ed0c5294aed3b7c045adac96611c\",\"name\":\"Arthur Charlan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Arthur-charlam.jpg?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Arthur-charlam.jpg?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Arthur-charlam.jpg?fit=96%2C96&ssl=1\",\"caption\":\"Arthur Charlan\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/ArthurCharlan\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/acharlan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coram Deo y la respuesta de Jane Grahan (Una respuesta teologal a los acontecimientos actuales) - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/","og_locale":"es_ES","og_type":"article","og_title":"Coram Deo y la respuesta de Jane Grahan (Una respuesta teologal a los acontecimientos actuales) - Informatepy","og_description":"Hace poco un amigo me hizo con toda seriedad una pregunta: \u00ab\u00bfCu\u00e1l es la gran idea de la vida cristiana?\u00bb Estaba interesado en el objetivo general y final de la vida cristiana. Para responder a su pregunta, reca\u00ed en la prerrogativa del te\u00f3logo y le di un t\u00e9rmino latino. Le dije: \u00abLa gran idea de [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/","og_site_name":"Informatepy","article_published_time":"2022-05-27T11:30:00+00:00","og_image":[{"width":1281,"height":700,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1281%2C700&ssl=1","type":"image\/png"}],"author":"Arthur Charlan","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ArthurCharlan","twitter_misc":{"Escrito por":"Arthur Charlan","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/"},"author":{"name":"Arthur Charlan","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/fae5ed0c5294aed3b7c045adac96611c"},"headline":"Coram Deo y la respuesta de Jane Grahan (Una respuesta teologal a los acontecimientos actuales)","datePublished":"2022-05-27T11:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/"},"wordCount":1494,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1281%2C700&ssl=1","keywords":["destacada"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/","url":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/","name":"Coram Deo y la respuesta de Jane Grahan (Una respuesta teologal a los acontecimientos actuales) - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1281%2C700&ssl=1","datePublished":"2022-05-27T11:30:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1281%2C700&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1281%2C700&ssl=1","width":1281,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/05\/27\/coram-deo-y-la-respuesta-de-jane-grahan-una-respuesta-teologal-a-los-acontecimientos-actuales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Coram Deo y la respuesta de Jane Grahan (Una respuesta teologal a los acontecimientos actuales)"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/fae5ed0c5294aed3b7c045adac96611c","name":"Arthur Charlan","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Arthur-charlam.jpg?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Arthur-charlam.jpg?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Arthur-charlam.jpg?fit=96%2C96&ssl=1","caption":"Arthur Charlan"},"sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/ArthurCharlan"],"url":"https:\/\/informatepy.com\/2021\/author\/acharlan\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1281%2C700&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":12205,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/17\/no-todas-las-vidas-negras-importan\/","url_meta":{"origin":11802,"position":0},"title":"No todas las vidas negras importan","date":"17 de junio de 2022","format":false,"excerpt":"Desde 2009, despu\u00e9s de la insurgencia del grupo islamista Boko Haram, Nigeria ha tenido que lidiar con atentados contra iglesias, escuelas y otras organizaciones","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/Masacre-Nigeria.webp?fit=1068%2C712&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11617,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/14\/el-fiscal-de-dios-y-la-patria\/","url_meta":{"origin":11802,"position":1},"title":"El fiscal de Dios y la Patria","date":"14 de mayo de 2022","format":false,"excerpt":"La muerte del Fiscal Marcelo Pecci, QEPD, despert\u00f3 todo tipo de reacciones en la sociedad paraguaya y en Hispanoam\u00e9rica en general. Es que toda la situaci\u00f3n se prest\u00f3 para una novela de tipo tr\u00e1gico aunque con esperanzadora moraleja por las escenas finales del periplo que toc\u00f3 vivir al ilustre difunto\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/05\/pecci-despacho.webp?fit=1016%2C677&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13934,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/","url_meta":{"origin":11802,"position":2},"title":"Los insumisos","date":"15 de septiembre de 2022","format":false,"excerpt":"El mundo no ser\u00e1 salvado, si lo es, por nadie m\u00e1s que los insumisos. Andr\u00e9 Gide O, dir\u00eda yo, a los ojos de Dios, lo \u00fanicos que se salvar\u00e1n ser\u00e1n los insumisos. Fundamento b\u00edblico tengo, el remanente fiel, en \u00e9l, como perlas que se suceden en el tiempo, est\u00e1 toda\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/raul-melamed-columnista.png?fit=1200%2C657&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11539,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/08\/finis-coronat-opus\/","url_meta":{"origin":11802,"position":3},"title":"Finis coronat opus","date":"8 de mayo de 2022","format":false,"excerpt":"La frase latina que da nombre al t\u00edtulo de este art\u00edculo tiene varios significados, uno de ellos \u00edndica que debemos persistir en lo que se empieza hasta acabarlo, otra que nada ha de darse por definitivo hasta su conclusi\u00f3n. Ahora bien, dicho esto, cuantas veces habr\u00edamos dado un tajo a\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1200%2C656&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12192,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/17\/los-que-dicen-que-cristiano-es-mejor-que-messi-no-saben-nada-de-futbol\/","url_meta":{"origin":11802,"position":4},"title":"Los que dicen que Cristiano es mejor que Messi no saben nada de f\u00fatbol","date":"17 de junio de 2022","format":false,"excerpt":"Como cada vez que habla\u00a0Marco van Basten\u00a0dej\u00f3 tela para cortar. En una charla de f\u00fatbol dio su opini\u00f3n sobre los jugadores que han marcado la historia de este deporte y se meti\u00f3 de lleno en la pol\u00e9mica sobre qui\u00e9n es mejor, Lionel Messi o Cristiano Ronaldo. El neerland\u00e9s, famoso por\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/van-vasten.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6756,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/","url_meta":{"origin":11802,"position":5},"title":"Cristiano Ronaldo lleg\u00f3 a un acuerdo con el Manchester City","date":"26 de agosto de 2021","format":false,"excerpt":"Desde Espa\u00f1a afirman que el portugu\u00e9s tiene encaminado su contrato con la entidad inglesa, pero la gran traba radica en las pretensiones de la Vecchia Signora","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1728,"user_id":41,"is_guest":0,"slug":"acharlan","display_name":"Arthur Charlan","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Arthur-charlam.jpg?fit=96%2C96&ssl=1","first_name":"Arthur","last_name":"Charlan","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/11802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=11802"}],"version-history":[{"count":3,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/11802\/revisions"}],"predecessor-version":[{"id":11806,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/11802\/revisions\/11806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/11109"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=11802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=11802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=11802"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=11802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}