{"id":11675,"date":"2022-05-19T08:14:00","date_gmt":"2022-05-19T11:14:00","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=11675"},"modified":"2022-05-19T10:19:24","modified_gmt":"2022-05-19T13:19:24","slug":"la-modernidad-liquida-de-zygmun-baugman-y-woody-allen","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/","title":{"rendered":"La modernidad l\u00edquida de Zygmun Baugman y Woody Allen"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Estas palabras pertenecen a un diario secreto de Woody Allen, que se publicar\u00e1 p\u00f3stumamente o, despu\u00e9s de su muerte, lo que suceda primero. (Cuentos sin plumas, de wooddy Allen)<\/h5>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Esta absurdez es lo que estamos viviendo en nuestra \u00e9poca contempor\u00e1nea. Un sinsentido cubista como el cuadro de Picasso <strong>\u00abmujer desnuda en la cama\u00bb<\/strong> que se acaba de subastar y vender por 67 millones de d\u00f3lares en la <strong>casa Sotheby&#8217;s de Nueva York.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El ej\u00e9rcito del caos y de lo absurdo campa a sus anchas como una panda guerrillera, pistola en mano, no se esconden y se ampl\u00edan abiertamente en el campo de batalla, preparado para combatir sin miedo ni pudor en las fronteras vulnerables de la sociedad. Gracias a Dios, esto no ocurre en sociedades como Rusia, Jap\u00f3n, Corea, la del sur\u2026 en occidente necesitamos que Trump vuelva a ocupar la Casa Blanca. Tal vez, Europa despierte, pero, no lo creo, ya que vive bajo opi\u00e1ceos muy intensos.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En medio de todo este caos mundial, luchamos para combatir las amenazas que surgen por todos lados a nuestras vidas y familias.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El mundo se est\u00e1 fragmentando y cambiando en direcciones desafortunadamente, inmorales y dictatoriales. El paraguas moral bajo el cual hemos estado afincados durante siglos se est\u00e1 derrumbando bajo los feroces vientos del caos. La esperanza (Eucatastrofe) de la que con tanto fervor y ah\u00ednco nos habla J.R.R.Tolkien en sus libros, est\u00e1 quedando diluida ante la falta de solidez de nuestros fundamentos fundacionales de nuestros padres. Como escribi\u00f3 el soci\u00f3logo Zygmun Bauman, la solidez de nuestra sociedad se est\u00e1 desgajando hacia un estado l\u00edquido, impermanente, para dar paso a una sociedad disfuncional, donde todo cambia constantemente y se deteriora, sin remedio, hacia una sociedad inmadura.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">De hecho, si recordamos los Diez Mandamientos, estos nos revelan unos l\u00edmites que nos aseguran estabilidad y bienestar en la Tierra: 1-Adoraci\u00f3 verdadera 2-Trascendencia 3-reverencia 4-Santidad 5- Familia 6- Santidad de la vida 7- Comportamiento moral 8-Propiedad 9- Integridad 10- Respeto a los dem\u00e1s.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Es cierto que hoy d\u00eda estos l\u00edmites se ven coaccionados con restricciones al placer del d\u00eda a d\u00eda. Pero, es en ausencia de l\u00edmites s\u00f3lidos, que las libertades se deterioran y se convierten en anarqu\u00eda, convirtiendo los muros protectores en barreras que aprisionan.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Uno de los puntos principales que Bauman habla en su libro Modernidad L\u00edquida, es el sentido de la disoluci\u00f3n de pertenencia social del ser humano, para dar paso a una marcada individualidad, real e independiente. Este hecho remarca que para Bauman, la modernidad l\u00edquida es como la posibilidad de que una verdadera modernidad fruct\u00edfera y verdadera se nos escapara de entre las manos como el agua entre los dedos.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La globalizaci\u00f3n nos ha llevado a alejarnos de la verdadera humanidad, a desencajarnos del verdadero puzle que nos manten\u00eda unido a la sociedad. De esta manera tenemos una sociedad l\u00edquida, maleable, escurridiza, que fluye no como un r\u00edo, sino como una catarata sin freno. Nos sentimos independiente, libres, emancipados, seguros, empoderados, rectores de nuestro destino, pero es todo lo contrario, vamos camino de una prisi\u00f3n farenhiana (l\u00e9ase Farenheit 451, de Ray Bradbury).<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Este falso progresismo liberal, pretende con tantas libertades, atarnos al vacuo, pero no de la inocua despreocupaci\u00f3n por lo real. Abocados por esta ingenier\u00eda social, a la despreocupaci\u00f3n, al consumismo, a la b\u00fasqueda de satisfacci\u00f3n r\u00e1pida, a la oferta del dos por uno, a las colecciones de moda, para dejar de hoy para ma\u00f1ana. Todo esto da por hecho la falta de rumbo de una sociedad que ha sido planificada hacia el caos emocional de un exorcismo maniqueo muy sutil.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Pero porque Bauman y Allen, porque ambos retratan a su manera la absurdidad del momento que vivimos como el cuadro, de Picasso que pueden buscar en las redes. El cuadro de estilo cubista, retrata a Marie-Ther\u00e8se Walter, musa del pintor malague\u00f1o, con quien mantuvo una relaci\u00f3n pese a los 27 a\u00f1os de diferencia entre ambos. Aqu\u00ed estoy de acuerdo con el relato de Haruki Murakami -El Carnaval- pero es que Murakami sabe convertir lo absurdo en algo hermoso y como dice en otro relato -Antolog\u00eda po\u00e9tica de los Yakult Swallows de Tokio- :<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00abEl valor del tiempo que paso aqu\u00ed no depende del resultado que muestre al final el marcador.<br>El valor de las horas y los minutos es intr\u00ednseco a ellos, y tambi\u00e9n es responsabilidad de uno<br>dialogar con el paso del tiempo para que este sea ben\u00e9volo y le otorgue buenos recuerdos que<br>llevarse. Esto es, sin duda, lo m\u00e1s importante.<\/p><\/blockquote><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00abUn hombre se despierta y descubre que su loro ha sido nombrado subsecretario de agricultura. Los celos le consumen y se pega un tiro, pero desgraciadamente la pistola es de \u00e9sas de las que vale una banderita que pone -Bang- La banderita le saca un ojo, pero sobrevive\u00bb.<\/p>\n","protected":false},"author":41,"featured_media":11109,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":false},"categories":[248],"tags":[1036,1381],"ppma_author":[1728],"class_list":["post-11675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-destacada","tag-globalizacion"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La modernidad l\u00edquida de Zygmun Baugman y Woody Allen - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La modernidad l\u00edquida de Zygmun Baugman y Woody Allen - Informatepy\" \/>\n<meta property=\"og:description\" content=\"&quot;Un hombre se despierta y descubre que su loro ha sido nombrado subsecretario de agricultura. Los celos le consumen y se pega un tiro, pero desgraciadamente la pistola es de \u00e9sas de las que vale una banderita que pone -Bang- La banderita le saca un ojo, pero sobrevive&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-19T11:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-19T13:19:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1281\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arthur Charlan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ArthurCharlan\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur Charlan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/\"},\"author\":{\"name\":\"Arthur Charlan\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/fae5ed0c5294aed3b7c045adac96611c\"},\"headline\":\"La modernidad l\u00edquida de Zygmun Baugman y Woody Allen\",\"datePublished\":\"2022-05-19T11:14:00+00:00\",\"dateModified\":\"2022-05-19T13:19:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/\"},\"wordCount\":800,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Arthur-Charlan.png?fit=1281%2C700&ssl=1\",\"keywords\":[\"destacada\",\"globalizacion\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/\",\"name\":\"La modernidad l\u00edquida de Zygmun Baugman y Woody Allen - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Arthur-Charlan.png?fit=1281%2C700&ssl=1\",\"datePublished\":\"2022-05-19T11:14:00+00:00\",\"dateModified\":\"2022-05-19T13:19:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Arthur-Charlan.png?fit=1281%2C700&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Arthur-Charlan.png?fit=1281%2C700&ssl=1\",\"width\":1281,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/05\\\/19\\\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La modernidad l\u00edquida de Zygmun Baugman y Woody Allen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/fae5ed0c5294aed3b7c045adac96611c\",\"name\":\"Arthur Charlan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Arthur-charlam.jpg?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Arthur-charlam.jpg?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Arthur-charlam.jpg?fit=96%2C96&ssl=1\",\"caption\":\"Arthur Charlan\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/ArthurCharlan\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/acharlan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La modernidad l\u00edquida de Zygmun Baugman y Woody Allen - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/","og_locale":"es_ES","og_type":"article","og_title":"La modernidad l\u00edquida de Zygmun Baugman y Woody Allen - Informatepy","og_description":"\"Un hombre se despierta y descubre que su loro ha sido nombrado subsecretario de agricultura. Los celos le consumen y se pega un tiro, pero desgraciadamente la pistola es de \u00e9sas de las que vale una banderita que pone -Bang- La banderita le saca un ojo, pero sobrevive\".","og_url":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/","og_site_name":"Informatepy","article_published_time":"2022-05-19T11:14:00+00:00","article_modified_time":"2022-05-19T13:19:24+00:00","og_image":[{"width":1281,"height":700,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png","type":"image\/png"}],"author":"Arthur Charlan","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ArthurCharlan","twitter_misc":{"Escrito por":"Arthur Charlan","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/"},"author":{"name":"Arthur Charlan","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/fae5ed0c5294aed3b7c045adac96611c"},"headline":"La modernidad l\u00edquida de Zygmun Baugman y Woody Allen","datePublished":"2022-05-19T11:14:00+00:00","dateModified":"2022-05-19T13:19:24+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/"},"wordCount":800,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1281%2C700&ssl=1","keywords":["destacada","globalizacion"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/","url":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/","name":"La modernidad l\u00edquida de Zygmun Baugman y Woody Allen - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1281%2C700&ssl=1","datePublished":"2022-05-19T11:14:00+00:00","dateModified":"2022-05-19T13:19:24+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1281%2C700&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1281%2C700&ssl=1","width":1281,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/05\/19\/la-modernidad-liquida-de-zygmun-baugman-y-woody-allen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"La modernidad l\u00edquida de Zygmun Baugman y Woody Allen"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/fae5ed0c5294aed3b7c045adac96611c","name":"Arthur Charlan","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Arthur-charlam.jpg?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Arthur-charlam.jpg?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Arthur-charlam.jpg?fit=96%2C96&ssl=1","caption":"Arthur Charlan"},"sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/ArthurCharlan"],"url":"https:\/\/informatepy.com\/2021\/author\/acharlan\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1281%2C700&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":485,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/conspiracion-y-secretos-neil-armstrong-vio-ovnis-en-la-luna\/","url_meta":{"origin":11675,"position":0},"title":"Conspiraci\u00f3n y secretos \u00bfNeil Armstrong vio ovnis en la Luna?","date":"10 de febrero de 2019","format":false,"excerpt":"Hay pocas personas a las que con total certeza se las pueda calificar como \"primer hombre\". Este es el caso de Neil Armstrong. Fue el primero en pisar la Luna. En total, 12 hombres forman parte del club m\u00e1s selecto del mundo, el de los que llegaron a la Luna\u2026","rel":"","context":"En \u00abCiencia y Tecnolog\u00eda\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nasa-aliens.jpg?fit=611%2C308&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12176,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/16\/nuestra-conciencia-como-bastion-de-la-verdad\/","url_meta":{"origin":11675,"position":1},"title":"Nuestra conciencia como basti\u00f3n de la verdad","date":"16 de junio de 2022","format":false,"excerpt":"\"Por primera vez me examin\u00e9 seriamente con un prop\u00f3sito pr\u00e1ctico. Y encontr\u00e9 algo que me aterr\u00f3: un zool\u00f3gico de lujurias, un manicomio de ambiciones, una guarder\u00eda de miedos, un har\u00e9n de odios mimados. Mi nombre era legi\u00f3n\". C.S.Lewis","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/Arthur-Charlan.png?fit=1200%2C656&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10291,"url":"https:\/\/informatepy.com\/2021\/2022\/02\/23\/argentina-detienen-a-dos-personas-vinculadas-a-madres-de-plaza-de-mayo-por-incendiar-campos-en-corrientes\/","url_meta":{"origin":11675,"position":2},"title":"ARGENTINA: Detienen a dos personas vinculadas a Madres de Plaza de Mayo por incendiar campos en Corrientes","date":"23 de febrero de 2022","format":false,"excerpt":"Durante las \u00faltimas horas, fuentes de la Polic\u00eda de Corrientes revelaron que efectivos detuvieron a dos personas acusadas de provocar focos de incendio en zonas de Alvear. Hebe de Bonafini, titular de Abuelas de Plaza de Mayo hab\u00eda llamado a \u201cincendiar los campos de los ricos\u201d. https:\/\/twitter.com\/capcentral\/status\/1496283794579599367 La camioneta secuestrada\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/CAMIONETA-MADRES-PLAZA-DE-MAYO.jpg?fit=1200%2C877&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8861,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/15\/uno-mas-y-van-futbolista-frances-abandona-el-campo-de-juego-con-problemas-respiratorios\/","url_meta":{"origin":11675,"position":3},"title":"Uno m\u00e1s, \u00bfY van&#8230;? Futbolista franc\u00e9s abandona el campo de juego con problemas respiratorios","date":"15 de diciembre de 2021","format":false,"excerpt":"El futbolista profesional franc\u00e9s,\u00a0Martin TERRIER, que juega en el club Rennes, de la Ligue 1, fue sustituido el domingo durante su partido ante el Niza tras sufrir dolores en el pecho. Este es el\u00a0tercer incidente\u00a0en cuesti\u00f3n de d\u00edas (V\u00edctor Lidelof en Inglaterra, Piotr Zielinski en Italia)\u00a0que se vio a importantes\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/martin-terrier.jpg?fit=679%2C399&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10879,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/30\/ex-estrella-de-la-nba-afirma-tener-una-lista-de-cientos-de-atletas-vacunados-que-han-caido-muertos-en-el-campo\/","url_meta":{"origin":11675,"position":4},"title":"Ex estrella de la NBA afirma tener una lista de cientos de atletas vacunados que han ca\u00eddo muertos en el campo","date":"30 de marzo de 2022","format":false,"excerpt":"El armador de\u00a0los Brooklyn Nets,\u00a0Kyrie Irving, y el\u00a0mariscal de campo de los\u00a0Green Bay Packers,\u00a0Aaron Rodgers, son dos de las personas m\u00e1s notables del mundo que a\u00fan no han recibido la vacuna COVID-19.\u00a0Ambas estrellas han recibido muchas cr\u00edticas de quienes apoyan la vacuna y tambi\u00e9n han recibido mucho apoyo de quienes\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/John-Stockton-NBA.webp?fit=960%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":646,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/22\/israel-lanzo-su-primera-nave-que-se-posara-en-la-luna\/","url_meta":{"origin":11675,"position":5},"title":"Israel lanz\u00f3 su primera nave que se posar\u00e1 en la Luna","date":"22 de febrero de 2019","format":false,"excerpt":"La primera nave espacial interplanetaria no tripulada de Israel se lanz\u00f3 este jueves por la noche en una misi\u00f3n lunar hist\u00f3rica desde Cabo Ca\u00f1averal, en Florida, EEUU. Se trata del lander lunar rob\u00f3tico que despeg\u00f3 sobre un cohete Falcon 9 de la empresa SpaceX a las 22:45 hora argentina, iniciando\u2026","rel":"","context":"En \u00abCiencia y Tecnolog\u00eda\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/lanzamiento-mision-israeli-luna.jpg?fit=660%2C421&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1728,"user_id":41,"is_guest":0,"slug":"acharlan","display_name":"Arthur Charlan","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Arthur-charlam.jpg?fit=96%2C96&ssl=1","first_name":"Arthur","last_name":"Charlan","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/11675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=11675"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/11675\/revisions"}],"predecessor-version":[{"id":11682,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/11675\/revisions\/11682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/11109"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=11675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=11675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=11675"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=11675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}