{"id":1141,"date":"2019-05-12T20:19:00","date_gmt":"2019-05-12T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1141"},"modified":"2021-02-20T17:58:10","modified_gmt":"2021-02-20T21:58:10","slug":"el-marketing-de-la-desgracia","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/","title":{"rendered":"El \u00abMarketing de la desgracia\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Pero en este caso, el marketing del gobierno nacional, no se hizo en base a una desgracia personal, sino a una desgracia de su pueblo. El caso de la ciudad de Pilar, deber\u00e1 ser considerado de cara al futuro, como una clara muestra de lo que no hay que hacer en pol\u00edtica. El mundo cambi\u00f3, trajo las redes sociales y, con ellas, el escrache inmediato a quienes quieren tomar a la ciudadan\u00eda como idiotas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puntualmente hablo del video que \u00abaccidentalmente\u00bb publico en su Instagram Marly Figueredo, pieza clave en el entorno m\u00e1s cercano al presidente Abdo, donde el Intendente de la ciudad de Pilar, Alfredo \u00abChulo\u00bb Stete, les dicta el discurso que tienen que decir al momento de llegar a la zona afectada:  \u201cEs que el muro de Pilar se va a hacer, y se van a calmar, eso nom\u00e1s ten\u00e9s que decir al llegar y termin\u00f3 el problema, le dije, eso nom\u00e1s quiere escuchar la gente\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/marketing.jpg?w=740&#038;ssl=1\" alt=\"\" class=\"wp-image-1393\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien este es el aspecto m\u00e1s grave de lo sucedido ayer, existen otros \u00abdetalles\u00bb que no deben ser pasados por alto; todos los integrantes de la Oficina de la Primera Dama y de la Presidencia, buscando desesperadamente una foto con un colch\u00f3n o una frazada en la mano y, si fuera posible, abrazando a un damnificado con cara de circunstancia pero, como vemos en las fotos que acompa\u00f1an a esta nota, la verdad es otra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas herramientas con las que buscan generar empat\u00eda en la ciudadan\u00eda ya no sirven, se usaban cuando el mundo estaba dominado por los medios tradicionales y estos a su vez por la \u00abbilletera\u00bb gubernamental; hoy, en tiempo de redes sociales, todo es inmediato y no  hay margen de error, el que se equivoca&#8230; pierde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ND<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pero en este caso, el marketing del gobierno nacional, no se hizo en base a una desgracia personal, sino a una desgracia de su pueblo. El caso de la ciudad de Pilar, deber\u00e1 ser considerado de cara al futuro, como una clara muestra de lo que no hay que hacer en pol\u00edtica. El mundo cambi\u00f3, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[332,577,479,578],"ppma_author":[1065],"class_list":["post-1141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-mario-abdo","tag-marly-figueredo","tag-nd","tag-rodolfo-friedmann"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El &quot;Marketing de la desgracia&quot; - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El &quot;Marketing de la desgracia&quot; - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Pero en este caso, el marketing del gobierno nacional, no se hizo en base a una desgracia personal, sino a una desgracia de su pueblo. El caso de la ciudad de Pilar, deber\u00e1 ser considerado de cara al futuro, como una clara muestra de lo que no hay que hacer en pol\u00edtica. El mundo cambi\u00f3, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-12T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-20T21:58:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/abdo-en-pilar.gif?fit=1024%2C683&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Nicol\u00e1s D\u00b4Ursi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/NicoDursi\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicol\u00e1s D\u00b4Ursi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/\"},\"author\":{\"name\":\"Nicol\u00e1s D\u00b4Ursi\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/5f11462f4da127b423f029d0dbae9131\"},\"headline\":\"El \u00abMarketing de la desgracia\u00bb\",\"datePublished\":\"2019-05-12T20:19:00+00:00\",\"dateModified\":\"2021-02-20T21:58:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/\"},\"wordCount\":304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/abdo-en-pilar.gif?fit=1024%2C683&ssl=1\",\"keywords\":[\"mario abdo\",\"marly figueredo\",\"ND\",\"rodolfo friedmann\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/\",\"name\":\"El \\\"Marketing de la desgracia\\\" - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/abdo-en-pilar.gif?fit=1024%2C683&ssl=1\",\"datePublished\":\"2019-05-12T20:19:00+00:00\",\"dateModified\":\"2021-02-20T21:58:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/abdo-en-pilar.gif?fit=1024%2C683&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/abdo-en-pilar.gif?fit=1024%2C683&ssl=1\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/12\\\/el-marketing-de-la-desgracia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El \u00abMarketing de la desgracia\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/5f11462f4da127b423f029d0dbae9131\",\"name\":\"Nicol\u00e1s D\u00b4Ursi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/nicolas-dursi.jpg?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/nicolas-dursi.jpg?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/nicolas-dursi.jpg?fit=96%2C96&ssl=1\",\"caption\":\"Nicol\u00e1s D\u00b4Ursi\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/NicoDursi\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/ndursi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El \"Marketing de la desgracia\" - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/","og_locale":"es_ES","og_type":"article","og_title":"El \"Marketing de la desgracia\" - Informatepy","og_description":"Pero en este caso, el marketing del gobierno nacional, no se hizo en base a una desgracia personal, sino a una desgracia de su pueblo. El caso de la ciudad de Pilar, deber\u00e1 ser considerado de cara al futuro, como una clara muestra de lo que no hay que hacer en pol\u00edtica. El mundo cambi\u00f3, [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/","og_site_name":"Informatepy","article_published_time":"2019-05-12T20:19:00+00:00","article_modified_time":"2021-02-20T21:58:10+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/abdo-en-pilar.gif?fit=1024%2C683&ssl=1","type":"image\/gif"}],"author":"Nicol\u00e1s D\u00b4Ursi","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/NicoDursi","twitter_misc":{"Escrito por":"Nicol\u00e1s D\u00b4Ursi","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/"},"author":{"name":"Nicol\u00e1s D\u00b4Ursi","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/5f11462f4da127b423f029d0dbae9131"},"headline":"El \u00abMarketing de la desgracia\u00bb","datePublished":"2019-05-12T20:19:00+00:00","dateModified":"2021-02-20T21:58:10+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/"},"wordCount":304,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/abdo-en-pilar.gif?fit=1024%2C683&ssl=1","keywords":["mario abdo","marly figueredo","ND","rodolfo friedmann"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/","url":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/","name":"El \"Marketing de la desgracia\" - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/abdo-en-pilar.gif?fit=1024%2C683&ssl=1","datePublished":"2019-05-12T20:19:00+00:00","dateModified":"2021-02-20T21:58:10+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/abdo-en-pilar.gif?fit=1024%2C683&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/abdo-en-pilar.gif?fit=1024%2C683&ssl=1","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/05\/12\/el-marketing-de-la-desgracia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"El \u00abMarketing de la desgracia\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/5f11462f4da127b423f029d0dbae9131","name":"Nicol\u00e1s D\u00b4Ursi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","caption":"Nicol\u00e1s D\u00b4Ursi"},"sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/NicoDursi"],"url":"https:\/\/informatepy.com\/2021\/author\/ndursi\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/abdo-en-pilar.gif?fit=1024%2C683&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":8883,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/18\/rolfi-y-marly-eligen-hacer-turismo-interno\/","url_meta":{"origin":1141,"position":0},"title":"Rolfi y Marly \u00abeligen\u00bb hacer turismo interno","date":"18 de diciembre de 2021","format":false,"excerpt":"El programa period\u00edstico \"Cuarto Intermedio\" inform\u00f3 a trav\u00e9s de sus redes sociales que, a pedido del fiscal de la causa, Osmar Leal, el juez a cargo, Jos\u00e9 Delmas, deneg\u00f3 el pedido de autorizaci\u00f3n para salir del pa\u00eds de Marly Figueredo. Figueredo, hab\u00eda solicitado permiso para viajar a los Estados Unidos\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/marly-y-rodolfo-lujo.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1388,"url":"https:\/\/informatepy.com\/2021\/2019\/08\/01\/marly-lo-hizo-de-nuevo\/","url_meta":{"origin":1141,"position":1},"title":"Marly lo hizo de nuevo","date":"1 de agosto de 2019","format":false,"excerpt":"Casi como si ese fuera su trabajo, Marly lo volvi\u00f3 a hacer, \u00bfQu\u00e9 cosa? quedar en rid\u00edculo, obviamente. Esta vez, no conforme con el desafortunado Twet de anoche, donde anunciaba que hab\u00edan salido de los \"cuarteles\", hoy, luego de las disculpas p\u00fablicas del presidente Mario Abdo, lanz\u00f3 un nuevo y\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/marly.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2117,"url":"https:\/\/informatepy.com\/2021\/2020\/08\/14\/hermano-de-marly-figueredo-no-se-hace-cargo-de-grave-accidente-de-transito-denuncian\/","url_meta":{"origin":1141,"position":2},"title":"Hermano de Marly Figueredo no se hace cargo de grave accidente de tr\u00e1nsito, denuncian","date":"14 de agosto de 2020","format":false,"excerpt":"La ciudadana Susana Jara L\u00f3pez denunci\u00f3 p\u00fablicamente a Marcos Figueredo, de 23 a\u00f1os, hermano menor de la exmodelo Marly Figueredo, por no hacerse cargo de un grave accidente de tr\u00e1nsito causado por el joven. El hecho ocurri\u00f3 a las 12:30 del 23 de mayo del 2020, sobre las calles Fulgencio\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/accidente-hermano-mary-figueredo.jpg?fit=1016%2C494&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6163,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/04\/una-mas-y-van-suspenden-preliminar-de-friedmann-y-marly\/","url_meta":{"origin":1141,"position":3},"title":"Una m\u00e1s y van&#8230;: Suspenden preliminar de Friedmann y Marly","date":"4 de agosto de 2021","format":false,"excerpt":"Esta ma\u00f1ana se produjo un nuevo intento de realizar la audiencia preliminar para Rodolfo Friedmann, su esposa Marly Figueredo y otros procesados, en la causa que investiga el negociado con el almuerzo escolar en el Departamento del Guair\u00e1, durante el per\u00edodo en el que el legislador de hecho era gobernador.\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/Marly-Figueredo-y-Rodolfo-Friedmann.jpg?fit=660%2C330&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5498,"url":"https:\/\/informatepy.com\/2021\/2021\/06\/28\/fiscalia-acusa-a-friedmann-y-marly-por-lavado-de-dinero-y-otros-delitos\/","url_meta":{"origin":1141,"position":4},"title":"Fiscal\u00eda acusa a Friedmann y Marly por lavado de dinero y otros delitos","date":"28 de junio de 2021","format":false,"excerpt":"El fiscal Osmar Legal, de la Unidad Especializada en Delitos Econ\u00f3micos y Anticorrupci\u00f3n, present\u00f3 acusaci\u00f3n contra Rodolfo Max Friedmann Alfaro, su esposa la exmodelo Marly Figueredo y otras personas por varios delitos cometidos durante su gesti\u00f3n al frente de la Gobernaci\u00f3n del Guair\u00e1 a trav\u00e9s de una empresa suya.","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/marly-y-rodolfo-a-pie.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5822,"url":"https:\/\/informatepy.com\/2021\/2021\/07\/16\/caso-merienda-escolar-sin-desafuero-de-diputado-no-puede-avanzar-proceso-de-investigacion\/","url_meta":{"origin":1141,"position":5},"title":"Caso merienda escolar: sin desafuero de diputado no puede avanzar proceso de investigaci\u00f3n","date":"16 de julio de 2021","format":false,"excerpt":"Sobre la acusaci\u00f3n al senador Rodolfo Friedmann y su esposa Marly Figueredo, por lavado de dinero, administraci\u00f3n en provecho propio, cohecho pasivo agravado y asociaci\u00f3n criminal, el fiscal Osmar Legal, cont\u00f3 que el obst\u00e1culo sigue siendo con relaci\u00f3n al diputado Ever Noguera, quien no fue desaforado en la causa y\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/FRIEDMANN-NOGUERA-1.jpg?fit=800%2C500&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1065,"user_id":5,"is_guest":0,"slug":"ndursi","display_name":"Nicol\u00e1s D\u00b4Ursi","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","first_name":"Nicol\u00e1s","last_name":"D\u00b4Ursi","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1141"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1141\/revisions"}],"predecessor-version":[{"id":2965,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1141\/revisions\/2965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1142"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1141"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}