{"id":1113,"date":"2019-05-03T20:19:00","date_gmt":"2019-05-03T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1113"},"modified":"2021-02-20T17:58:38","modified_gmt":"2021-02-20T21:58:38","slug":"zapag-hagase-cargo","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/","title":{"rendered":"Zapag, h\u00e1gase cargo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Muchos se habl\u00f3 los \u00faltimos d\u00edas del error de la terna\narbitral comandada por Aquino, producto del ins\u00f3lito gol convalidado a San\nLorenzo, es verdad, es una risa que den ese gol que claramente pic\u00f3 afuera.\nAhora, \u00bfes la primera vez que los \u00e1rbitros paraguayos se equivocan? \u00bfSiempre es\nCerro porte\u00f1o el perjudicado por estas acciones?, \u00bfEl penal no cobrado a favor\nde San Lorenzo en el primer tiempo es un error y el gol mal convalidado una\nestafa?; si son intelectualmente honestos al momento de responder, si lo hacen\nsin fanatismo, se van a dar cuenta que el problema aqu\u00ed no es una supuesta persecuci\u00f3n\ncontra el equipo de Barrio Obrero, sino que los \u00e1rbitros paraguayos son\nrealmente horribles (t\u00e9cnicamente) y est\u00e1n deficientemente preparados en el\naspecto f\u00edsico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta situaci\u00f3n, obviamente no exime al \u00e1rbitro de su error, pero hace que descartemos la posible \u201cConspiraci\u00f3n\u201d que menciona Zapag. A General D\u00edaz en un mismo encuentro no le convalidaron dos, no uno, sino dos goles l\u00edcitos. Tampoco olvidemos lo ocurrido entre Cerro Porte\u00f1o y General D\u00edaz, hace poco m\u00e1s de un a\u00f1o; donde un desastroso arbitraje provoc\u00f3 que el Presidente de General D\u00edaz manifestara que: <em>\u201cMandaron a D\u00edaz de Vivar para revivir a un muerto. Favoreci\u00f3 claramente a Cerro\u201d, \u201cApareci\u00f3 porque ten\u00eda que vivir a los cebollitas\u201d<\/em>; ese d\u00eda, nadie, salvo Gonz\u00e1lez, se quej\u00f3; no se derramaron r\u00edos de tinta ni se pidi\u00f3 la cabeza de los \u00e1rbitros, ni de Elizondo ni mucho menos de Harrison.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/escrache-harrison.jpeg?w=740&#038;ssl=1\" alt=\"\" class=\"wp-image-1343\" data-recalc-dims=\"1\"\/><figcaption>Escrache en la casa del Presidente de la APF &#8211; Foto Gentileza<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante lo antedicho, finalmente no son los errores\narbitrales lo que preocupan a quien esto escribe, si no la teatralizaci\u00f3n\nposterior de los dirigentes de cerro, quienes, una vez m\u00e1s, act\u00faan de manera\nirracional (y deliberada dir\u00eda yo) como factores generadores de violencia; ya\nque luego de las manifestaciones p\u00fablicas de Zapag, se dieron una serie de\nhechos que deber\u00edan ser los que realmente nos ocupen: Las amenazas a la terna\narbitral y las manifestaciones frente a la casa del Presidente de la Asociaci\u00f3n\nParaguaya de Futbol. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tristemente, muchos dirigentes de Cerro nos vienen\nacostumbrando en los \u00faltimos tiempos a este tipo de manifestaciones p\u00fablicas,\ndonde exacerban a su p\u00fablico con, a mi criterio, la clara intenci\u00f3n de tapar\nsus propios errores:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00bfTrajeron refuerzos al nivel que requer\u00eda la\nsituaci\u00f3n del club?, No<\/li><li>\u00bfContrataron un cuerpo t\u00e9cnico de nivel?, No<\/li><li>\u00bfMantienen al club con una deuda millonaria por\nla nueva olla?, Si<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Estos errores, graves para un club del fuste de Cerro\nPorte\u00f1o, denotan cierta improvisaci\u00f3n por parte de una dirigencia inmersa en un\nfutbol cada d\u00eda m\u00e1s competitivo, donde no alcanza con el marketing de LNO, ni\nCerruber ni nada de eso; eso no tapa que el hincha quiere logros deportivos, despu\u00e9s\nde todo, de eso se trata este deporte, de ganar. El marketing de la pasi\u00f3n\npuede ser efectivo muchas veces para tapar la falta de logros, pero tarde o\ntemprano, la frustraci\u00f3n de no alcanzarlos va a salir a flote y las cosas se\nvan a poner feas. Por eso, quisiera sugerirle a los hermanos Zapag que\nabandonen la pol\u00edtica de victimizarse, que busquen mejorar los resultados\ndeportivos en una instituci\u00f3n del tama\u00f1o de Cerro Porte\u00f1o; y eso, solo lo van a\nalcanzar, si dejan de ver fantasmas donde no los hay, porque cuando la gente se\ncanse, la violencia que se va a generar va a ser toda responsabilidad suya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zapag, h\u00e1gase cargo; porque mientras usted no lo hace, su cl\u00e1sico rival le sigue sacando ventaja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ND<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muchos se habl\u00f3 los \u00faltimos d\u00edas del error de la terna arbitral comandada por Aquino, producto del ins\u00f3lito gol convalidado a San Lorenzo, es verdad, es una risa que den ese gol que claramente pic\u00f3 afuera. Ahora, \u00bfes la primera vez que los \u00e1rbitros paraguayos se equivocan? \u00bfSiempre es Cerro porte\u00f1o el perjudicado por estas [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1114,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[183],"tags":[186,187,252,479,430,445],"ppma_author":[1065],"class_list":["post-1113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-apf","tag-cerro-porteno","tag-futbol-paraguayo","tag-nd","tag-raul-zapag","tag-zapag"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zapag, h\u00e1gase cargo - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zapag, h\u00e1gase cargo - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Muchos se habl\u00f3 los \u00faltimos d\u00edas del error de la terna arbitral comandada por Aquino, producto del ins\u00f3lito gol convalidado a San Lorenzo, es verdad, es una risa que den ese gol que claramente pic\u00f3 afuera. Ahora, \u00bfes la primera vez que los \u00e1rbitros paraguayos se equivocan? \u00bfSiempre es Cerro porte\u00f1o el perjudicado por estas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-03T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-20T21:58:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/raul-zapag.jpeg?fit=730%2C486&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicol\u00e1s D\u00b4Ursi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/NicoDursi\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicol\u00e1s D\u00b4Ursi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/\"},\"author\":{\"name\":\"Nicol\u00e1s D\u00b4Ursi\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/5f11462f4da127b423f029d0dbae9131\"},\"headline\":\"Zapag, h\u00e1gase cargo\",\"datePublished\":\"2019-05-03T20:19:00+00:00\",\"dateModified\":\"2021-02-20T21:58:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/\"},\"wordCount\":641,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/raul-zapag.jpeg?fit=730%2C486&ssl=1\",\"keywords\":[\"apf\",\"cerro porte\u00f1o\",\"futbol paraguayo\",\"ND\",\"raul zapag\",\"zapag\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/\",\"name\":\"Zapag, h\u00e1gase cargo - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/raul-zapag.jpeg?fit=730%2C486&ssl=1\",\"datePublished\":\"2019-05-03T20:19:00+00:00\",\"dateModified\":\"2021-02-20T21:58:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/raul-zapag.jpeg?fit=730%2C486&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/raul-zapag.jpeg?fit=730%2C486&ssl=1\",\"width\":730,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/05\\\/03\\\/zapag-hagase-cargo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zapag, h\u00e1gase cargo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/5f11462f4da127b423f029d0dbae9131\",\"name\":\"Nicol\u00e1s D\u00b4Ursi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/nicolas-dursi.jpg?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/nicolas-dursi.jpg?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/nicolas-dursi.jpg?fit=96%2C96&ssl=1\",\"caption\":\"Nicol\u00e1s D\u00b4Ursi\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/NicoDursi\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/ndursi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zapag, h\u00e1gase cargo - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/","og_locale":"es_ES","og_type":"article","og_title":"Zapag, h\u00e1gase cargo - Informatepy","og_description":"Muchos se habl\u00f3 los \u00faltimos d\u00edas del error de la terna arbitral comandada por Aquino, producto del ins\u00f3lito gol convalidado a San Lorenzo, es verdad, es una risa que den ese gol que claramente pic\u00f3 afuera. Ahora, \u00bfes la primera vez que los \u00e1rbitros paraguayos se equivocan? \u00bfSiempre es Cerro porte\u00f1o el perjudicado por estas [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/","og_site_name":"Informatepy","article_published_time":"2019-05-03T20:19:00+00:00","article_modified_time":"2021-02-20T21:58:38+00:00","og_image":[{"width":730,"height":486,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/raul-zapag.jpeg?fit=730%2C486&ssl=1","type":"image\/jpeg"}],"author":"Nicol\u00e1s D\u00b4Ursi","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/NicoDursi","twitter_misc":{"Escrito por":"Nicol\u00e1s D\u00b4Ursi","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/"},"author":{"name":"Nicol\u00e1s D\u00b4Ursi","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/5f11462f4da127b423f029d0dbae9131"},"headline":"Zapag, h\u00e1gase cargo","datePublished":"2019-05-03T20:19:00+00:00","dateModified":"2021-02-20T21:58:38+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/"},"wordCount":641,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/raul-zapag.jpeg?fit=730%2C486&ssl=1","keywords":["apf","cerro porte\u00f1o","futbol paraguayo","ND","raul zapag","zapag"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/","url":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/","name":"Zapag, h\u00e1gase cargo - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/raul-zapag.jpeg?fit=730%2C486&ssl=1","datePublished":"2019-05-03T20:19:00+00:00","dateModified":"2021-02-20T21:58:38+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/raul-zapag.jpeg?fit=730%2C486&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/raul-zapag.jpeg?fit=730%2C486&ssl=1","width":730,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/05\/03\/zapag-hagase-cargo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Zapag, h\u00e1gase cargo"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/5f11462f4da127b423f029d0dbae9131","name":"Nicol\u00e1s D\u00b4Ursi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","caption":"Nicol\u00e1s D\u00b4Ursi"},"sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/NicoDursi"],"url":"https:\/\/informatepy.com\/2021\/author\/ndursi\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/raul-zapag.jpeg?fit=730%2C486&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1177,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/21\/cerro-porteno-y-una-autocritica-que-se-demora\/","url_meta":{"origin":1113,"position":0},"title":"Cerro Porte\u00f1o y una autocr\u00edtica que se demora","date":"21 de mayo de 2019","format":false,"excerpt":"Barras, falta de logros deportivos, errores dirigenciales graves y una larga lista de etc\u00e9teras hacen que se f\u00e1cil realizar diagn\u00f3sticos sobre la realidad de un gran del futbol paraguayo como lo es Cerro Porte\u00f1o. De un tiempo a esta parte, uno de los grandes del futbol paraguayo no para de\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/cerristas.jpg?fit=712%2C678&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":746,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/27\/zapag-sale-a-respaldar-a-jubero-ante-los-rumores\/","url_meta":{"origin":1113,"position":1},"title":"Zapag sale a respaldar a Jubero ante los rumores","date":"27 de febrero de 2019","format":false,"excerpt":"Cerro Porte\u00f1o\u00a0no levanta cabeza. El Cicl\u00f3n de Barrio Obrero no pudo en el estadio Erico Galeano y cay\u00f3 derrotado este martes por 2-1 ante la revelaci\u00f3n San Lorenzo por la octava fecha del torneo Apertura 2019. Tras el partido,\u00a0Ra\u00fal Zapag, mandam\u00e1s de la instituci\u00f3n azulgrana, dio total respaldo al entrenador\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nani-zapag-jubero.jpeg?fit=730%2C486&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1920,"url":"https:\/\/informatepy.com\/2021\/2020\/04\/22\/se-agrava-la-crisis-en-cerro-porteno\/","url_meta":{"origin":1113,"position":2},"title":"Se agrava la crisis en Cerro Porte\u00f1o","date":"22 de abril de 2020","format":false,"excerpt":"Las declaraciones de Mario Grana a un medio radial, donde manifest\u00f3 que con kits de alimentos ellos no pod\u00edan pagar los servicios b\u00e1sicos como luz, agua y dem\u00e1s, calaron hondo en la directiva azulgrana, al punto que se decidi\u00f3 desvincular al formador de inferiores de la instituci\u00f3n. Esta destituci\u00f3n de\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/mario-grana-CCP.jpg?fit=600%2C379&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1459,"url":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/","url_meta":{"origin":1113,"position":3},"title":"Cerro perjudica a Cerro","date":"28 de agosto de 2019","format":false,"excerpt":"Antes de que arranquen (y me gustar\u00eda que se los ahorraran) con los insultos, he de decirles que quien esto escribe es hincha del Club Cerro Porte\u00f1o. Dicho hecho, avancemos. Hoy vivimos, gracias a un periodista, una situaci\u00f3n ins\u00f3lita que solo encuentra su arraigo en la retroalimentaci\u00f3n del hincha cerrista\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/de-la-cruz-donofrio-pipino.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1664,"url":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/","url_meta":{"origin":1113,"position":4},"title":"Se calienta la interna cerrista","date":"4 de diciembre de 2019","format":false,"excerpt":"Las cosas no est\u00e1n nada bien en Cerro Porte\u00f1o luego de haber perdido el cl\u00e1sico con Olimpia y la posibilidad de acceder en forma directa a la Copa Libertadores. Apenas terminado el encuentro con Libertad, se viraliz\u00f3 el Hashtag en las redes sociales #RechazoGestionZapag, donde los hinchas del conjunto azulgrana\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/rechazo-gestion-zapag.jpg?fit=1200%2C751&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1108,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/02\/tras-el-escandalo-hablo-el-arbitro-cristian-aquino\/","url_meta":{"origin":1113,"position":5},"title":"Tras el esc\u00e1ndalo, habl\u00f3 el \u00e1rbitro Cristian Aquino","date":"2 de mayo de 2019","format":false,"excerpt":"Como se sabe, Cerro Porte\u00f1o y Sportivo San Lorenzo igualaron a un gol, en un encuentro v\u00e1lido por la fecha 19 del torneo Apertura. El partido estuvo cargado por las pol\u00e9micas ya sabidas. Llegando a la comisar\u00eda cuarta para hacer la denuncia, posterior al partido, habl\u00f3 el \u00e1rbitro, y sus\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/cerro-san-lorenzo.jpg?fit=1200%2C592&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1065,"user_id":5,"is_guest":0,"slug":"ndursi","display_name":"Nicol\u00e1s D\u00b4Ursi","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","first_name":"Nicol\u00e1s","last_name":"D\u00b4Ursi","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1113"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1113\/revisions"}],"predecessor-version":[{"id":2982,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1113\/revisions\/2982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1114"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1113"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}