{"id":1102,"date":"2019-04-30T20:19:00","date_gmt":"2019-04-30T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1102"},"modified":"2021-02-09T00:59:54","modified_gmt":"2021-02-09T00:59:54","slug":"levantamiento-militar-en-venezuela","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/","title":{"rendered":"Levantamiento militar en Venezuela"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El opositor venezolano&nbsp;Leopoldo L\u00f3pez&nbsp;fue liberado este martes en Caracas por fuerzas militares antichavistas. Tras su salida, el dirigente pol\u00edtico llam\u00f3 a movilizarse hacia las unidades militares para&nbsp;lograr la ca\u00edda del gobierno&nbsp;de&nbsp;Nicol\u00e1s Maduro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abVenezuela: ha iniciado la&nbsp;fase definitiva para el cese de la usurpaci\u00f3n, la Operaci\u00f3n Libertad. He sido liberado por militares a la orden de la Constituci\u00f3n y del Presidente Guaid\u00f3. Estoy en la Base La Carlota.&nbsp;Todos a movilizarnos. Es hora de conquistar la Libertad. Fuerza y Fe\u00bb, escribi\u00f3 L\u00f3pez en su cuenta en Twitter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la Asamblea Nacional venezolana,&nbsp;Juan Guaid\u00f3&nbsp;(reconocido como presidente interino por medio centenar de pa\u00edses), apareci\u00f3 junto a L\u00f3pez y a un grupo de militares en un video en el que llam\u00f3 al resto de las fuerzas y a la poblaci\u00f3n civil a&nbsp;salir a las calles&nbsp;en busca del \u00abcese definitivo\u00bb de la \u00abusurpaci\u00f3n\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Pueblo de Venezuela, es necesario que salgamos juntos a la calle, a respaldar a las fuerzas democr\u00e1ticas y a recuperar nuestra libertad. Organizados y juntos movil\u00edcense a las principales unidades militares. Pueblo de Caracas, todos a la Carlota.<\/p>&mdash; Juan Guaid\u00f3 (@jguaido) <a href=\"https:\/\/twitter.com\/jguaido\/status\/1123164653704577024?ref_src=twsrc%5Etfw\">April 30, 2019<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abPueblo de Venezuela, es necesario que salgamos juntos a la calle, a respaldar a las fuerzas democr\u00e1ticas y a recuperar nuestra libertad. Organizados y juntosmovil\u00edcense a las principales unidades militares. Pueblo de Caracas, todos a la Carlota\u00bb, inst\u00f3 Guaid\u00f3 tambi\u00e9n en Twitter. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Venezuela: ha iniciado la fase definitiva para el cese de  la usurpaci\u00f3n, la Operaci\u00f3n Libertad. He sido liberado por militares a la orden de la Constituci\u00f3n y del Presidente Guaid\u00f3. Estoy en la Base La Carlota. Todos a movilizarnos. Es hora de conquistar la Libertad. Fuerza y Fe <a href=\"https:\/\/t.co\/Awm6P09ZM0\">pic.twitter.com\/Awm6P09ZM0<\/a><\/p>&mdash; Leopoldo L\u00f3pez (@leopoldolopez) <a href=\"https:\/\/twitter.com\/leopoldolopez\/status\/1123169379661819904?ref_src=twsrc%5Etfw\">April 30, 2019<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abPueblo de Venezuela vamos a la calle, Fuerza Armada Nacional a continuar el despliegue hasta que consolidemos el fin de la usurpaci\u00f3n que ya es irreversible\u00bb, agreg\u00f3. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El opositor venezolano&nbsp;Leopoldo L\u00f3pez&nbsp;fue liberado este martes en Caracas por fuerzas militares antichavistas. Tras su salida, el dirigente pol\u00edtico llam\u00f3 a movilizarse hacia las unidades militares para&nbsp;lograr la ca\u00edda del gobierno&nbsp;de&nbsp;Nicol\u00e1s Maduro. \u00abVenezuela: ha iniciado la&nbsp;fase definitiva para el cese de la usurpaci\u00f3n, la Operaci\u00f3n Libertad. He sido liberado por militares a la orden de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[173],"tags":[273,274,174,211],"ppma_author":[1039],"class_list":["post-1102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-crisis-venezuela","tag-juan-guaido","tag-leopoldo-lopez","tag-nicolas-maduro"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Levantamiento militar en Venezuela - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Levantamiento militar en Venezuela - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El opositor venezolano&nbsp;Leopoldo L\u00f3pez&nbsp;fue liberado este martes en Caracas por fuerzas militares antichavistas. Tras su salida, el dirigente pol\u00edtico llam\u00f3 a movilizarse hacia las unidades militares para&nbsp;lograr la ca\u00edda del gobierno&nbsp;de&nbsp;Nicol\u00e1s Maduro. \u00abVenezuela: ha iniciado la&nbsp;fase definitiva para el cese de la usurpaci\u00f3n, la Operaci\u00f3n Libertad. He sido liberado por militares a la orden de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-30T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-09T00:59:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Juan-Guaido-leopoldo-lopez.jpg?fit=611%2C308&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"611\" \/>\n\t<meta property=\"og:image:height\" content=\"308\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Levantamiento militar en Venezuela\",\"datePublished\":\"2019-04-30T20:19:00+00:00\",\"dateModified\":\"2021-02-09T00:59:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/\"},\"wordCount\":260,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Juan-Guaido-leopoldo-lopez.jpg?fit=611%2C308&ssl=1\",\"keywords\":[\"crisis venezuela\",\"juan guaido\",\"leopoldo lopez\",\"nicolas maduro\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/\",\"name\":\"Levantamiento militar en Venezuela - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Juan-Guaido-leopoldo-lopez.jpg?fit=611%2C308&ssl=1\",\"datePublished\":\"2019-04-30T20:19:00+00:00\",\"dateModified\":\"2021-02-09T00:59:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Juan-Guaido-leopoldo-lopez.jpg?fit=611%2C308&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Juan-Guaido-leopoldo-lopez.jpg?fit=611%2C308&ssl=1\",\"width\":611,\"height\":308},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/30\\\/levantamiento-militar-en-venezuela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Levantamiento militar en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Levantamiento militar en Venezuela - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/","og_locale":"es_ES","og_type":"article","og_title":"Levantamiento militar en Venezuela - Informatepy","og_description":"El opositor venezolano&nbsp;Leopoldo L\u00f3pez&nbsp;fue liberado este martes en Caracas por fuerzas militares antichavistas. Tras su salida, el dirigente pol\u00edtico llam\u00f3 a movilizarse hacia las unidades militares para&nbsp;lograr la ca\u00edda del gobierno&nbsp;de&nbsp;Nicol\u00e1s Maduro. \u00abVenezuela: ha iniciado la&nbsp;fase definitiva para el cese de la usurpaci\u00f3n, la Operaci\u00f3n Libertad. He sido liberado por militares a la orden de [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/","og_site_name":"Informatepy","article_published_time":"2019-04-30T20:19:00+00:00","article_modified_time":"2021-02-09T00:59:54+00:00","og_image":[{"width":611,"height":308,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Juan-Guaido-leopoldo-lopez.jpg?fit=611%2C308&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Levantamiento militar en Venezuela","datePublished":"2019-04-30T20:19:00+00:00","dateModified":"2021-02-09T00:59:54+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/"},"wordCount":260,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Juan-Guaido-leopoldo-lopez.jpg?fit=611%2C308&ssl=1","keywords":["crisis venezuela","juan guaido","leopoldo lopez","nicolas maduro"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/","url":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/","name":"Levantamiento militar en Venezuela - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Juan-Guaido-leopoldo-lopez.jpg?fit=611%2C308&ssl=1","datePublished":"2019-04-30T20:19:00+00:00","dateModified":"2021-02-09T00:59:54+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Juan-Guaido-leopoldo-lopez.jpg?fit=611%2C308&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Juan-Guaido-leopoldo-lopez.jpg?fit=611%2C308&ssl=1","width":611,"height":308},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/30\/levantamiento-militar-en-venezuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Levantamiento militar en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Juan-Guaido-leopoldo-lopez.jpg?fit=611%2C308&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":795,"url":"https:\/\/informatepy.com\/2021\/2019\/03\/05\/se-acerca-el-final-del-regimen-chavista\/","url_meta":{"origin":1102,"position":0},"title":"\u00bfSe acerca el final del r\u00e9gimen chavista?","date":"5 de marzo de 2019","format":false,"excerpt":"Los \u00faltimos d\u00edas en la regi\u00f3n han sido bastante agitados detr\u00e1s de la situaci\u00f3n venezolana, los distintos gobiernos han ido moviendo sus piezas detr\u00e1s de la estrategia de Juan Guaid\u00f3; dando un paso importante ayer con la llegada del presidente encargado al aeropuerto de Maiquet\u00eda. Pudimos vislumbrar el claro debilitamiento\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/maduro-estetica-comunista.jpg?fit=996%2C662&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1148,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/14\/juan-guaido-denuncia-que-el-regimen-de-maduro-quiere-cerrar-el-parlamento\/","url_meta":{"origin":1102,"position":1},"title":"Juan Guaid\u00f3 denuncia que el r\u00e9gimen de Maduro quiere cerrar el Parlamento","date":"14 de mayo de 2019","format":false,"excerpt":"El Parlamento venezolano debi\u00f3 aplazar para el mi\u00e9rcoles 15 de mayo su sesi\u00f3n ordinaria luego de que se desplegara un fuerte operativo policial en los alrededores del Palacio Legislativo por una supuesta amenaza de bomba, informaron fuentes de la Asamblea.\u00a0\"Ocuparon militarmente el Parlamento\", denunci\u00f3 Guaid\u00f3. \"Ma\u00f1ana hay sesi\u00f3n, no tenemos\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Maduro-Guaido.jpg?fit=673%2C419&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":922,"url":"https:\/\/informatepy.com\/2021\/2020\/03\/21\/maduro-detuvo-al-jefe-de-despacho-de-juan-guaido\/","url_meta":{"origin":1102,"position":2},"title":"Maduro detuvo al Jefe de Despacho de Juan Guaid\u00f3","date":"21 de marzo de 2020","format":false,"excerpt":"El r\u00e9gimen de Nicol\u00e1s Maduro detuvo esta madrugada a Roberto Marrero, jefe del despacho del presidente interino Juan Guaid\u00f3. Adem\u00e1s, allan\u00f3 la casa del diputado\u00a0Sergio Vergara. \"La dictadura perdi\u00f3 la ofensiva pol\u00edtica desde hace tiempo, y solo le queda la represi\u00f3n\", expres\u00f3 en Twitter el legislador Freddy Guevara. Guevara hab\u00eda\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/roberto-marrero-jefe-despacho-guaido-1.jpg?fit=630%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":497,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/11\/juan-guaido-confirmo-que-ya-fue-entregado-el-primer-cargamento-de-ayuda-humanitaria-en-venezuela\/","url_meta":{"origin":1102,"position":3},"title":"Juan Guaid\u00f3 confirm\u00f3 que ya fue entregado el primer cargamento de ayuda humanitaria en Venezuela","date":"11 de febrero de 2019","format":false,"excerpt":"Juan Guaid\u00f3 confirm\u00f3 este lunes que\u00a0ya fue entregado el primer cargamento de la ayuda humanitaria\u00a0que gestiona desde hace d\u00edas y que el\u00a0r\u00e9gimen de Nicol\u00e1s Maduro ha estado bloqueando. \"Cumpliendo con nuestras competencias, hoy entregamos el primer cargamento de insumos de la ayuda humanitaria a la Asociaci\u00f3n de Centros de Salud\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/juan-guaido.jpg?fit=822%2C674&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1299,"url":"https:\/\/informatepy.com\/2021\/2019\/06\/26\/juan-guaido-frustro-un-intento-de-secuestro\/","url_meta":{"origin":1102,"position":4},"title":"Juan Guaid\u00f3 frustr\u00f3 un intento de secuestro","date":"26 de junio de 2019","format":false,"excerpt":"El presidente interino de Venezuela,\u00a0Juan Guaid\u00f3, frustr\u00f3 este mi\u00e9rcoles un\u00a0intento de secuestro a su equipo\u00a0sobre una autopista en Caracas. La informaci\u00f3n la dio a conocer el\u00a0Centro de Comunicaci\u00f3n Nacional de la Presidencia Encargada del pa\u00eds caribe\u00f1o, quien public\u00f3 en Twitter: \"El presidente (E) de la Rep\u00fablica, Juan Guaid\u00f3, frustr\u00f3 intento\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/secuestro-guaido.jpg?fit=1080%2C607&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":438,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/estados-unidos-busca-que-militares-venezolanos-le-retiren-su-apoyo-a-maduro\/","url_meta":{"origin":1102,"position":5},"title":"Estados Unidos busca que militares venezolanos le retiren su apoyo a Maduro","date":"10 de febrero de 2019","format":false,"excerpt":"El gobierno de Estados Unidos estar\u00eda en contacto directo con militares venezolanos, a quienes inst\u00f3 a que retiren su apoyo al presidente Nicol\u00e1s Maduro. Seg\u00fan el diario El Nacional, basado en un informe de la agencia Reuters, las conversaciones, aunque \u201climitadas\u201d, tendr\u00edan como objetivo convencer a antiguos miembros de las\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/maduro-trump.jpg?fit=1140%2C640&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1102"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1102\/revisions"}],"predecessor-version":[{"id":2988,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1102\/revisions\/2988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1103"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1102"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}