{"id":1100,"date":"2019-04-29T20:19:00","date_gmt":"2019-04-29T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1100"},"modified":"2021-02-09T01:04:58","modified_gmt":"2021-02-09T01:04:58","slug":"se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/","title":{"rendered":"Se filtran los nombres de los periodistas de la Lista del DETAVE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los nombres que figuran en la n\u00f3mina estaban anotados de la siguiente manera:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rufo (\u00d1andut\u00ed)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Molina (periodista)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00d1andut\u00ed<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ag\u00fcero<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>V\u00edctor Pesoa<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gabi Le\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hugo Candia<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mario Bracho<\/strong><strong><br><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En algunos de los casos solo figuraba un \u00fanico pago, a diferencia de Le\u00f3n, la \u00fanica persona de la lista que ten\u00eda un desembolso constante que variaba entre los G. 600.000 y G. 800.000, siempre de acuerdo a las anotaciones filtradas del cuaderno del Gral. Ben\u00edtez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta ma\u00f1ana el ministro de la Secretar\u00eda Nacional Antidrogas (Senad), Arnaldo Giuzzio, afirm\u00f3 que el cuaderno en cuesti\u00f3n no pod\u00eda ser calificado como una agenda, pero los apuntes hac\u00edan referencia de qui\u00e9nes eran los que entregaban el dinero de los sobornos y tambi\u00e9n a qui\u00e9nes pagaban tambi\u00e9n, entre ellos se encuentran periodistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de la filtraci\u00f3n se hab\u00eda anunciado que los comunicadores citados en el cuaderno del Gral. Ben\u00edtez iban a ser citados a declarar ante la Fiscal\u00eda, para que expliquen su relaci\u00f3n con el esquema montado en Detave que captaba sobornos para permitir el contrabando de mercader\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gral. Ben\u00edtez est\u00e1 imputado, junto a seis funcionarios del Detave y un polic\u00eda, por los hechos punibles de asociaci\u00f3n criminal, cohecho pasivo agravado y contrabando.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SE DEFIENDE<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Rufo Diana, de Radio \u00d1andut\u00ed, uno de los periodistas que aparecen en&nbsp;la lista del Gral. Ram\u00f3n Ben\u00edtez, coment\u00f3 a ABC Cardinal que conoce muy poco al detenido y que particip\u00f3 de varios procedimientos desarrollados en Detave.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNosotros cumplimos la agenda que nos piden en la radio. Puedo dar fe de que ni siquiera fuimos insinuados. Ben\u00edtez nunca, ni intermediarios\u201d, sostuvo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNunca nos ofreci\u00f3 absolutamente nada; es m\u00e1s, me sorprendi\u00f3 much\u00edsimo sobre esta situaci\u00f3n porque siempre lo tuve como referente\u201d, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abYo no tengo nada que esconder, estoy a disposici\u00f3n absoluta de hablar y aclarar todas las cosas; yo, como ser humano, estoy m\u00e1s tranquilo que agua\u00bb, sostuvo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los nombres que figuran en la n\u00f3mina estaban anotados de la siguiente manera: Rufo (\u00d1andut\u00ed) Molina (periodista) \u00d1andut\u00ed Ag\u00fcero V\u00edctor Pesoa Gabi Le\u00f3n Hugo Candia Mario Bracho En algunos de los casos solo figuraba un \u00fanico pago, a diferencia de Le\u00f3n, la \u00fanica persona de la lista que ten\u00eda un desembolso constante que variaba entre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[242,559,560],"ppma_author":[1039],"class_list":["post-1100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-corrupcion","tag-detave","tag-ramon-benitez"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se filtran los nombres de los periodistas de la Lista del DETAVE - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se filtran los nombres de los periodistas de la Lista del DETAVE - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Los nombres que figuran en la n\u00f3mina estaban anotados de la siguiente manera: Rufo (\u00d1andut\u00ed) Molina (periodista) \u00d1andut\u00ed Ag\u00fcero V\u00edctor Pesoa Gabi Le\u00f3n Hugo Candia Mario Bracho En algunos de los casos solo figuraba un \u00fanico pago, a diferencia de Le\u00f3n, la \u00fanica persona de la lista que ten\u00eda un desembolso constante que variaba entre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-29T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-09T01:04:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/benotez-detavee.jpg?fit=700%2C440&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Se filtran los nombres de los periodistas de la Lista del DETAVE\",\"datePublished\":\"2019-04-29T20:19:00+00:00\",\"dateModified\":\"2021-02-09T01:04:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/\"},\"wordCount\":351,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/benotez-detavee.jpg?fit=700%2C440&ssl=1\",\"keywords\":[\"corrupcion\",\"detave\",\"ramon benitez\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/\",\"name\":\"Se filtran los nombres de los periodistas de la Lista del DETAVE - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/benotez-detavee.jpg?fit=700%2C440&ssl=1\",\"datePublished\":\"2019-04-29T20:19:00+00:00\",\"dateModified\":\"2021-02-09T01:04:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/benotez-detavee.jpg?fit=700%2C440&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/benotez-detavee.jpg?fit=700%2C440&ssl=1\",\"width\":700,\"height\":440,\"caption\":\"Ram\u00f3n Ben\u00edtez, detenido. Foto: La Naci\u00f3n.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/29\\\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se filtran los nombres de los periodistas de la Lista del DETAVE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se filtran los nombres de los periodistas de la Lista del DETAVE - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/","og_locale":"es_ES","og_type":"article","og_title":"Se filtran los nombres de los periodistas de la Lista del DETAVE - Informatepy","og_description":"Los nombres que figuran en la n\u00f3mina estaban anotados de la siguiente manera: Rufo (\u00d1andut\u00ed) Molina (periodista) \u00d1andut\u00ed Ag\u00fcero V\u00edctor Pesoa Gabi Le\u00f3n Hugo Candia Mario Bracho En algunos de los casos solo figuraba un \u00fanico pago, a diferencia de Le\u00f3n, la \u00fanica persona de la lista que ten\u00eda un desembolso constante que variaba entre [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/","og_site_name":"Informatepy","article_published_time":"2019-04-29T20:19:00+00:00","article_modified_time":"2021-02-09T01:04:58+00:00","og_image":[{"width":700,"height":440,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/benotez-detavee.jpg?fit=700%2C440&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Se filtran los nombres de los periodistas de la Lista del DETAVE","datePublished":"2019-04-29T20:19:00+00:00","dateModified":"2021-02-09T01:04:58+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/"},"wordCount":351,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/benotez-detavee.jpg?fit=700%2C440&ssl=1","keywords":["corrupcion","detave","ramon benitez"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/","url":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/","name":"Se filtran los nombres de los periodistas de la Lista del DETAVE - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/benotez-detavee.jpg?fit=700%2C440&ssl=1","datePublished":"2019-04-29T20:19:00+00:00","dateModified":"2021-02-09T01:04:58+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/benotez-detavee.jpg?fit=700%2C440&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/benotez-detavee.jpg?fit=700%2C440&ssl=1","width":700,"height":440,"caption":"Ram\u00f3n Ben\u00edtez, detenido. Foto: La Naci\u00f3n."},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/se-filtran-los-nombres-de-los-periodistas-de-la-lista-del-detave\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Se filtran los nombres de los periodistas de la Lista del DETAVE"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/benotez-detavee.jpg?fit=700%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":13209,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/09\/san-jose-es-el-campeon-de-la-liga-nacional-de-basquet\/","url_meta":{"origin":1100,"position":0},"title":"San Jos\u00e9 es el campe\u00f3n de la Liga Nacional de B\u00e1squet","date":"9 de agosto de 2022","format":false,"excerpt":"Como en los partidos anteriores en la serie, vibrantes juegos hasta el final que se resolvieron en los \u00faltimos segundos. San Jos\u00e9 se consagr\u00f3 como campe\u00f3n de la Liga Nacional de la Confederaci\u00f3n Paraguaya de B\u00e1squetbol tras vencer a Olimpia Kings en tres partidos. En un Polideportivo Le\u00f3n Condou abarrotado\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/san-jose-campeon-basquet.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":599,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/19\/miguel-marecos-cuestiona-al-ministro-petta-kits-escolares-no-son-la-unica-necesidad-del-sector-educativo\/","url_meta":{"origin":1100,"position":1},"title":"Miguel Marecos cuestiona al ministro Petta: Kits escolares no son la \u00fanica necesidad del sector educativo","date":"19 de febrero de 2019","format":false,"excerpt":"Miguel Marecos, titular del Sindicato Nacional de Directores (Sinadi), declar\u00f3 en una entrevista en Radio \u00d1andut\u00ed que la novedad en el \u00e1mbito educativo, es que los kits escolares ser\u00e1n entregados en su totalidad a m\u00e1s tardar el jueves. No obstante, dijo que este a\u00f1o contiene menos \u00fatiles. Marecos a\u00f1adi\u00f3 que\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/miguel-marecos-sindicato-directores-educacion.jpg?fit=610%2C396&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13884,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/13\/payo-afirma-que-fleitas-jaquea-a-efrain-en-las-internas-de-la-cocnertacion\/","url_meta":{"origin":1100,"position":2},"title":"Payo afirma que Fleitas jaquea a Efra\u00edn en las internas de la Concertaci\u00f3n","date":"13 de septiembre de 2022","format":false,"excerpt":"El precandidato presidencial Paraguayo Cubas dispar\u00f3 contra la figura de la concertaci\u00f3n opositora. \u201cNo hay padr\u00f3n abierto, le hemos mentido a la poblaci\u00f3n\u201d, expres\u00f3 Cubas a la radio \u00d1anduti AM. Afirm\u00f3 que las internas de la Concertaci\u00f3n, ser\u00e1n una interna liberal, aunque puntualiz\u00f3 que difiere con la lectura que sostiene\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/payo-y-efrain.jpg?fit=545%2C330&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8982,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/22\/salyn-buzarquis-payo-cubas\/","url_meta":{"origin":1100,"position":3},"title":"\u00bfSalyn Buzarquis &#8211; Payo Cubas 2023?","date":"22 de diciembre de 2021","format":false,"excerpt":"Sigue la danza de nombres para las chapas presidenciales del 2023. La \u00faltima en sumarse es la que podr\u00eda conformarse entre el senador del Partido Liberal Salyn Buzarquis y el ex senador \"Payo\" Cubas. Salyn Buzarquis, confirm\u00f3 a Radio \u00d1andut\u00ed que no descarta formar una dupla presidencial con el exsenador\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2203,"url":"https:\/\/informatepy.com\/2021\/2020\/10\/06\/infames\/","url_meta":{"origin":1100,"position":4},"title":"Infames","date":"6 de octubre de 2020","format":false,"excerpt":"La abogada Carolina Arias, representante legal de la familia de Natalia Godoy afirm\u00f3 en Radio \u00d1andut\u00ed, que la defensa de la familia de la conductora acudi\u00f3 a ella para ofrecer G. 1. 500.000 por tres a\u00f1os como resarcimiento del da\u00f1o. Agreg\u00f3 que a su criterio lo propicio ser\u00eda tratar la\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/accidente-natalia-godoy.jpg?fit=750%2C563&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9297,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/07\/hugo-ramirez-pretende-presidir-la-anr\/","url_meta":{"origin":1100,"position":5},"title":"Hugo Ram\u00edrez pretende presidir la ANR","date":"7 de enero de 2022","format":false,"excerpt":"En una entrevista que brind\u00f3 al programa de Hugo Rub\u00edn en Radio \u00d1andut\u00ed, el diputado Hugo Ram\u00edrez manifest\u00f3 que pretende candidatearse para presidente de la Asociaci\u00f3n Nacional Republicana (ANR). Luego de hablar de su proyecto de ley para la instauraci\u00f3n de una pase sanitario en nuestro pa\u00eds y de criticar\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/hugo-ramirez1.png?fit=1200%2C672&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1100"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1100\/revisions"}],"predecessor-version":[{"id":2995,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1100\/revisions\/2995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1101"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1100"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}