{"id":10773,"date":"2022-03-23T07:00:00","date_gmt":"2022-03-23T10:00:00","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=10773"},"modified":"2022-03-22T20:01:17","modified_gmt":"2022-03-22T23:01:17","slug":"jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/","title":{"rendered":"Jueza de Paz ejerce censura previa a un comunicador para favorecer a una concejal cercana a Miguel Prieto"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">La Jueza de Paz, <strong>C\u00e1ndida Ivone Barreto Quevedo<\/strong>, emiti\u00f3 una resoluci\u00f3n judicial que viola preceptos consagrados en la Carta Magna, al censurar previamente a un comunicador y, adem\u00e1s, emite una restricci\u00f3n que impedir\u00eda que el periodista, <strong>V\u00edctor Barboza Spahr<\/strong> ejerza su labor como tal. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La resoluci\u00f3n judicial se basa en el pedido de la Concejal <strong>Valeria Romero<\/strong>, apuntada por Spahr, entre otros comunicadores, por graves casos de corrupci\u00f3n en la administraci\u00f3n municipal desde que la misma se desempe\u00f1aba como Directora de CODENI, bajo administraci\u00f3n de <strong>Miguel Prieto Vallejos<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"582\" height=\"960\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/ResolucionJuezaDePazCDE.jpg?resize=582%2C960&#038;ssl=1\" alt=\"\" class=\"wp-image-10774\" srcset=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/ResolucionJuezaDePazCDE.jpg?w=582&amp;ssl=1 582w, https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/ResolucionJuezaDePazCDE.jpg?resize=182%2C300&amp;ssl=1 182w\" sizes=\"auto, (max-width: 582px) 100vw, 582px\" data-recalc-dims=\"1\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La concejal, seg\u00fan menciona V\u00edctor Spahr, habr\u00eda intentado callar las denuncias de V\u00edctor Spahr envi\u00e1ndole como \u201cobsequio\u201d una costosa remera de futbol y una \u201cayudita\u201d econ\u00f3mica de 5 millones de guaran\u00edes para que el mismo pueda arreglar su casa pero, como Spahr rechaz\u00f3 la \u201cgentileza\u201d, Valeria Romero ahora insin\u00faa que el comunicador desea extorsionarla. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La edil promovi\u00f3 la denuncia aduciendo ataques por su condici\u00f3n de mujer, lo que gener\u00f3 la resoluci\u00f3n de la Jueza de Paz C\u00e1ndida Barreto Quevedo, prohibi\u00e9ndole al comunicador emitir opiniones y acercare a la misma hasta 20 metros, lo que impedir\u00eda las labores de Spahr, quien no podr\u00e1 realizar entrevistas ni a ella ni a otros concejales si ella se encuentra cerca.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"461\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-10778\" data-id=\"10778\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/chatCDE1.jpg?resize=461%2C1024&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/chatCDE1.jpg?resize=461%2C1024&amp;ssl=1 461w, https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/chatCDE1.jpg?resize=135%2C300&amp;ssl=1 135w, https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/chatCDE1.jpg?w=640&amp;ssl=1 640w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" data-recalc-dims=\"1\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"486\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-10775\" data-id=\"10775\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/ChatCDE2.jpg?resize=720%2C486&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/ChatCDE2.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/ChatCDE2.jpg?resize=300%2C203&amp;ssl=1 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" data-recalc-dims=\"1\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"648\" height=\"798\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-10777\" data-id=\"10777\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/ChatCDE4.jpg?resize=648%2C798&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/ChatCDE4.jpg?w=648&amp;ssl=1 648w, https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/ChatCDE4.jpg?resize=244%2C300&amp;ssl=1 244w\" sizes=\"auto, (max-width: 648px) 100vw, 648px\" data-recalc-dims=\"1\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"837\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-10776\" data-id=\"10776\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/ChatCDE3.jpg?resize=720%2C837&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/ChatCDE3.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/ChatCDE3.jpg?resize=258%2C300&amp;ssl=1 258w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" data-recalc-dims=\"1\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<h6 class=\"wp-block-heading\">Con informaci\u00f3n de Ciudad del Este Noticias<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La Jueza de Paz, C\u00e1ndida Ivone Barreto Quevedo, emiti\u00f3 una resoluci\u00f3n judicial que viola preceptos consagrados en la Carta Magna, al censurar previamente a un comunicador y, adem\u00e1s, emite una restricci\u00f3n que impedir\u00eda que el periodista, V\u00edctor Barboza Spahr ejerza su labor como tal. La resoluci\u00f3n judicial se basa en el pedido de la Concejal [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":false},"categories":[483],"tags":[290,564,1036,588,1734],"ppma_author":[1051],"class_list":["post-10773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipales","tag-cde","tag-ciudad-del-este","tag-destacada","tag-miguel-prieto","tag-valeria-romero"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jueza de Paz ejerce censura previa a un comunicador para favorecer a una concejal cercana a Miguel Prieto - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jueza de Paz ejerce censura previa a un comunicador para favorecer a una concejal cercana a Miguel Prieto - Informatepy\" \/>\n<meta property=\"og:description\" content=\"La Jueza de Paz, C\u00e1ndida Ivone Barreto Quevedo, emiti\u00f3 una resoluci\u00f3n judicial que viola preceptos consagrados en la Carta Magna, al censurar previamente a un comunicador y, adem\u00e1s, emite una restricci\u00f3n que impedir\u00eda que el periodista, V\u00edctor Barboza Spahr ejerza su labor como tal. La resoluci\u00f3n judicial se basa en el pedido de la Concejal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-23T10:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Concejal.valeria-romero.jpg?fit=572%2C350&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"572\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Jueza de Paz ejerce censura previa a un comunicador para favorecer a una concejal cercana a Miguel Prieto\",\"datePublished\":\"2022-03-23T10:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/\"},\"wordCount\":252,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Concejal.valeria-romero.jpg?fit=572%2C350&ssl=1\",\"keywords\":[\"CDE\",\"ciudad del este\",\"destacada\",\"miguel prieto\",\"valeria romero\"],\"articleSection\":[\"Municipales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/\",\"name\":\"Jueza de Paz ejerce censura previa a un comunicador para favorecer a una concejal cercana a Miguel Prieto - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Concejal.valeria-romero.jpg?fit=572%2C350&ssl=1\",\"datePublished\":\"2022-03-23T10:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Concejal.valeria-romero.jpg?fit=572%2C350&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Concejal.valeria-romero.jpg?fit=572%2C350&ssl=1\",\"width\":572,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/03\\\/23\\\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jueza de Paz ejerce censura previa a un comunicador para favorecer a una concejal cercana a Miguel Prieto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jueza de Paz ejerce censura previa a un comunicador para favorecer a una concejal cercana a Miguel Prieto - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/","og_locale":"es_ES","og_type":"article","og_title":"Jueza de Paz ejerce censura previa a un comunicador para favorecer a una concejal cercana a Miguel Prieto - Informatepy","og_description":"La Jueza de Paz, C\u00e1ndida Ivone Barreto Quevedo, emiti\u00f3 una resoluci\u00f3n judicial que viola preceptos consagrados en la Carta Magna, al censurar previamente a un comunicador y, adem\u00e1s, emite una restricci\u00f3n que impedir\u00eda que el periodista, V\u00edctor Barboza Spahr ejerza su labor como tal. La resoluci\u00f3n judicial se basa en el pedido de la Concejal [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-03-23T10:00:00+00:00","og_image":[{"width":572,"height":350,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Concejal.valeria-romero.jpg?fit=572%2C350&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Jueza de Paz ejerce censura previa a un comunicador para favorecer a una concejal cercana a Miguel Prieto","datePublished":"2022-03-23T10:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/"},"wordCount":252,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Concejal.valeria-romero.jpg?fit=572%2C350&ssl=1","keywords":["CDE","ciudad del este","destacada","miguel prieto","valeria romero"],"articleSection":["Municipales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/","url":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/","name":"Jueza de Paz ejerce censura previa a un comunicador para favorecer a una concejal cercana a Miguel Prieto - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Concejal.valeria-romero.jpg?fit=572%2C350&ssl=1","datePublished":"2022-03-23T10:00:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Concejal.valeria-romero.jpg?fit=572%2C350&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Concejal.valeria-romero.jpg?fit=572%2C350&ssl=1","width":572,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/03\/23\/jueza-de-paz-ejerce-censura-previa-a-un-comunicador-para-favorecer-a-una-concejal-cercana-a-miguel-prieto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Jueza de Paz ejerce censura previa a un comunicador para favorecer a una concejal cercana a Miguel Prieto"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Concejal.valeria-romero.jpg?fit=572%2C350&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":11150,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/13\/sin-votar-y-sin-haberla-visto-los-concejales-estenos-aprobaron-la-rendicion-de-cuentas-de-prieto\/","url_meta":{"origin":10773,"position":0},"title":"Sin votar y sin haberla visto, los concejales este\u00f1os aprobaron la rendici\u00f3n de cuentas de Prieto","date":"13 de abril de 2022","format":false,"excerpt":"El presidente de la Junta Municipal de CDE, Pedro Acu\u00f1a, cu\u00f1ado del intendente Miguel Prieto, no puso en votaci\u00f3n el dictamen de Valeria Romero (ex pareja de Prieto) quien aconsejo la aprobaci\u00f3n de la rendici\u00f3n de cuenta de 2021 del jefe comunal. Nadie vio los documentos. Pero se sabe que\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/pedro-acuna-miguel-prieto.jpg?fit=770%2C578&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1172,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/20\/concejales-estenos-emplazan-a-prieto\/","url_meta":{"origin":10773,"position":1},"title":"Concejales este\u00f1os emplazan a Prieto","date":"20 de mayo de 2019","format":false,"excerpt":"En estos momentos se realiza la sesi\u00f3n extraordinaria de la Junta Municipal de Ciudad del Este, donde los concejales piden informes a la administraci\u00f3n de Miguel Prieto, sobre las distintas disposiciones que realiz\u00f3 luego de asumir el cargo. La sesi\u00f3n se realiza con la presencia de los 6 concejales colorados\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/junta-municipal-cde.jpg?fit=768%2C512&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10380,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/01\/clan-prieto-recibio-coima-del-esquema-de-lavado-de-dinero-investigado-por-a-ultranza-paraguay\/","url_meta":{"origin":10773,"position":2},"title":"Clan Prieto recibi\u00f3 coima del esquema de lavado de dinero investigado por \u201cA ultranza Paraguay\u00bb","date":"1 de marzo de 2022","format":false,"excerpt":"El Clan Prieto que maneja la comuna de Ciudad del Este, desde 2019, recibi\u00f3 coimas para habilitar estaciones de servicios del esquema de lavado de dinero que investiga los fiscales con la operaci\u00f3n \u201cA Ultranza Paraguay\u201d. Fue a trav\u00e9s de la empresa Tapiracuai S.A., propiedad de Alberto Koube. El propio\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/petrochaco-cde.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6846,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/30\/denuncian-pago-de-coimas-por-1-500-millones-al-equipo-de-miguel-prieto\/","url_meta":{"origin":10773,"position":3},"title":"Denuncian pago de coimas por 1.500 millones al equipo de Miguel Prieto","date":"30 de agosto de 2021","format":false,"excerpt":"El empresario Enrique Ignacio V\u00e1zquez Garc\u00eda, del consorcio \u00d1ande Y Poti, adjudicado para la construcci\u00f3n de la costanera de Ciudad del Este, revel\u00f3 un esquema de pago millonario de coimas a integrantes del equipo de Miguel Prieto y a concejales municipales. El monto habr\u00eda alcanzado los 1.500 millones de guaran\u00edes,\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/pedro-acuna-mieguel-prieto.jpg?fit=960%2C705&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1352,"url":"https:\/\/informatepy.com\/2021\/2019\/07\/20\/miguel-prieto-desconoce-el-concepto-de-seguridad-juridica\/","url_meta":{"origin":10773,"position":4},"title":"Miguel Prieto desconoce el concepto de seguridad jur\u00eddica","date":"20 de julio de 2019","format":false,"excerpt":"La municipalidad de Ciudad del Este volvi\u00f3 a tomar el control sobre la Terminal de \u00d3mnibus de esa ciudad, avalada solamente por una resoluci\u00f3n firmada por el Intendente Municipal, Miguel Prieto. Seg\u00fan la resoluci\u00f3n, existen una serie de incumplimientos de contrato por parte de la empresa Ita Paran\u00e1.\u00a0 Entre los\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/prieto-terminal-de-cde.jpg?fit=870%2C498&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1798,"url":"https:\/\/informatepy.com\/2021\/2020\/03\/29\/denuncian-sobrefacturacion-en-kits-de-emergencia-en-cde\/","url_meta":{"origin":10773,"position":5},"title":"Denuncian sobrefacturaci\u00f3n en kits de emergencia en CDE","date":"29 de marzo de 2020","format":false,"excerpt":"El Concejal Celso \"Kelembu\" Miranda denunci\u00f3 que los Concejales oficialistas y el Intendente Municipal Miguel Prieto usaron la emergencia por el Covid-19 para despilfarrar el dinero de las arcas municipales. Seg\u00fan denunci\u00f3 Miranda, aprobaron 8 mil millones para cestas b\u00e1sicas que compraron por valo de 125.000 guaran\u00edes y el mismo\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/minuta-CDE-1.jpg?fit=658%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/10773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=10773"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/10773\/revisions"}],"predecessor-version":[{"id":10780,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/10773\/revisions\/10780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/10779"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=10773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=10773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=10773"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=10773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}