{"id":1048,"date":"2019-04-17T20:19:00","date_gmt":"2019-04-17T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1048"},"modified":"2021-02-09T18:16:01","modified_gmt":"2021-02-09T18:16:01","slug":"jubero-se-lo-sirve-en-bandeja","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/","title":{"rendered":"Jubero se lo sirve en bandeja"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Decano fue contundente en el Manuel Ferreira y venci\u00f3 por 2-0 a Sportivo Luque\u00f1o por la regularizaci\u00f3n de la fecha 14 del campeonato Apertura 2019. Con este resultado, el equipo de Daniel Garnero aprovech\u00f3 el empate de Cerro en Capiat\u00e1 y le sac\u00f3 cuatro puntos de ventaja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Franjeado lidera la tabla del torneo con 37 unidades y arriba al supercl\u00e1sico del s\u00e1bado en racha y de forma invicta. El mencionado partido, supercl\u00e1sico del f\u00fatbol paraguayo, podr\u00eda poner, en caso de otra victoria del puntero, en el umbral de su tricampeonato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto, Cerro Porte\u00f1o, de la mano de Jubero empat\u00f3 1-1 ante el equipo del Chito Ayala y resign\u00f3 puntos valiosos en su visita a Capiat\u00e1. El Cicl\u00f3n llega frenado y m\u00e1s comprometido al cl\u00e1sico del s\u00e1bado ante el l\u00edder Olimpia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Decano fue contundente en el Manuel Ferreira y venci\u00f3 por 2-0 a Sportivo Luque\u00f1o por la regularizaci\u00f3n de la fecha 14 del campeonato Apertura 2019. Con este resultado, el equipo de Daniel Garnero aprovech\u00f3 el empate de Cerro en Capiat\u00e1 y le sac\u00f3 cuatro puntos de ventaja. El Franjeado lidera la tabla del torneo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[183],"tags":[186,187,252,253],"ppma_author":[1039],"class_list":["post-1048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-apf","tag-cerro-porteno","tag-futbol-paraguayo","tag-olimpia"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jubero se lo sirve en bandeja - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jubero se lo sirve en bandeja - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El Decano fue contundente en el Manuel Ferreira y venci\u00f3 por 2-0 a Sportivo Luque\u00f1o por la regularizaci\u00f3n de la fecha 14 del campeonato Apertura 2019. Con este resultado, el equipo de Daniel Garnero aprovech\u00f3 el empate de Cerro en Capiat\u00e1 y le sac\u00f3 cuatro puntos de ventaja. El Franjeado lidera la tabla del torneo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-17T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-09T18:16:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Olimpia-vs.-LuquenCC83o.jpg?fit=1000%2C667&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Jubero se lo sirve en bandeja\",\"datePublished\":\"2019-04-17T20:19:00+00:00\",\"dateModified\":\"2021-02-09T18:16:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/\"},\"wordCount\":149,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Olimpia-vs.-LuquenCC83o.jpg?fit=1000%2C667&ssl=1\",\"keywords\":[\"apf\",\"cerro porte\u00f1o\",\"futbol paraguayo\",\"olimpia\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/\",\"name\":\"Jubero se lo sirve en bandeja - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Olimpia-vs.-LuquenCC83o.jpg?fit=1000%2C667&ssl=1\",\"datePublished\":\"2019-04-17T20:19:00+00:00\",\"dateModified\":\"2021-02-09T18:16:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Olimpia-vs.-LuquenCC83o.jpg?fit=1000%2C667&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Olimpia-vs.-LuquenCC83o.jpg?fit=1000%2C667&ssl=1\",\"width\":1000,\"height\":667,\"caption\":\"Brian Montenegro marc\u00f3 en el triunfo de Olimpia ante Luque\u00f1o. Foto: An\u00edbal Gauto.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/17\\\/jubero-se-lo-sirve-en-bandeja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jubero se lo sirve en bandeja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jubero se lo sirve en bandeja - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/","og_locale":"es_ES","og_type":"article","og_title":"Jubero se lo sirve en bandeja - Informatepy","og_description":"El Decano fue contundente en el Manuel Ferreira y venci\u00f3 por 2-0 a Sportivo Luque\u00f1o por la regularizaci\u00f3n de la fecha 14 del campeonato Apertura 2019. Con este resultado, el equipo de Daniel Garnero aprovech\u00f3 el empate de Cerro en Capiat\u00e1 y le sac\u00f3 cuatro puntos de ventaja. El Franjeado lidera la tabla del torneo [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/","og_site_name":"Informatepy","article_published_time":"2019-04-17T20:19:00+00:00","article_modified_time":"2021-02-09T18:16:01+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Olimpia-vs.-LuquenCC83o.jpg?fit=1000%2C667&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Jubero se lo sirve en bandeja","datePublished":"2019-04-17T20:19:00+00:00","dateModified":"2021-02-09T18:16:01+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/"},"wordCount":149,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Olimpia-vs.-LuquenCC83o.jpg?fit=1000%2C667&ssl=1","keywords":["apf","cerro porte\u00f1o","futbol paraguayo","olimpia"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/","url":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/","name":"Jubero se lo sirve en bandeja - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Olimpia-vs.-LuquenCC83o.jpg?fit=1000%2C667&ssl=1","datePublished":"2019-04-17T20:19:00+00:00","dateModified":"2021-02-09T18:16:01+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Olimpia-vs.-LuquenCC83o.jpg?fit=1000%2C667&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Olimpia-vs.-LuquenCC83o.jpg?fit=1000%2C667&ssl=1","width":1000,"height":667,"caption":"Brian Montenegro marc\u00f3 en el triunfo de Olimpia ante Luque\u00f1o. Foto: An\u00edbal Gauto."},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/17\/jubero-se-lo-sirve-en-bandeja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Jubero se lo sirve en bandeja"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Olimpia-vs.-LuquenCC83o.jpg?fit=1000%2C667&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1082,"url":"https:\/\/informatepy.com\/2021\/2019\/04\/26\/jubero-con-un-pie-afuera-de-cerro-porteno\/","url_meta":{"origin":1048,"position":0},"title":"Jubero con un pie afuera de Cerro Porte\u00f1o","date":"26 de abril de 2019","format":false,"excerpt":"Fernando Jubero est\u00e1 en la cuerda floja luego de las \u00faltimas (y dolorosas) derrotas ante a Olimpia Olimpia por el torneo local (1-3) y con el Zamora (1-2) en Copa Libertadores. Los malos resultados y, por encima de eso, la actitud mostrada por el equipo, hizo que los dirigentes de\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/fernando-jubero.jpg?fit=590%2C440&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":585,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/olimpia-y-cerro-porteno-empatan-en-un-dramatico-superclasico\/","url_meta":{"origin":1048,"position":1},"title":"Olimpia y Cerro Porte\u00f1o empatan en un dram\u00e1tico supercl\u00e1sico","date":"18 de febrero de 2019","format":false,"excerpt":"Parec\u00eda que Olimpia se quedaba con el supercl\u00e1sico 302 del f\u00fatbol paraguayo, pero a los 90 apareci\u00f3 \u00d3scar Ruiz para salvar al Cicl\u00f3n con un golpe de cabeza. Con este resultado, los dos colosos del f\u00fatbol nacional siguen como punteros del campeonato Apertura 2019 con 13 unidades. El equipo de\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Olimpia-cerro-clasico-302.jpeg?fit=730%2C486&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1171,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/20\/jubero-ya-no-es-el-dt-de-cerro-porteno\/","url_meta":{"origin":1048,"position":2},"title":"Jubero ya no es el DT de Cerro Porte\u00f1o","date":"20 de mayo de 2019","format":false,"excerpt":"Fernando Jubero ya no es entrenador de Cerro Porte\u00f1o. Luego de que el Cicl\u00f3n haya cerrado su participaci\u00f3n en el torneo Apertura finalizando en la segunda posici\u00f3n con 43 puntos, 11 menos que el campe\u00f3n, Olimpia, la dirigencia anunci\u00f3 la salida del DT, quien hab\u00eda llegado a Barrio Obrero en\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nani-zapag-jubero.jpeg?fit=730%2C486&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1024,"url":"https:\/\/informatepy.com\/2021\/2019\/04\/14\/olimpia-y-cerro-ganan-y-la-punta-del-torneo-sigue-sin-cambios\/","url_meta":{"origin":1048,"position":3},"title":"Olimpia y Cerro golean y la punta del torneo sigue sin cambios","date":"14 de abril de 2019","format":false,"excerpt":"Tanto Olimpia como Cerro ganaron ayer s\u00e1bado por goleada y se mantienen primero y segundo, respectivamente, en la pelea por la punta del campeonato Apertura. En primer lugar Olimpia gan\u00f3 en su casa 4-0 a Sol de Am\u00e9rica para mantenerse como puntero, con 34 puntos, e invicto habiendo 14 partidos\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/olimpia.jpg?fit=640%2C477&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1056,"url":"https:\/\/informatepy.com\/2021\/2019\/04\/20\/a-todo-o-nada\/","url_meta":{"origin":1048,"position":4},"title":"A todo o nada","date":"20 de abril de 2019","format":false,"excerpt":"En pleno s\u00e1bado de Gloria, Cerro Porte\u00f1o\u00a0y Olimpia tienen una cita con el f\u00fatbol en el Defensores del Chaco. El\u00a0Cicl\u00f3n, que viene de igualar 1a1 con Capiat\u00e1, se juega quiz\u00e1s su \u00faltima carta para buscar acercarse m\u00e1s al puntero del Apertura, que le saca cuatro puntos de ventaja (37 unidades\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/haedo-y-roque.jpg?fit=730%2C501&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1061,"url":"https:\/\/informatepy.com\/2021\/2019\/04\/20\/olimpia-castiga-duro-a-cerro\/","url_meta":{"origin":1048,"position":5},"title":"Olimpia castiga duro a Cerro","date":"20 de abril de 2019","format":false,"excerpt":"Olimpia, el bicampe\u00f3n vigente del f\u00fatbol paraguayo y actual puntero invicto del torneo Apertura 2019, se hizo fuerte este s\u00e1bado en el estadio Defensores del Chaco y derrot\u00f3 con contundencia por 3-1 a\u00a0Cerro Porte\u00f1o. Alejandro Silva, Roque Santa Cruz y Tabar\u00e9 Viudez anotaron los goles del Rey de Copas, que\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/superclasico.jpg?fit=730%2C433&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1048"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1048\/revisions"}],"predecessor-version":[{"id":3082,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1048\/revisions\/3082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1049"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1048"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}