{"id":10300,"date":"2022-02-24T10:42:57","date_gmt":"2022-02-24T13:42:57","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=10300"},"modified":"2022-02-24T10:43:00","modified_gmt":"2022-02-24T13:43:00","slug":"uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/","title":{"rendered":"Uno m\u00e1s \u00bfY van?: Joaqu\u00edn Roa con yate de u$s 400.000 y v\u00ednculos narcos"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">El ministro de Emergencia Nacional reconoci\u00f3 ser propietario (desde el 2018) de un yate valuado en <strong>400.000 d\u00f3lares,<\/strong> que, seg\u00fan \u00e9l, sigue pagando. En sus declaraciones juradas solamente figura una lancha, porque <strong><em>\u00abtodav\u00eda no tiene los papeles<\/em><\/strong>\u00ab. <strong>Admiti\u00f3 ser amigo del presunto narco Alberto Koube y haberle adjudicado tres licitaciones de la SEN.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Detall\u00f3 que hace 23 a\u00f1os incursion\u00f3 en el rubro de los Retails, con una tienda de franquicias de una marca brasile\u00f1a. Actualmente cuenta con ocho locales (Hering) en diferentes shoppings, entre ellos, de Asunci\u00f3n, San Lorenzo y Encarnaci\u00f3n.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Asegur\u00f3 que la facturaci\u00f3n promedio de estos negocios es de 26.000 a 30.000 millones de guaran\u00edes al a\u00f1o y otros negocios gastron\u00f3micos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Emergencia Nacional reconoci\u00f3 ser propietario (desde el 2018) de un yate valuado en 400.000 d\u00f3lares, que, seg\u00fan \u00e9l, sigue pagando. En sus declaraciones juradas solamente figura una lancha, porque \u00abtodav\u00eda no tiene los papeles\u00ab. Admiti\u00f3 ser amigo del presunto narco Alberto Koube y haberle adjudicado tres licitaciones de la SEN. Detall\u00f3 que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10301,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[1036,1696,180],"ppma_author":[1051],"class_list":["post-10300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-destacada","tag-joaquin-roa","tag-narcotrafico"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uno m\u00e1s \u00bfY van?: Joaqu\u00edn Roa con yate de u$s 400.000 y v\u00ednculos narcos - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uno m\u00e1s \u00bfY van?: Joaqu\u00edn Roa con yate de u$s 400.000 y v\u00ednculos narcos - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El ministro de Emergencia Nacional reconoci\u00f3 ser propietario (desde el 2018) de un yate valuado en 400.000 d\u00f3lares, que, seg\u00fan \u00e9l, sigue pagando. En sus declaraciones juradas solamente figura una lancha, porque \u00abtodav\u00eda no tiene los papeles\u00ab. Admiti\u00f3 ser amigo del presunto narco Alberto Koube y haberle adjudicado tres licitaciones de la SEN. Detall\u00f3 que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-24T13:42:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-24T13:43:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/yate-antares-joaquin-roa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"726\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Uno m\u00e1s \u00bfY van?: Joaqu\u00edn Roa con yate de u$s 400.000 y v\u00ednculos narcos\",\"datePublished\":\"2022-02-24T13:42:57+00:00\",\"dateModified\":\"2022-02-24T13:43:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/\"},\"wordCount\":136,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/yate-antares-joaquin-roa.jpg?fit=726%2C490&ssl=1\",\"keywords\":[\"destacada\",\"joaquin roa\",\"narcotrafico\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/\",\"name\":\"Uno m\u00e1s \u00bfY van?: Joaqu\u00edn Roa con yate de u$s 400.000 y v\u00ednculos narcos - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/yate-antares-joaquin-roa.jpg?fit=726%2C490&ssl=1\",\"datePublished\":\"2022-02-24T13:42:57+00:00\",\"dateModified\":\"2022-02-24T13:43:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/yate-antares-joaquin-roa.jpg?fit=726%2C490&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/yate-antares-joaquin-roa.jpg?fit=726%2C490&ssl=1\",\"width\":726,\"height\":490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/24\\\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uno m\u00e1s \u00bfY van?: Joaqu\u00edn Roa con yate de u$s 400.000 y v\u00ednculos narcos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uno m\u00e1s \u00bfY van?: Joaqu\u00edn Roa con yate de u$s 400.000 y v\u00ednculos narcos - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/","og_locale":"es_ES","og_type":"article","og_title":"Uno m\u00e1s \u00bfY van?: Joaqu\u00edn Roa con yate de u$s 400.000 y v\u00ednculos narcos - Informatepy","og_description":"El ministro de Emergencia Nacional reconoci\u00f3 ser propietario (desde el 2018) de un yate valuado en 400.000 d\u00f3lares, que, seg\u00fan \u00e9l, sigue pagando. En sus declaraciones juradas solamente figura una lancha, porque \u00abtodav\u00eda no tiene los papeles\u00ab. Admiti\u00f3 ser amigo del presunto narco Alberto Koube y haberle adjudicado tres licitaciones de la SEN. Detall\u00f3 que [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-02-24T13:42:57+00:00","article_modified_time":"2022-02-24T13:43:00+00:00","og_image":[{"width":726,"height":490,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/yate-antares-joaquin-roa.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Uno m\u00e1s \u00bfY van?: Joaqu\u00edn Roa con yate de u$s 400.000 y v\u00ednculos narcos","datePublished":"2022-02-24T13:42:57+00:00","dateModified":"2022-02-24T13:43:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/"},"wordCount":136,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/yate-antares-joaquin-roa.jpg?fit=726%2C490&ssl=1","keywords":["destacada","joaquin roa","narcotrafico"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/","url":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/","name":"Uno m\u00e1s \u00bfY van?: Joaqu\u00edn Roa con yate de u$s 400.000 y v\u00ednculos narcos - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/yate-antares-joaquin-roa.jpg?fit=726%2C490&ssl=1","datePublished":"2022-02-24T13:42:57+00:00","dateModified":"2022-02-24T13:43:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/yate-antares-joaquin-roa.jpg?fit=726%2C490&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/yate-antares-joaquin-roa.jpg?fit=726%2C490&ssl=1","width":726,"height":490},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/uno-mas-y-van-joaquin-roa-con-yate-de-us-400-000-y-vinculos-narcos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Uno m\u00e1s \u00bfY van?: Joaqu\u00edn Roa con yate de u$s 400.000 y v\u00ednculos narcos"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/yate-antares-joaquin-roa.jpg?fit=726%2C490&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":10303,"url":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/segundo-ministro-destituido-esta-semana-por-vinculos-con-narcos\/","url_meta":{"origin":10300,"position":0},"title":"Segundo ministro destituido esta semana por v\u00ednculos con narcos","date":"24 de febrero de 2022","format":false,"excerpt":"Los ministros del gabinete del presidente Abdo caen como mu\u00f1ecos. Apenas 48 horas despu\u00e9s de que fuera destituido Arnaldo Giuzzio, quien estaba al frente del Ministerio del Interior por sus v\u00ednculos con presuntos narcotraficantes; Joaqu\u00edn Roa, Ministro de la Secretar\u00eda de Emergencia Nacional corri\u00f3 la misma suerte. Seg\u00fan el mismo\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/joaquin-roa.jpg?fit=900%2C597&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12160,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/15\/jorge-querey-adelanto-que-seran-investigados-todos-los-temas-incluyendo-el-negocio-del-banco-atlas-con-cabeca-branca\/","url_meta":{"origin":10300,"position":1},"title":"Jorge Querey adelant\u00f3 que ser\u00e1n investigados \u201ctodos los temas\u201d, incluyendo el negocio del Banco Atlas con \u201cCabe\u00e7a Branca\u201d","date":"15 de junio de 2022","format":false,"excerpt":"El senador Jorge Querey (Frente Guasu), presidente de la Comisi\u00f3n Bicameral de Investigaci\u00f3n (CBI) al lavado de dinero y delitos conexos en Paraguay, adelant\u00f3 que ser\u00e1n indagados \u201ctodos los temas\u201d, incluyendo el negocio del Banco Atlas con el testaferro del capo narco Luiz Carlos da Rocha, alias \u201cCabe\u00e7a Branca\u201d, preso\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/jorge-querey.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10562,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/11\/humillante-claudicacion-de-biden-ante-la-narco-tirania-bananera-de-maduro\/","url_meta":{"origin":10300,"position":2},"title":"Humillante claudicaci\u00f3n de Biden ante la narco-tiran\u00eda bananera de Maduro","date":"11 de marzo de 2022","format":false,"excerpt":"El acontecimiento mundial que ha capturado la mayor atenci\u00f3n de la prensa, la academia y la opini\u00f3n en general, sin duda es lo refido a la invasi\u00f3n de Rusia a Ucrania y la reacci\u00f3n de Occidente, b\u00e1sicamente la Uni\u00f3n Europea, Estados Unidos y algunos de sus socios en de la\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/nahem.png?fit=1200%2C657&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2003,"url":"https:\/\/informatepy.com\/2021\/2020\/05\/28\/vox-populi-vox-dei\/","url_meta":{"origin":10300,"position":3},"title":"Vox Populi, \u00bfVox Dei?","date":"28 de mayo de 2020","format":false,"excerpt":"\u201cVox Populi, Vox Dei\u201d reza un adagio que ha sido utilizado a lo largo de la historia por toda clase de dictadores para justificar sus atropellos a las libertades civiles. Hasta el momento nadie ha podido precisar a quien se le ocurri\u00f3 semejante desacierto pero, aun as\u00ed, lo siguen utilizando.\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/MAria-Esther-Roa-CACE.jpg?fit=769%2C495&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1655,"url":"https:\/\/informatepy.com\/2021\/2019\/12\/02\/enrique-riera-le-responde-a-kattya-gonzalez\/","url_meta":{"origin":10300,"position":4},"title":"Enrique Riera le respondi\u00f3 a Kattya Gonz\u00e1lez","date":"2 de diciembre de 2019","format":false,"excerpt":"Luego que la diputada nacional por el Departamento Central criticara a los senadores por haber votado la p\u00e9rdida de investidura de Payo Cubas, el senador nacional Enrique Riera sali\u00f3 a responderle a trav\u00e9s de su cuenta de Twitter. La diputada hab\u00eda cuestionado la autoridad moral de los senadores, olvidando, tal\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/Riera-y-Kattya-Gonzalez-scaled.jpg?fit=1200%2C668&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1000,"url":"https:\/\/informatepy.com\/2021\/2019\/04\/05\/el-gobernador-de-central-se-reunio-con-el-comite-de-emergencia-nacional\/","url_meta":{"origin":10300,"position":5},"title":"El Gobernador de Central se reuni\u00f3 con el Comit\u00e9 de Emergencia Nacional","date":"5 de abril de 2019","format":false,"excerpt":"El Gobernador de Central, Hugo Javier Gonz\u00e1lez, particip\u00f3 de una mesa de trabajo con las instituciones integrantes del comit\u00e9 de Emergencia Nacional, en el marco de los trabajos de asistencia a las familias afectadas por las inundaciones.\u00a0 Al respecto, el jefe\u00a0 departamental resalt\u00f3 la importancia de una\u00a0 cooperaci\u00f3n interinstitucional para\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/IMG-20190405-WA0067.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/10300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=10300"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/10300\/revisions"}],"predecessor-version":[{"id":10302,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/10300\/revisions\/10302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/10301"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=10300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=10300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=10300"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=10300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}