{"id":10086,"date":"2022-02-14T07:47:30","date_gmt":"2022-02-14T10:47:30","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=10086"},"modified":"2022-02-14T07:47:33","modified_gmt":"2022-02-14T10:47:33","slug":"el-sistema-te-obliga-a-la-corrupcion","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/","title":{"rendered":"El sistema te obliga a la corrupci\u00f3n"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">El diablo puede citar las Escrituras para conseguir sus fines cuenta el dicho y as\u00ed tambi\u00e9n la casta pol\u00edtica se llena la boca con derechos humanos, laborales, colectivos y sociales, legislan sobre ellos y los imponen sobre el resto. Pero como en el mundo de los opuestos no es por los sujetos que protegen esos derechos sino para promover sus propios intereses.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Es bonito aspirar a algo m\u00e1s alto pero en un sistema como el nuestro el papel no es para hacerlo cumplir, sino algo con que la coima pedir, es dif\u00edcil estar formal porque as\u00ed es m\u00e1s f\u00e1cil coimear, en negro el riesgo es uno, que te descubran, y se soluciona transando, estar en blanco es muy caro y te persiguen a cada rato, de arriba, de abajo y los costados, comenzando por\u00a0 el estado, te hacen problemas por todos lados, porque ese no es el trato. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Y as\u00ed el empleado desamparado y el empresario maniatado son presa del corrupto con el c\u00f3digo, el reglamento o la constituci\u00f3n en la mano, que garantizando derechos en abstracto obliga a la corrupci\u00f3n al ciudadano, por la forma en que est\u00e1 el sistema dise\u00f1ado y el modo en que es aplicado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El diablo puede citar las Escrituras para conseguir sus fines cuenta el dicho y as\u00ed tambi\u00e9n la casta pol\u00edtica se llena la boca con derechos humanos, laborales, colectivos y sociales, legislan sobre ellos y los imponen sobre el resto. Pero como en el mundo de los opuestos no es por los sujetos que protegen esos [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":10087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":false},"categories":[248],"tags":[242],"ppma_author":[1298],"class_list":["post-10086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-corrupcion"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El sistema te obliga a la corrupci\u00f3n - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El sistema te obliga a la corrupci\u00f3n - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El diablo puede citar las Escrituras para conseguir sus fines cuenta el dicho y as\u00ed tambi\u00e9n la casta pol\u00edtica se llena la boca con derechos humanos, laborales, colectivos y sociales, legislan sobre ellos y los imponen sobre el resto. Pero como en el mundo de los opuestos no es por los sujetos que protegen esos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-14T10:47:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-14T10:47:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/corrupcion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julio Ben\u00edtez Capli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julio Ben\u00edtez Capli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/\"},\"author\":{\"name\":\"Julio Ben\u00edtez Capli\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/7cfd8ce58fc1947339d5ee594028a3b0\"},\"headline\":\"El sistema te obliga a la corrupci\u00f3n\",\"datePublished\":\"2022-02-14T10:47:30+00:00\",\"dateModified\":\"2022-02-14T10:47:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/\"},\"wordCount\":217,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/corrupcion.jpg?fit=640%2C360&ssl=1\",\"keywords\":[\"corrupcion\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/\",\"name\":\"El sistema te obliga a la corrupci\u00f3n - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/corrupcion.jpg?fit=640%2C360&ssl=1\",\"datePublished\":\"2022-02-14T10:47:30+00:00\",\"dateModified\":\"2022-02-14T10:47:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/corrupcion.jpg?fit=640%2C360&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/corrupcion.jpg?fit=640%2C360&ssl=1\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/14\\\/el-sistema-te-obliga-a-la-corrupcion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El sistema te obliga a la corrupci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/7cfd8ce58fc1947339d5ee594028a3b0\",\"name\":\"Julio Ben\u00edtez Capli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/julio-benitez-capli.jpg?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/julio-benitez-capli.jpg?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/julio-benitez-capli.jpg?fit=96%2C96&ssl=1\",\"caption\":\"Julio Ben\u00edtez Capli\"},\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/jbenitez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El sistema te obliga a la corrupci\u00f3n - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/","og_locale":"es_ES","og_type":"article","og_title":"El sistema te obliga a la corrupci\u00f3n - Informatepy","og_description":"El diablo puede citar las Escrituras para conseguir sus fines cuenta el dicho y as\u00ed tambi\u00e9n la casta pol\u00edtica se llena la boca con derechos humanos, laborales, colectivos y sociales, legislan sobre ellos y los imponen sobre el resto. Pero como en el mundo de los opuestos no es por los sujetos que protegen esos [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/","og_site_name":"Informatepy","article_published_time":"2022-02-14T10:47:30+00:00","article_modified_time":"2022-02-14T10:47:33+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/corrupcion.jpg","type":"image\/jpeg"}],"author":"Julio Ben\u00edtez Capli","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julio Ben\u00edtez Capli","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/"},"author":{"name":"Julio Ben\u00edtez Capli","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/7cfd8ce58fc1947339d5ee594028a3b0"},"headline":"El sistema te obliga a la corrupci\u00f3n","datePublished":"2022-02-14T10:47:30+00:00","dateModified":"2022-02-14T10:47:33+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/"},"wordCount":217,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/corrupcion.jpg?fit=640%2C360&ssl=1","keywords":["corrupcion"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/","url":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/","name":"El sistema te obliga a la corrupci\u00f3n - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/corrupcion.jpg?fit=640%2C360&ssl=1","datePublished":"2022-02-14T10:47:30+00:00","dateModified":"2022-02-14T10:47:33+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/corrupcion.jpg?fit=640%2C360&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/corrupcion.jpg?fit=640%2C360&ssl=1","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/14\/el-sistema-te-obliga-a-la-corrupcion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"El sistema te obliga a la corrupci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/7cfd8ce58fc1947339d5ee594028a3b0","name":"Julio Ben\u00edtez Capli","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/julio-benitez-capli.jpg?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/julio-benitez-capli.jpg?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/julio-benitez-capli.jpg?fit=96%2C96&ssl=1","caption":"Julio Ben\u00edtez Capli"},"url":"https:\/\/informatepy.com\/2021\/author\/jbenitez\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/corrupcion.jpg?fit=640%2C360&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1913,"url":"https:\/\/informatepy.com\/2021\/2020\/04\/21\/mensajes-en-celular-del-chofer-detenido-en-cde-confirman-el-pago-de-coimas-a-aduaneros\/","url_meta":{"origin":10086,"position":0},"title":"Mensajes en celular del chofer detenido en CDE confirman el pago de coimas a aduaneros","date":"21 de abril de 2020","format":false,"excerpt":"Inicialmente se mencion\u00f3 que fueron los aduaneros quienes decomisaron la carga. Pero fueron los militares debido a que existe una fuerte pelea por las coimas. En la puja tambi\u00e9n est\u00e1n los agentes de Contra Delitos Econ\u00f3micos de la Polic\u00eda Nacional. Si los marinos no reten\u00edan la carga, los agentes polic\u00edas\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/coimas-cde.jpg?fit=567%2C553&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1085,"url":"https:\/\/informatepy.com\/2021\/2019\/04\/27\/detienen-al-director-del-detave-por-corrupcion\/","url_meta":{"origin":10086,"position":1},"title":"Detienen al Director del DETAVE por corrupci\u00f3n","date":"27 de abril de 2019","format":false,"excerpt":"Este dinero entregado como parte del bot\u00edn, hab\u00eda sido previamente fotocopiado y ser se\u00f1alado como dinero que habitualmente se le rend\u00eda al militar retirado, como la cabeza de esta red de coimas. Los sobornos se dar\u00edan a cambio de hacer la \u201cvista gorda\u201d o simplemente no observar los cargamentos ilegales\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/detave.jpg?fit=1143%2C1200&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1096,"url":"https:\/\/informatepy.com\/2021\/2019\/04\/29\/guardan-celosamente-la-lista-de-periodistas-que-recibian-dinero-de-las-coimas-del-detave\/","url_meta":{"origin":10086,"position":2},"title":"Guardan celosamente la lista de periodistas que recib\u00edan dinero de las coimas del DETAVE","date":"29 de abril de 2019","format":false,"excerpt":"El ministro de la Senad, Arnaldo Giuzzio, confirm\u00f3 que varios periodistas recib\u00edan dinero para hablar bien del Detave, hac\u00edan \u2018alabanzas\u2019 excesivas y destacan peque\u00f1os operativos de incautaci\u00f3n, haci\u00e9ndolos pasar como hechos de gran envergadura. \u201cSe sobrevaloraba la intervenci\u00f3n, se presentaba como una operaci\u00f3n enorme la ca\u00edda de un camioncito de\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/detave1.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10380,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/01\/clan-prieto-recibio-coima-del-esquema-de-lavado-de-dinero-investigado-por-a-ultranza-paraguay\/","url_meta":{"origin":10086,"position":3},"title":"Clan Prieto recibi\u00f3 coima del esquema de lavado de dinero investigado por \u201cA ultranza Paraguay\u00bb","date":"1 de marzo de 2022","format":false,"excerpt":"El Clan Prieto que maneja la comuna de Ciudad del Este, desde 2019, recibi\u00f3 coimas para habilitar estaciones de servicios del esquema de lavado de dinero que investiga los fiscales con la operaci\u00f3n \u201cA Ultranza Paraguay\u201d. Fue a trav\u00e9s de la empresa Tapiracuai S.A., propiedad de Alberto Koube. El propio\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/petrochaco-cde.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9757,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/26\/el-problema-es-que-es-el-pastor-abreu\/","url_meta":{"origin":10086,"position":4},"title":"El problema es que es el pastor Abreu","date":"26 de enero de 2022","format":false,"excerpt":"Si no fuera el conocido susodicho, a lo mejor hasta era una noticia celebrada por la gente en general. Pero es \u00e9l, no es Marta o Juana la que agoniza hace meses rogando ser atendida o suplicando una medicina para vivir un d\u00eda m\u00e1s. Ni siquiera tratada: \u00a1atendida! Y no\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/pastor-abreu.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7583,"url":"https:\/\/informatepy.com\/2021\/2021\/10\/08\/cde-miguel-prieto-y-la-corrupcion-silenciada-por-los-medios\/","url_meta":{"origin":10086,"position":5},"title":"CDE: Miguel Prieto y la corrupci\u00f3n silenciada por los medios","date":"8 de octubre de 2021","format":false,"excerpt":"Mucho se habl\u00f3 estos \u00faltimos d\u00edas en todos los medios de la denuncia en contra de \u201cNenecho\u201d y est\u00e1 bien, tambi\u00e9n est\u00e1 bien que se hable de las denuncias contra Hugo Javier, lo que no est\u00e1 bien, es que los medios de comunicaci\u00f3n miren al costado en otros casos donde\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/prietto-y-kattya.jpg?fit=1035%2C1200&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1298,"user_id":18,"is_guest":0,"slug":"jbenitez","display_name":"Julio Ben\u00edtez Capli","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/julio-benitez-capli.jpg?fit=96%2C96&ssl=1","first_name":"Julio","last_name":"Ben\u00edtez Capli","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/10086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=10086"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/10086\/revisions"}],"predecessor-version":[{"id":10088,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/10086\/revisions\/10088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/10087"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=10086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=10086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=10086"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=10086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}