{"id":1008,"date":"2019-04-07T20:19:00","date_gmt":"2019-04-07T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1008"},"modified":"2021-02-10T14:03:49","modified_gmt":"2021-02-10T14:03:49","slug":"finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/","title":{"rendered":"Finaliz\u00f3 el XII Torneo Internacional Abierto de Artes Marciales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el Predio de la Secretaria Nacional de Deporte \u00abSND Arena\u00bb, se llev\u00f3  cabo el XII Torneo Internacional Abierto de Artes Marciales. El mismo estuvo organizado por el Prof. Javier Colman (Artes Marciales) y el Maestro Francisco Lefebvre (Deportes de Contacto).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del torneo participaron delegaciones de atletas y academias de nuestro pa\u00eds, de Argentina, Brasil y Chile. Las delegaciones sumaron mas de 500 atletas de las artes marciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento fue declarado de inter\u00e9s municipal y departamental, recibiendo un importante apoyo del Gobernador del Departamento Central, Hugo Javier Gonz\u00e1lez.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/IMG-20190407-WA0175.jpg?w=740&#038;ssl=1\" alt=\"\" class=\"wp-image-1185\" data-recalc-dims=\"1\"\/><figcaption>Jos\u00e9 Vallejo Serv\u00edn, Prof. Juan Carlos Balmori y Prof. Javier Colman<br><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las autoridades presentes estuvo el Intendente de la ciudad de Guarambar\u00e9, <strong>Jos\u00e9 Vallejos Serv\u00edn<\/strong>; el Presidente de la Junta Departamental  <strong>Gustavo Adolfo Machuca<\/strong>, y en representaci\u00f3n de la Gobernaci\u00f3n del Departamento Central, el <strong>Prof. Juan Carlos Balmori<\/strong>, Jefe del Departamento de Promoci\u00f3n de eventos y proyectos deportivos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el Predio de la Secretaria Nacional de Deporte \u00abSND Arena\u00bb, se llev\u00f3 cabo el XII Torneo Internacional Abierto de Artes Marciales. El mismo estuvo organizado por el Prof. Javier Colman (Artes Marciales) y el Maestro Francisco Lefebvre (Deportes de Contacto). Del torneo participaron delegaciones de atletas y academias de nuestro pa\u00eds, de Argentina, Brasil [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[183,302],"tags":[355,374,421],"ppma_author":[1039],"class_list":["post-1008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-destacados","tag-departamento-central","tag-hugo-javier-gonzalez","tag-juan-carlos-balmori"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finaliz\u00f3 el XII Torneo Internacional Abierto de Artes Marciales - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finaliz\u00f3 el XII Torneo Internacional Abierto de Artes Marciales - Informatepy\" \/>\n<meta property=\"og:description\" content=\"En el Predio de la Secretaria Nacional de Deporte \u00abSND Arena\u00bb, se llev\u00f3 cabo el XII Torneo Internacional Abierto de Artes Marciales. El mismo estuvo organizado por el Prof. Javier Colman (Artes Marciales) y el Maestro Francisco Lefebvre (Deportes de Contacto). Del torneo participaron delegaciones de atletas y academias de nuestro pa\u00eds, de Argentina, Brasil [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-07T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-10T14:03:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/IMG-20190407-WA0176.jpg?fit=1280%2C960&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Finaliz\u00f3 el XII Torneo Internacional Abierto de Artes Marciales\",\"datePublished\":\"2019-04-07T20:19:00+00:00\",\"dateModified\":\"2021-02-10T14:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/\"},\"wordCount\":164,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IMG-20190407-WA0176.jpg?fit=1280%2C960&ssl=1\",\"keywords\":[\"departamento central\",\"hugo javier gonzalez\",\"juan carlos balmori\"],\"articleSection\":[\"Deportes\",\"Destacados\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/\",\"name\":\"Finaliz\u00f3 el XII Torneo Internacional Abierto de Artes Marciales - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IMG-20190407-WA0176.jpg?fit=1280%2C960&ssl=1\",\"datePublished\":\"2019-04-07T20:19:00+00:00\",\"dateModified\":\"2021-02-10T14:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IMG-20190407-WA0176.jpg?fit=1280%2C960&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IMG-20190407-WA0176.jpg?fit=1280%2C960&ssl=1\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/07\\\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finaliz\u00f3 el XII Torneo Internacional Abierto de Artes Marciales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finaliz\u00f3 el XII Torneo Internacional Abierto de Artes Marciales - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/","og_locale":"es_ES","og_type":"article","og_title":"Finaliz\u00f3 el XII Torneo Internacional Abierto de Artes Marciales - Informatepy","og_description":"En el Predio de la Secretaria Nacional de Deporte \u00abSND Arena\u00bb, se llev\u00f3 cabo el XII Torneo Internacional Abierto de Artes Marciales. El mismo estuvo organizado por el Prof. Javier Colman (Artes Marciales) y el Maestro Francisco Lefebvre (Deportes de Contacto). Del torneo participaron delegaciones de atletas y academias de nuestro pa\u00eds, de Argentina, Brasil [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/","og_site_name":"Informatepy","article_published_time":"2019-04-07T20:19:00+00:00","article_modified_time":"2021-02-10T14:03:49+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/IMG-20190407-WA0176.jpg?fit=1280%2C960&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Finaliz\u00f3 el XII Torneo Internacional Abierto de Artes Marciales","datePublished":"2019-04-07T20:19:00+00:00","dateModified":"2021-02-10T14:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/"},"wordCount":164,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/IMG-20190407-WA0176.jpg?fit=1280%2C960&ssl=1","keywords":["departamento central","hugo javier gonzalez","juan carlos balmori"],"articleSection":["Deportes","Destacados"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/","url":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/","name":"Finaliz\u00f3 el XII Torneo Internacional Abierto de Artes Marciales - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/IMG-20190407-WA0176.jpg?fit=1280%2C960&ssl=1","datePublished":"2019-04-07T20:19:00+00:00","dateModified":"2021-02-10T14:03:49+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/IMG-20190407-WA0176.jpg?fit=1280%2C960&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/IMG-20190407-WA0176.jpg?fit=1280%2C960&ssl=1","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/07\/finalizo-el-xii-torneo-internacional-abierto-de-artes-marciales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Finaliz\u00f3 el XII Torneo Internacional Abierto de Artes Marciales"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/IMG-20190407-WA0176.jpg?fit=1280%2C960&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1090,"url":"https:\/\/informatepy.com\/2021\/2019\/04\/28\/finalizo-el-ii-campeonato-nacional-de-kick-boxing-y-muaythai\/","url_meta":{"origin":1008,"position":0},"title":"Finaliz\u00f3 el II Campeonato Nacional de Kick Boxing y Muaythai","date":"28 de abril de 2019","format":false,"excerpt":"Con la participaci\u00f3n de renombrados exponentes nacionales e internacionales y la presencia de Academias de Coronel Oviedo, Concepci\u00f3n, Villa Rica, Asunci\u00f3n y todo el Departamento Central, se llev\u00f3 a cabo el II Campeonato Nacional de Kick Boxing y Muaythai. Del evento participaron 150 luchadores y se llevaron a cabo m\u00e1s\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/FB_IMG_1556407830704.jpg?fit=720%2C960&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11599,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/12\/hugo-javier-ya-no-es-gobernador-de-central\/","url_meta":{"origin":1008,"position":1},"title":"Hugo Javier ya no es gobernador de Central","date":"12 de mayo de 2022","format":false,"excerpt":"La Junta Departamental destituy\u00f3 hoy (12\/05\/2022) a Hugo Javier Gonz\u00e1lez como Gobernador del departamento Central, por lo que a partir de ahora deja oficialmente de ser la m\u00e1xima autoridad del departamento. En la sesi\u00f3n del d\u00eda de la fecha, los concejales departamentales de Central, con 14 votos a favor, resolvieron\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/hugo-javier.jpg?fit=1200%2C711&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11224,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/19\/abogado-de-hugo-javier-pide-que-su-cliente-pueda-concurrir-a-la-gobernacion-en-horario-laboral\/","url_meta":{"origin":1008,"position":2},"title":"Abogado de Hugo Javier pide que su cliente pueda concurrir a la gobernaci\u00f3n en horario laboral","date":"19 de abril de 2022","format":false,"excerpt":"Andr\u00e9s Casati, abogado de Hugo Javier Gonz\u00e1lez, indic\u00f3 que solicit\u00f3 permiso para que el mismo pueda asistir a la sede de la gobernaci\u00f3n de Central para desempe\u00f1ar las funciones\u00a0 que le dio la ciudadan\u00eda que vot\u00f3 por \u00e9l. Adem\u00e1s de criticar el r\u00e9gimen de arresto domiciliario que decret\u00f3 al juzgado,\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/hugo-javier.jpg?fit=1200%2C711&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1000,"url":"https:\/\/informatepy.com\/2021\/2019\/04\/05\/el-gobernador-de-central-se-reunio-con-el-comite-de-emergencia-nacional\/","url_meta":{"origin":1008,"position":3},"title":"El Gobernador de Central se reuni\u00f3 con el Comit\u00e9 de Emergencia Nacional","date":"5 de abril de 2019","format":false,"excerpt":"El Gobernador de Central, Hugo Javier Gonz\u00e1lez, particip\u00f3 de una mesa de trabajo con las instituciones integrantes del comit\u00e9 de Emergencia Nacional, en el marco de los trabajos de asistencia a las familias afectadas por las inundaciones.\u00a0 Al respecto, el jefe\u00a0 departamental resalt\u00f3 la importancia de una\u00a0 cooperaci\u00f3n interinstitucional para\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/IMG-20190405-WA0067.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":569,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/16\/trabajos-de-revitalizacion-del-lago-ypacarai\/","url_meta":{"origin":1008,"position":4},"title":"Trabajos de revitalizaci\u00f3n del Lago Ypacara\u00ed","date":"16 de febrero de 2019","format":false,"excerpt":"La Gobernaci\u00f3n del departamento Central, por disposici\u00f3n del Gobernador Hugo Javier Gonz\u00e1lez Alegre, se encuentra trabajando en la revitalizaci\u00f3n de la Playa Municipal de Aregu\u00e1. El objetivo de esta iniciativa apunta a que los visitantes y pobladores de la zona realicen caminatas o actividades deportivas en el lugar, respetando la\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/IMG-20190216-WA0066.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":595,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/coordinan-politicas-publicas-de-seguridad-en-el-departamento-central\/","url_meta":{"origin":1008,"position":5},"title":"Coordinan pol\u00edticas p\u00fablicas de seguridad en el Departamento Central","date":"18 de febrero de 2019","format":false,"excerpt":"En el d\u00eda de hoy, el Gobernador del Departamento central, Hugo Javier, mantuvo una reuni\u00f3n con los Intendentes del Departamento (y algunos representantes), con el objetivo de establecer pol\u00edticas p\u00fablicas de seguridad a nivel departamental. Hugo Javier, Gobernador del departamento Central La idea del gobernador es saltar las bander\u00edas pol\u00edticas\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/seguridad.jpg?fit=1200%2C696&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1008"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1008\/revisions"}],"predecessor-version":[{"id":3140,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1008\/revisions\/3140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1009"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1008"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}